{"id":734,"date":"2021-03-21T17:34:39","date_gmt":"2021-03-21T20:34:39","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/trabalho-remoto-nao-passa-nem-perto-da-maioria\/"},"modified":"2021-03-21T17:34:39","modified_gmt":"2021-03-21T20:34:39","slug":"trabalho-remoto-nao-passa-nem-perto-da-maioria","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/trabalho-remoto-nao-passa-nem-perto-da-maioria\/","title":{"rendered":"Trabalho remoto n\u00e3o passa nem perto da maioria"},"content":{"rendered":"<p>Difundido pela pandemia de covid-19, o trabalho remoto passa longe da realidade da grande maioria dos trabalhadores brasileiros. Sem poder trabalhar de casa, esse grupo tamb\u00e9m encontra mais dificuldade para se recolocar na retomada da economia. Em sua maioria, s\u00e3o trabalhadores mais jovens e de menor escolaridade. \u00c9 o caso de gar\u00e7ons, vendedores de lojas, manicures e empregadas dom\u00e9sticas.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Antes da crise, as vagas de trabalho, formais e informais, que necessariamente s\u00e3o presenciais somavam 79,7 milh\u00f5es de trabalhadores &#8211; 86% do total de empregados no fim de 2019. Essa parcela perdeu mais empregos com a crise, na compara\u00e7\u00e3o com os 12,9 milh\u00f5es de trabalhadores em vagas que podiam ser executadas a dist\u00e2ncia, conforme um estudo em andamento da consultoria IDados, obtido com exclusividade pelo <strong>Estad\u00e3o<\/strong>.<\/p>\n<p>Com a piora da pandemia neste in\u00edcio de 2021, a tend\u00eancia \u00e9 que as oportunidades nas profiss\u00f5es necessariamente presenciais sigam mais raras, o que dever\u00e1 contribuir para a alta do desemprego e o aumento da pobreza &#8211; conforme proje\u00e7\u00e3o do pesquisador Daniel Duque, do Instituto Brasileiro de Economia da Funda\u00e7\u00e3o Getulio Vargas (Ibre\/FGV), sem o aux\u00edlio emergencial, 62,4 milh\u00f5es de brasileiros, quase um ter\u00e7o (29,5%) da popula\u00e7\u00e3o, come\u00e7aram este ano abaixo da linha de pobreza.<\/p>\n<p>Segundo Bruno Ottoni, pesquisador do iDados, no quarto trimestre do ano passado a popula\u00e7\u00e3o ocupada nas profiss\u00f5es prop\u00edcias ao trabalho remoto era 3,4% menor do que um ano antes, em igual per\u00edodo de 2019. Enquanto isso, a varia\u00e7\u00e3o da popula\u00e7\u00e3o ocupada em vagas necessariamente presenciais apontava para o fechamento de 8 milh\u00f5es de vagas ante um ano antes, um tombo de 10% na ocupa\u00e7\u00e3o desse grupo. \u00c9 uma retra\u00e7\u00e3o tr\u00eas vezes maior do que a vista nas profiss\u00f5es prop\u00edcias ao trabalho remoto &#8211; a discrep\u00e2ncia aumentou, em rela\u00e7\u00e3o ao terceiro trimestre.<\/p>\n<p>O estudo do IDados usa as informa\u00e7\u00f5es da Pesquisa Nacional por Amostra de Domic\u00edlios Cont\u00ednua do IBGE, replicando a classifica\u00e7\u00e3o de ocupa\u00e7\u00f5es prop\u00edcias ao trabalho remoto de um estudo publicado no ano passado nos Estados Unidos.<\/p>\n<p>O perfil do trabalhador remoto \u00e9 composto majoritariamente por mulheres brancas que completaram o ensino superior, diz Geraldo G\u00f3es, especialista em pol\u00edticas p\u00fablicas e gest\u00e3o governamental do Instituto de Pesquisa Econ\u00f4mica e Aplicada (Ipea), \u00f3rg\u00e3o do Minist\u00e9rio da Economia. Esse tipo de profissional est\u00e1 concentrado no Sudeste e no Distrito Federal.<\/p>\n<p>&#8220;Quanto maior a renda per capita do Estado, maior a escolaridade local, maior a propor\u00e7\u00e3o de pessoas trabalhando remotamente. Tem muito pouco trabalho remoto no Norte e Nordeste, mas na Faria Lima tem bastante&#8221;, afirma G\u00f3es.<\/p>\n<p><strong>Discrep\u00e2ncia<\/strong><\/p>\n<p>Para Ottoni, do IDados, a discrep\u00e2ncia na din\u00e2mica de abertura e fechamento de vagas entre os dois grupos tende a aumentar neste primeiro trimestre, quando a economia dever\u00e1 encolher frente o quarto trimestre de 2020. Os trabalhadores enfrentar\u00e3o, ao mesmo tempo, a piora da pandemia e a falta do aux\u00edlio emergencial, j\u00e1 que a retomada do pagamento do benef\u00edcio ficou mesmo para abril.<\/p>\n<p>&#8220;Minha expectativa, diante do que tenho analisado dos dados antecedentes, \u00e9 que, em janeiro e fevereiro, as pessoas voltaram para o mercado de trabalho, voltaram a procurar emprego, porque o aux\u00edlio acabou&#8221;, diz Ottoni.<\/p>\n<p>Os trabalhadores informais devem ter retomado suas atividades, de acordo com Ottoni. Com a abertura de vagas formais nas empresas que estavam funcionando mais ou menos normalmente em janeiro e fevereiro &#8211; antes do aperto nas restri\u00e7\u00f5es ao contato social -, a ocupa\u00e7\u00e3o deve ter crescido. Por outro lado, sem o aux\u00edlio, os informais podem ter voltado a trabalhar por qualquer remunera\u00e7\u00e3o. O rendimento do trabalho pode ter despencado.<\/p>\n<p><strong>Nova remunera\u00e7\u00e3o<\/strong><\/p>\n<p>O representante comercial Fabio Chrisostomo, de 25 anos, trabalhou com carteira assinada para uma cervejaria artesanal at\u00e9 abril de 2020. Perdeu o emprego quando a empresa foi afetada pela suspens\u00e3o dos eventos presenciais e pelo fechamento de bares e restaurantes. Nos meses que se seguiram, conseguiu um trabalho na manuten\u00e7\u00e3o de sistemas de chope, e agora est\u00e1 de volta \u00e0 cervejaria, mas remunerado por comiss\u00e3o.<\/p>\n<p>&#8220;O volume de vendas ainda n\u00e3o \u00e9 suficiente para manter todos os custos de um funcion\u00e1rio com carteira assinada. Bares e restaurantes est\u00e3o comprando s\u00f3 o essencial. A proje\u00e7\u00e3o para o futuro, com a vacina\u00e7\u00e3o, \u00e9 muito boa. A pandemia \u00e9 que est\u00e1 travando tudo&#8221;, conta Chrisostomo.<\/p>\n<p>O economista Cosmo Donato, da LCA Consultores, lembra que a retra\u00e7\u00e3o da economia n\u00e3o ser\u00e1 como em 2020, no in\u00edcio da pandemia, porque o choque &#8220;n\u00e3o \u00e9 inesperado&#8221;. Ao mesmo tempo, o trabalhador informal &#8220;est\u00e1 t\u00e3o vulner\u00e1vel quanto antes&#8221;. Nesse quadro, a economia segue em retomada na compara\u00e7\u00e3o com 2020, mas com desemprego maior e aumento da pobreza.<\/p>\n<p>&#8220;O cen\u00e1rio da segunda onda da pandemia \u00e9 uma recupera\u00e7\u00e3o mais desigual&#8221;, afirma Donato. Por isso, para o economista, &#8220;\u00e9 importante, sim, pensar em medidas&#8221; para mitigar a crise, como a reedi\u00e7\u00e3o do aux\u00edlio emergencial.<\/p>\n<p><strong>Dom\u00e9sticas est\u00e3o no grupo dos mais atingidos<\/strong><\/p>\n<p>H\u00e1 um ano, com a chegada da pandemia, o Pa\u00eds parou. As fam\u00edlias de renda m\u00e9dia e alta, que puderam ficaram em casa, usar o com\u00e9rcio eletr\u00f4nico e as entregas em domic\u00edlio dos restaurantes, tamb\u00e9m mudaram suas combina\u00e7\u00f5es com as empregadas dom\u00e9sticas. Destaque nas ocupa\u00e7\u00f5es que n\u00e3o podem ser exercidas remotamente, as dom\u00e9sticas est\u00e3o entre os trabalhadores mais atingidos pela crise. Ano passado, 1,2 milh\u00e3o de pessoas perderam o emprego nessa atividade, 16% do total de vagas fechadas, entre formais e informais, segundo o IBGE.<\/p>\n<p>A adapta\u00e7\u00e3o \u00e0 pandemia passou por v\u00e1rios arranjos. Houve fam\u00edlias que seguiram pagando sal\u00e1rios normalmente, mesmo sem os servi\u00e7os prestados. Nas rela\u00e7\u00f5es formais, com carteira assinada, foi poss\u00edvel dar f\u00e9rias, suspender contratos e reduzir jornadas. Nas rela\u00e7\u00f5es sem carteira, incluindo diaristas e as dom\u00e9sticas mensalistas em situa\u00e7\u00e3o ilegal, foi mais dif\u00edcil ficar apenas na redu\u00e7\u00e3o do sal\u00e1rio. Em todos os casos, n\u00e3o faltaram demiss\u00f5es.<\/p>\n<p>A piora da pandemia agrava o quadro. O Sindom\u00e9stica, sindicato das dom\u00e9sticas do Rio, percebeu aumento das demiss\u00f5es formais neste in\u00edcio de ano. Foi o que aconteceu com Eliana Maria de Moura, de 36 anos, demitida em meados do m\u00eas passado, ap\u00f3s quase um ano de isolamento, passando a maior parte do tempo em casa. No fim do ano, passou pelo trauma de perder a m\u00e3e, v\u00edtima da covid-19.<\/p>\n<p>&#8220;Gra\u00e7as a Deus meus patr\u00f5es seguraram por quase um ano. Sou muito grata a eles&#8221;, diz Eliana, que recebeu o sal\u00e1rio integral de R$ 1,4 mil o tempo todo, mesmo reduzindo a jornada. Durante a pandemia, ela ia trabalhar uma vez por semana, ou a cada quinzena. Na demiss\u00e3o, os patr\u00f5es alegaram que n\u00e3o estavam conseguindo manter o pagamento, conta Eliana.<\/p>\n<p>Segundo Luana Pinheiro, pesquisadora do Instituto de Pesquisa Econ\u00f4mica Aplicada (Ipea), a piora da pandemia e o aperto na renda das fam\u00edlias que contratam os servi\u00e7os dificultam a retomada das vagas perdidas. Isso num quadro de rendimentos em queda, pois &#8220;as dom\u00e9sticas que trabalhavam em faxina cinco ou seis dias na semana passaram a ter um ou dois dias&#8221;.<\/p>\n<p>A economista Hildete Pereira de Melo, professora da Universidade Federal Fluminense (UFF), lembra que a crise poder\u00e1 &#8220;empurrar&#8221; mais mulheres para o trabalho dom\u00e9stico. Muitas vezes, o servi\u00e7o serve como &#8220;bico&#8221; ou \u00faltima op\u00e7\u00e3o quando elas perdem o emprego em outras atividades.<\/p>\n<p>As informa\u00e7\u00f5es s\u00e3o do jornal <strong>O Estado de S. Paulo.<\/strong><\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/1788150\/trabalho-remoto-nao-passa-nem-perto-da-maioria?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Difundido pela pandemia de covid-19, o trabalho remoto passa longe da realidade da grande maioria<\/p>\n","protected":false},"author":0,"featured_media":735,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=734"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/734\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/735"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}