{"id":722,"date":"2021-03-21T15:28:27","date_gmt":"2021-03-21T18:28:27","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/reino-unido-testa-tratamentos-anti-covid-como-prevencao-em-pacientes-vulneraveis\/"},"modified":"2021-03-21T15:28:27","modified_gmt":"2021-03-21T18:28:27","slug":"reino-unido-testa-tratamentos-anti-covid-como-prevencao-em-pacientes-vulneraveis","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/reino-unido-testa-tratamentos-anti-covid-como-prevencao-em-pacientes-vulneraveis\/","title":{"rendered":"Reino Unido testa tratamentos anti-Covid como preven\u00e7\u00e3o em pacientes vulner\u00e1veis"},"content":{"rendered":"<p>O governo brit\u00e2nico come\u00e7ou a testar se tratamentos j\u00e1 comprovados contra Covid-19 podem tamb\u00e9m agir de forma profil\u00e1tica, ou seja, prevenindo a infec\u00e7\u00e3o e a transmiss\u00e3o de coronav\u00edrus entre pessoas vulner\u00e1veis -residentes de asilos e pessoas com sistema imunol\u00f3gico debilitado, como pacientes transplantados, em tratamento para c\u00e2ncer ou em di\u00e1lise.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Como a vacina pode ter o efeito reduzido em pessoas nas quais o sistema imunol\u00f3gico est\u00e1 diminu\u00eddo, o estudo brit\u00e2nico quer testar se os medicamentos podem oferecer uma prote\u00e7\u00e3o adicional, anunciou neste domingo (21) o governo.<\/p>\n<p>Os rem\u00e9dios testados ser\u00e3o dexametasona e tocilizumabe, que, em estudos preliminares, j\u00e1 se mostraram eficazes para reduzir mortes em casos graves de Covid-19 e s\u00e3o usados com esse objetivo em hospitais brit\u00e2nicos.<\/p>\n<p>M\u00e9dicos alertam, por\u00e9m, que esses medicamentos n\u00e3o devem ser usados fora de hospitais, porque podem ter efeitos perigosos.<br \/>No ensaio cl\u00ednico j\u00e1 iniciado pela Universidade de Cambridge, chamado de Protect-V, participar\u00e3o 2.250 volunt\u00e1rios com doen\u00e7a renal, que estejam em di\u00e1lise ou com transplante renal ou estejam recebendo imunossupress\u00e3o. Os testes v\u00e3o durar 12 meses.<\/p>\n<p>O ensaio Protect-CH, conduzido pela Universidade de Nottingham, come\u00e7a no pr\u00f3ximo m\u00eas e testar\u00e1 durante dois anos o efeito dos tratamentos para reduzir a transmiss\u00e3o dos Sars-Cov-2 e evitar casos graves de Covid-19 em residentes e funcion\u00e1rios de lares de idosos.<\/p>\n<p>Devem participar do estudo 12 mil volunt\u00e1rios, em 400 lares de idosos.<\/p>\n<p>Se os rem\u00e9dios se mostrarem eficazes para evitar a dissemina\u00e7\u00e3o do v\u00edrus entre esses grupos, seu uso pode beneficiar ao menos 500 mil pacientes imunodeprimidos e 420 mil residentes de asilo no Reino Unido, segundo os pesquisadores.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Mundo<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/mundo\/1788087\/reino-unido-testa-tratamentos-anti-covid-como-prevencao-em-pacientes-vulneraveis?utm_source=rss-mundo&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governo brit\u00e2nico come\u00e7ou a testar se tratamentos j\u00e1 comprovados contra Covid-19 podem tamb\u00e9m agir<\/p>\n","protected":false},"author":0,"featured_media":723,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=722"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/722\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/723"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}