{"id":716,"date":"2021-03-21T15:28:22","date_gmt":"2021-03-21T18:28:22","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/informacao-e-planejamento-sao-chaves-para-profissionalizar-negocios\/"},"modified":"2021-03-21T15:28:22","modified_gmt":"2021-03-21T18:28:22","slug":"informacao-e-planejamento-sao-chaves-para-profissionalizar-negocios","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/informacao-e-planejamento-sao-chaves-para-profissionalizar-negocios\/","title":{"rendered":"Informa\u00e7\u00e3o e planejamento s\u00e3o chaves para profissionalizar neg\u00f3cios"},"content":{"rendered":"<p>Informa\u00e7\u00e3o e planejamento s\u00e3o as palavras-chaves para quem decide empreender, seja por necessidade ou por oportunidade de neg\u00f3cio. Colocar no papel informa\u00e7\u00f5es b\u00e1sicas sobre o mercado consumidor e os custos s\u00e3o essenciais para alinhar as expectativas e garantir a sustentabilidade de uma empresa no longo prazo, em meio \u00e0 concorr\u00eancia.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>E foi isso que a empreendedora Acza Kate Rodrigues, de 36 anos, fez. Moradora de Bras\u00edlia, h\u00e1 cerca de dois anos ela descobriu a costura em sua vida e passou a fabricar pe\u00e7as para os tr\u00eas filhos. Ela buscou informa\u00e7\u00e3o, fez cursos e aproveitou o conte\u00fado dispon\u00edvel na internet. Isso foi alimentando a vontade de ter a pr\u00f3pria marca. No ano passado, encontrou a oportunidade de montar o neg\u00f3cio em sociedade, mesmo em meio \u00e0 pandemia de covid-19.<\/p>\n<p>A Gota D&#8217;\u00e1gua \u00e9 uma marca de roupas infantis e as vendas acontecem pelas redes sociais. Atualmente, Acza e a s\u00f3cia est\u00e3o lan\u00e7ando uma nova cole\u00e7\u00e3o e j\u00e1 t\u00eam projetos para ampliar a equipe e criar um <em>site<\/em>, para aumentar as vendas <em>online<\/em>.<\/p>\n<p>\u201cO que me fez decidir e tocar o neg\u00f3cio foi parar de esperar pelo tempo certo, mas come\u00e7ar com o que eu j\u00e1 tinha. As condi\u00e7\u00f5es exatas podem nunca chegar, mas as pessoas podem conseguir e ter sucesso no mercado\u201d, disse, explicando que logo no in\u00edcio fez seu registro como microempreendedor individual (MEI), j\u00e1 pensando na expans\u00e3o da empresa. \u201cNosso sonho \u00e9 ser empreendedoras, para isso precisa ter tudo regulamentado, para que esse crescimento seja real\u201d, explicou.<\/p>\n<p>Para se ter uma ideia, em 2020, houve um recorde na formaliza\u00e7\u00e3o de novos neg\u00f3cios no pa\u00eds, com alta de 6% em rela\u00e7\u00e3o a 2019, de acordo com o boletim do Mapa de Empresas, do Minist\u00e9rio da Economia. Das 3.359.750 de empresas abertas, 2.663.309, ou 79,3%, foram microempreendedores individuais (MEI), uma modalidade de empres\u00e1rio individual com processo simplificado para abertura de empresas, regime especial de tributa\u00e7\u00e3o e acesso facilitado a cr\u00e9dito.<\/p>\n<p>De acordo com o gerente da Unidade de Competitividade do Servi\u00e7o Brasileiro de Apoio \u00e0s Micro e Pequenas Empresas (Sebrae), C\u00e9sar Rissete, a participa\u00e7\u00e3o dos pequenos neg\u00f3cios no PIB (Produto Interno Bruto \u2013 soma de todos os bens e servi\u00e7os) do pa\u00eds aproxima-se de 30%. Al\u00e9m disso, eles t\u00eam sido fonte de gera\u00e7\u00e3o de emprego e representam hoje 56% dos trabalhos com carteira assinada.<\/p>\n<p>A pandemia de covid-19 refor\u00e7ou essa tend\u00eancia de crescimento das micro e pequenas empresas, segundo Rissete, pois muitas pessoas tiveram dificuldade de coloca\u00e7\u00e3o no mercado formal ou perderam seus empregos e tiveram que ir atr\u00e1s do sustento de outra maneira. \u201cA formaliza\u00e7\u00e3o \u00e9 um passo importante, mas \u00e9 insuficiente para a manuten\u00e7\u00e3o da empresa no mercado\u201d, disse.<\/p>\n<p>\u201cE parte significativa de aumentar a sobreviv\u00eancia do neg\u00f3cio vem do movimento de prepara\u00e7\u00e3o e profissionaliza\u00e7\u00e3o do empres\u00e1rio\u201d, explicou. Segundo o gerente do Sebrae, n\u00e3o \u00e9 necess\u00e1rio um planejamento exaustivo, que leve muito tempo, mas o empreendedor, mesmo por necessidade, precisa ter o m\u00ednimo de conhecimento sobre sua \u00e1rea de atua\u00e7\u00e3o, o mercado e o p\u00fablico que vai atender.<\/p>\n<p>Em geral, o empreendedor por oportunidade se dedica mais \u00e0 fase de planejamento, mas para Rissete, mesmo com menos tempo \u00e9 poss\u00edvel se preparar. Em primeiro lugar \u00e9 preciso pensar no mercado consumidor e no <em>marketing<\/em> de vendas: qual p\u00fablico vai atender, em qual localidade, a demanda pelo servi\u00e7o ou produto na regi\u00e3o e como chegar a esse consumidor e se fazer enxergar.<\/p>\n<p>\u201cSe eu colocar as informa\u00e7\u00f5es da empresa na internet ou nas redes sociais, o cliente est\u00e1 nesse canal? Ele vai me enxergar ou eu preciso fazer algum impresso f\u00edsico e distribuir para que as pessoas saibam que estou oferecendo aquele servi\u00e7o? Ou por meio de algum aplicativo eu consigo que as pessoas me enxerguem?\u201d, explicou o gerente do Sebrae, sobre as quest\u00f5es a serem respondidas pelo empreendedor.<\/p>\n<p>Para o especialista em gest\u00e3o de neg\u00f3cios e s\u00f3cio da empresa Prosphera, Haroldo Matsumoto, em muitas situa\u00e7\u00f5es, o microempres\u00e1rio acaba superestimando o pr\u00f3prio sucesso e come\u00e7ando o neg\u00f3cio de qualquer forma sem ter certeza se vai dar certo ou n\u00e3o. Nesse planejamento inicial, segundo ele, \u00e9 poss\u00edvel, inclusive, fazer testes com o produto ou o servi\u00e7o a ser oferecido. \u201cPara saber se as pessoas v\u00e3o querer comprar e se, nessa compra, sobra lucro para reinvestir no neg\u00f3cio, porque \u00e0s vezes s\u00f3 empata ou toma preju\u00edzo\u201d, disse.<\/p>\n<p>Tamb\u00e9m \u00e9 preciso entender a evolu\u00e7\u00e3o do produto ou servi\u00e7o, segundo o especialista, e trabalhar pelas recomenda\u00e7\u00f5es dos clientes. \u201cTem que ouvir muito a opini\u00e3o do cliente e ir aprimorando at\u00e9 que o n\u00edvel de satisfa\u00e7\u00e3o seja muito bom a ponto do cliente repetir a compra e come\u00e7ar a indicar seu produto ou servi\u00e7o\u201d, diz Matsumoto.<\/p>\n<p>Para os especialistas, \u00e9 indiscut\u00edvel que buscar orienta\u00e7\u00e3o profissional \u00e9 fundamental no in\u00edcio do neg\u00f3cio e h\u00e1 solu\u00e7\u00f5es gratuitas dispon\u00edveis. Os portais do Empreendedor e do Sebrae possuem um conte\u00fado amplo de informa\u00e7\u00f5es para quem quer come\u00e7ar o seu neg\u00f3cio. H\u00e1 ainda iniciativas como a organiza\u00e7\u00e3o Endeavor Brasil, que apoia empreendedores em diversas partes do mundo, e outros grupos de empres\u00e1rios e institui\u00e7\u00f5es que fazem esse trabalho.<\/p>\n<p>Al\u00e9m disso, segundo o gerente do Sebrae, \u00e9 preciso fazer o m\u00ednimo de contas e ter claro o custo para entrar no mercado. \u201cEssa \u00e9 chamada de gest\u00e3o financeira, que \u00e9 pensar quanto tenho de previs\u00e3o ou perspectiva de comercializar, quanto o mercado est\u00e1 pagando pelo meu servi\u00e7o ou pelo produto que vou comercializar, quanto vai custar e a quanto vou vender, quanto tenho que ter para me preparar, para ver se tenho f\u00f4lego financeiro para aguentar a entrada nesse mercado\u201d, diz Rissete.<\/p>\n<p>Matsumoto tamb\u00e9m explica que \u00e9 importante ter uma reserva financeira pessoal, j\u00e1 que o neg\u00f3cio pr\u00f3prio pode levar de um a dois anos para come\u00e7ar a dar um resultado positivo e o empres\u00e1rio conseguir fazer suas retiradas. \u201cPara quem abriu a empresa por necessidade, por causa da pandemia, isso \u00e9 um complicador\u201d, destacou.<\/p>\n<p>Nesse sentido, por exemplo, o governo oferece cr\u00e9dito facilitado para micro e pequenas empresas e, ano passado, criou o Programa Nacional de Apoio \u00e0s Microempresas e Empresas de Pequeno Porte (Pronampe), que instituiu linhas de cr\u00e9dito para que os pequenos neg\u00f3cios pudessem acessar capital de giro durante a pandemia. Matsumoto, entretanto, alerta que \u00e9 preciso cuidado com esse tipo de financiamento.<\/p>\n<p>\u201cO empreendedor n\u00e3o sabe se vai ter retorno para pagar a parcela, mesmo o Pronampe que tem car\u00eancia de seis meses, n\u00e3o d\u00e1 pra ter absoluta certeza. Mas se ele n\u00e3o tem outra sa\u00edda, n\u00e3o tem outro recurso com juros t\u00e3o baixos, s\u00f3 \u00e9 preciso tomar cuidado para que isso n\u00e3o se torne um pesadelo, tem que saber o que fazer com esse dinheiro\u201d, explicou.<\/p>\n<p>Outra dica cl\u00e1ssica e que sempre vale a pena lembrar, segundo Matsumoto, \u00e9 n\u00e3o misturar a conta pessoal do empres\u00e1rio com a da empresa. \u201c\u00c9 importante para saber quanto o neg\u00f3cio est\u00e1 dando de lucro ou preju\u00edzo. \u00c0s vezes a empresa \u00e9 lucrativa, mas se o propriet\u00e1rio tira muito dinheiro a\u00ed n\u00e3o h\u00e1 empresa que aguente\u201d, argumentou.<\/p>\n<p>E para quem v\u00ea na internet e nas redes sociais um caminho mais f\u00e1cil para come\u00e7ar o seu neg\u00f3cio, Rissete alerta que, da mesma forma que o empreendedor tem o mundo <em>online<\/em> \u00e0 disposi\u00e7\u00e3o, os clientes tamb\u00e9m se perdem mais facilmente e podem n\u00e3o enxergar o produto ou servi\u00e7o oferecido. \u201cNa medida que se tem muita op\u00e7\u00e3o, \u00e9 preciso se diferenciar. Tirando os produtos e servi\u00e7os mais disruptivos, que surgem e n\u00e3o tem ningu\u00e9m oferecendo no momento, muitos entram [nas vendas <em>online<\/em>] para oferecer algo que j\u00e1 existe, que j\u00e1 tem um concorrente\u201d, explicou.<\/p>\n<p>Segundo o gerente do Sebrae, nesse sentido, \u00e9 preciso aplicar o conceito da inova\u00e7\u00e3o, adapt\u00e1vel aos pequenos neg\u00f3cios. \u201cO que eu fa\u00e7o para me diferenciar e fazer com que a pessoa que compra de determinado estabelecimento me olhe e me coloque na sua lista de decis\u00e3o, e decida por mim? No canal digital isso \u00e9 mais forte porque l\u00e1 a concorr\u00eancia \u00e9 maior, h\u00e1 mais op\u00e7\u00f5es, ent\u00e3o a diferencia\u00e7\u00e3o \u00e9 fundamental\u201d, disse.<\/p>\n<p>De uma hora para outra, a empreendedora Bruna Castelo Branco, de 28 anos, precisou aprender esses caminhos do mercado <em>online<\/em> para manter seu sustento, em Teresina (PI). Ela tem uma loja f\u00edsica de roupas femininas desde setembro de 2018, a Mahalo, que acabou fechando em v\u00e1rios momentos durante a pandemia em raz\u00e3o das restri\u00e7\u00f5es adotadas pelo governo local. Mas diante da queda de 50% na demanda pelo seu produto principal, Bruna decidiu investir nas trufas de chocolate e hoje tamb\u00e9m toca a Trufas de Verdade, com atendimento <em>online<\/em> e <em>delivery<\/em> para a capital do Piau\u00ed.<\/p>\n<p>\u201cTem muita gente que tem o <em>online<\/em> muito fortalecido. Aqui era o contr\u00e1rio, o f\u00edsico \u00e9 melhor, mas com a pandemia, precisei fortalecer esse canal e foi dif\u00edcil\u201d, disse, explicando que passou a vender as roupas pela internet, enquanto buscava por capacita\u00e7\u00e3o e cursos \u00e0 dist\u00e2ncia para impulsionar o neg\u00f3cio <em>online<\/em>. \u201cMas as pessoas n\u00e3o estavam comprando roupa, n\u00e3o era o momento para aquilo ali, mesmo fazendo campanhas de frete gr\u00e1tis, facilita\u00e7\u00e3o de trocas e outros recursos que eu utilizei\u201d, contou.<\/p>\n<p>O caminho foi aprender outro of\u00edcio e, ent\u00e3o, passou a fazer trufas em casa. \u201cPensei: vou vender alguma coisa de comida, porque isso as pessoas est\u00e3o consumindo. Por mais que a situa\u00e7\u00e3o esteja dif\u00edcil e tudo mais que estamos vivendo, voc\u00ea consegue tirar um dinheiro para comer um doce\u201d, disse. E o neg\u00f3cio de trufas deu t\u00e3o certo que Bruna j\u00e1 pensa, um dia, em colocar um ponto fixo de vendas. \u201cPor conta ainda dessa incerteza [com os rumos da pandemia] n\u00e3o vou montar uma doceria agora porque n\u00e3o \u00e9 o momento de aumentar despesas com outro aluguel e funcion\u00e1rios\u201d, explicou.<\/p>\n<p>Al\u00e9m dos neg\u00f3cios com as roupas e os doces, com as boas vendas de final de ano, Bruna reformou a sua loja, passou a vender acess\u00f3rios esportivos e montou a Meus Acess\u00f3rios, tamb\u00e9m com atendimento <em>online<\/em> e na loja f\u00edsica. \u201cO importante \u00e9 n\u00e3o perder a esperan\u00e7a mesmo. Tem muita gente que quebrou, o com\u00e9rcio abalou demais. Mas a gente tem que estar preparado, o mundo do empreendedorismo \u00e9 isso. Sempre vai ter algu\u00e9m que goste e est\u00e1 disposto a comprar o seu produto, ent\u00e3o n\u00e3o precisa desistir ou ter vergonha de vender\u201d, disse.<\/p>\n<p>De acordo com Matsumoto, ap\u00f3s ter o neg\u00f3cio consolidado, o empreendedor receber\u00e1 dois sinais que apontam a necessidade de ampliar a empresa: a insatisfa\u00e7\u00e3o pessoal e a limita\u00e7\u00e3o de conhecimento.<\/p>\n<p>\u201cA primeira situa\u00e7\u00e3o \u00e9 quando o trabalho deixa de ser prazeroso, satisfat\u00f3rio, e virar um castigo, uma preocupa\u00e7\u00e3o. \u00c9 sinal que ele precisa se profissionalizar. At\u00e9 um certo ponto, o dono consegue tocar sozinho, mas quando come\u00e7a a crescer e isso passa a atrapalhar os controles, a qualidade, ent\u00e3o \u00e9 hora de evoluir\u201d, explicou.<\/p>\n<p>O segundo momento, de acordo com o especialista, \u00e9 quando a vontade de crescer existe, mas o empreendedor n\u00e3o tem todos os conhecimentos. \u201c\u00c0s vezes ele \u00e9 bom em fazer um produto ou servi\u00e7o, mas n\u00e3o \u00e9 bom no <em>marketing<\/em> ou venda ou gest\u00e3o de pessoas. \u00c9 o momento em que ele percebe que sozinho n\u00e3o tem as compet\u00eancias necess\u00e1rias para a empresa crescer e come\u00e7a a buscar outros colaboradores ou at\u00e9 uma consultoria\u201d, disse.<\/p>\n<p>Para o especialista em gest\u00e3o, com as incertezas sobre a pandemia ainda n\u00e3o \u00e9 poss\u00edvel definir os rumos do mercado, ent\u00e3o, os empreendedores devem tentar entender o pr\u00f3prio cen\u00e1rio, o produto ou servi\u00e7o que oferecem e se precisam fazer adapta\u00e7\u00f5es para se manter ou continuar crescendo no mercado. \u201cObter informa\u00e7\u00f5es e transform\u00e1-las em algo que ajude na empresa ou mesmo se atentar para outras oportunidades que surgiram com a nova reconfigura\u00e7\u00e3o social\u201d, disse.<\/p>\n<p>A empreendedora Ma\u00edra da Costa, de 39 anos, ficou atenta e tamb\u00e9m precisou reinventar seu neg\u00f3cio no ano passado. A partir de pesquisas com os pr\u00f3prios clientes, conseguiu manter a Free Soul Food em funcionamento em S\u00e3o Paulo (SP). \u201cAcho que o empreendedor tem que ter bem claro que \u00e9 o cliente que ajuda a te nortear quando acontecem essas coisas [no caso, a pandemia], \u00e9 preciso entender o que o cliente est\u00e1 fazendo e o que ele precisa\u201d, disse.<\/p>\n<p>H\u00e1 cinco anos no ramo da gastronomia, Ma\u00edra toca com a m\u00e3e a empresa que oferece alimenta\u00e7\u00e3o para pessoas com restri\u00e7\u00f5es alimentares, veganos e vegetarianos e tamb\u00e9m atuava com servi\u00e7o de <em>buffet<\/em> completo para eventos sociais e grandes clientes corporativos, como <em>coffee breaks<\/em> e coquet\u00e9is. Com as mudan\u00e7as impostas pela pandemia e a ado\u00e7\u00e3o do trabalho remoto em muitas corpora\u00e7\u00f5es, foi necess\u00e1rio explorar outros modelos de neg\u00f3cios. \u201cT\u00ednhamos v\u00e1rios eventos agendados para o segundo semestre [de 2020] e simplesmente foram cancelados\u201d, disse.<\/p>\n<p>No primeiro momento, elas passaram a oferecer cursos para pessoas f\u00edsicas e jur\u00eddicas, entre eles, de panifica\u00e7\u00e3o, prote\u00edna vegetal e alimenta\u00e7\u00e3o saud\u00e1vel. No segundo momento, por demanda dos clientes, foi a vez de explorar as vendas <em>online<\/em> e o servi\u00e7o de <em>delivery<\/em>.<\/p>\n<p>Hoje, elas oferecem cestas de refei\u00e7\u00f5es pr\u00e9-prontas e alimentos cortados e fracionados para serem feitas em casa. \u201cTodos estavam tentando se virar, a maioria em <em>home office<\/em>, para dar conta da alimenta\u00e7\u00e3o da fam\u00edlia; muitos estavam perdidos sobre o que comprar e como preparar as refei\u00e7\u00f5es. Ent\u00e3o, a partir de uma pesquisa, lan\u00e7amos a cesta inclusiva\u201d, explicou. Os pedidos s\u00e3o feitos pela internet, com entrega para diversas regi\u00f5es da cidade de S\u00e3o Paulo.<\/p>\n<p>Al\u00e9m da cesta para atender as fam\u00edlias, elas tamb\u00e9m queriam uma alternativa para manter o atendimento \u00e0s pessoas jur\u00eddicas e perceberam que os eventos continuavam acontecendo em um modelo diferente, com equipes reduzidas e transmiss\u00f5es <em>online<\/em>. Dessa forma, tamb\u00e9m foi criado o <em>coffee break<\/em> na caixa.<\/p>\n<p>\u201cParte dessas mudan\u00e7as n\u00e3o foram em processos simples, ficamos quase quatro meses com a empresa fechada. Fizemos a pesquisa e come\u00e7amos a oferecer os cursos para n\u00e3o perder o contato com o cliente. Al\u00e9m disso, participei de capacita\u00e7\u00f5es de entidades diferentes para podermos nos adaptar. A gente entende que o normal, como conhec\u00edamos, n\u00e3o existir\u00e1 mais, as pessoas v\u00e3o precisar se adaptar\u201d, explicou Ma\u00edra.<\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/1788122\/informacao-e-planejamento-sao-chaves-para-profissionalizar-negocios?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informa\u00e7\u00e3o e planejamento s\u00e3o as palavras-chaves para quem decide empreender, seja por necessidade ou por<\/p>\n","protected":false},"author":0,"featured_media":717,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=716"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/717"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}