{"id":602,"date":"2021-03-21T08:23:19","date_gmt":"2021-03-21T11:23:19","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/governo-brasileiro-diz-negociar-com-eua-compra-de-excedente-de-vacinas\/"},"modified":"2021-03-21T08:23:19","modified_gmt":"2021-03-21T11:23:19","slug":"governo-brasileiro-diz-negociar-com-eua-compra-de-excedente-de-vacinas","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/governo-brasileiro-diz-negociar-com-eua-compra-de-excedente-de-vacinas\/","title":{"rendered":"Governo brasileiro diz negociar com EUA compra de excedente de vacinas"},"content":{"rendered":"<p>O Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores informou neste s\u00e1bado (20) que est\u00e1 negociando com o governo dos Estados Unidos a compra de vacinas excedentes contra o novo coronav\u00edrus daquele pa\u00eds.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>A informa\u00e7\u00e3o foi divulgada nas redes sociais do minist\u00e9rio, que afirma estar com a negocia\u00e7\u00e3o em andamento h\u00e1 uma semana.<br \/>&#8220;Desde o dia 13\/3 o governo brasileiro, atrav\u00e9s do Itamaraty e da embaixada em Washington, em coordena\u00e7\u00e3o com o Minist\u00e9rio da Sa\u00fade, est\u00e1 em tratativas com o governo dos EUA para viabilizar a importa\u00e7\u00e3o pelo Brasil de vacinas do excedente dispon\u00edvel nos Estados Unidos&#8221;, afirma o texto divulgado.<\/p>\n<p>Na \u00faltima quinta, os EUA anunciaram que planejam enviar para o M\u00e9xico e o Canad\u00e1 cerca de 4 milh\u00f5es de doses da vacina contra a Covid-19 produzida pela AstraZeneca\/Oxford \u2013cuja autoriza\u00e7\u00e3o de uso ainda n\u00e3o foi aprovada no pa\u00eds.<br \/>Fontes no governo tamb\u00e9m afirmam que devem chegar neste domingo as primeiras doses das vacinas previstas pelo cons\u00f3rcio Covax Facility, iniciativa que conta com a ades\u00e3o do Brasil.<\/p>\n<p>A informa\u00e7\u00e3o da negocia\u00e7\u00e3o com os americanos foi divulgada um dia ap\u00f3s o presidente do Senado, Rodrigo Pacheco (DEM-MG), ter enviado of\u00edcio \u00e0 vice-presidente americana, Kamala Harris, com um pedido de &#8220;socorro&#8221; e um apelo pela importa\u00e7\u00e3o do excedente das vacinas dos Estados Unidos.<\/p>\n<p>No documento, Pacheco afirma que o Brasil virou o epicentro da pandemia da Covid-19 no mundo e que o r\u00e1pido avan\u00e7o do v\u00edrus no Brasil representa um risco para todo o hemisf\u00e9rio ocidental.<br \/>O presidente do Senado tamb\u00e9m menciona a &#8220;ang\u00fastia e sofrimento&#8221; dos brasileiros com o recrudescimento da pandemia no Brasil.<\/p>\n<p>O senador pede autoriza\u00e7\u00e3o especial para que o Brasil compre doses da vacina da AstraZeneca, que j\u00e1 aprovada pela Anvisa (Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria), recebendo o registro definitivo. Pacheco lembra que a j\u00e1 come\u00e7ou a fabricar a imuniza\u00e7\u00e3o em territ\u00f3rio nacional, mas sofre com a chegada dos ingredientes importados.<\/p>\n<p>A postagem do Itamaraty n\u00e3o menciona o of\u00edcio de Pacheco. No entanto, foi vista como uma resposta ao presidente do Senado.<br \/>Pacheco vem sendo o principal respons\u00e1vel por evitar a instala\u00e7\u00e3o de uma CPI (Comiss\u00e3o Parlamentar de Inqu\u00e9rito) no Senado para investigar a atua\u00e7\u00e3o do governo no enfrentamento \u00e0 pandemia do novo coronav\u00edrus.<\/p>\n<p>O requerimento para a abertura da comiss\u00e3o j\u00e1 conta com as assinaturas suficientes, mas a decis\u00e3o final cabe exclusivamente a Pacheco. A press\u00e3o para a instala\u00e7\u00e3o aumentou a partir de quinta-feira, ap\u00f3s a morte do senador Major Ol\u00edmpio (PSL-SP). Ele foi o terceiro senador a morrer v\u00edtima da Covid, mas sua morte causou um impacto maior, porque era carism\u00e1tico e se relacionava bem com os demais.<\/p>\n<p>Em uma tentativa de atuar de forma colaborativa com o governo, Pacheco tamb\u00e9m apresentou uma proposta ao presidente Jair Bolsonaro (sem partido) para uma reuni\u00e3o na pr\u00f3xima quarta-feira, que pode evoluir para um comit\u00ea de enfrentamento \u00e0 pandemia, com a participa\u00e7\u00e3o de Executivo, Legislativo, Judici\u00e1rio, governadores, prefeitos e demais entes.<\/p>\n<p>Bolsonaro aceitou a ideia e passou a liderar a iniciativa, convidando por telefone tamb\u00e9m os presidentes da C\u00e2mara, Arthur Lira (PP-AL), e do STF (Supremo Tribunal Federal), Luiz Fux. Parlamentares consideram que essa reuni\u00e3o e o comit\u00ea podem ser a &#8220;\u00faltima chance&#8221; de Bolsonaro. Caso a iniciativa fracasse, consideram inevit\u00e1vel a abertura da CPI e outras medidas contr\u00e1rias ao governo.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Mundo<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/mundo\/1787991\/governo-brasileiro-diz-negociar-com-eua-compra-de-excedente-de-vacinas?utm_source=rss-mundo&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores informou neste s\u00e1bado (20) que est\u00e1 negociando com o governo<\/p>\n","protected":false},"author":0,"featured_media":603,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=602"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/603"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}