{"id":584,"date":"2021-03-21T08:23:16","date_gmt":"2021-03-21T11:23:16","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/viih-tube-vence-anjo-no-bbb-21-e-indica-rodolffo-e-arthur-para-o-monstro\/"},"modified":"2021-03-21T08:23:16","modified_gmt":"2021-03-21T11:23:16","slug":"viih-tube-vence-anjo-no-bbb-21-e-indica-rodolffo-e-arthur-para-o-monstro","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/viih-tube-vence-anjo-no-bbb-21-e-indica-rodolffo-e-arthur-para-o-monstro\/","title":{"rendered":"Viih Tube vence Anjo no BBB 21 e indica Rodolffo e Arthur para o Monstro"},"content":{"rendered":"<p>Viih Tube \u00e9 o Anjo da semana ap\u00f3s marcar mais pontos no jogo da mem\u00f3ria da Prova do Anjo no in\u00edcio da tarde deste s\u00e1bado (20) no Big Brother Brasil 21. Com a vit\u00f3ria, a influenciadora indicou Rodolffo e Arthur para o Castigo do Monstro.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Al\u00e9m do colar de Anjo, ela tamb\u00e9m recebeu pr\u00eamio de R$ 5.000 em dinheiro e mais R$ 5.000 em ra\u00e7a -a prova foi patrocinada pela empresa Organnact. L\u00edder, Gilberto J\u00fanior n\u00e3o participou da prova -o doutorando em economia \u00e9 o L\u00edder da semana.<\/p>\n<p>Para participar da prova, os competidores tiveram que retirar bolinhas da urna: a de cor amarela jogava, a branca n\u00e3o. Com isso, Jo\u00e3o Luiz, Tha\u00eds, Sarah e Arthur foram eliminados da Prova do Anjo. Os demais fizeram um novo sorteiro para saber a ordem e quem usaria a roupa de cachorro ou de gato.<\/p>\n<p>Como definiu Tiago Leifert, a prova foi de m\u00e9rito j\u00e1 que a vit\u00f3ria dependia apenas de os participantes conseguirem memorizar as imagens dos produtos de suplementos para animais. Durante a prova, eles chegaram a reclamar do calor e da roupa.<\/p>\n<p>A sequ\u00eancia do jogo foi: Fiuk (gato), Camilla de Lucas (cachorro), Caio Afiune (gato), Carla Diaz (cachorro), Juliette Freire (gato), Viih Tube (cachorro), Rodolffo (gato) e Pocah (cachorro). Quem acertasse mais as combina\u00e7\u00f5es se consagraria Anjo. Entre as regras, o jogador teria direito a jogar novamente caso acertasse o card.<\/p>\n<p>Na primeira rodada, Juliette marca um ponto. Na etapa seguinte, Camilla de Lucas marca um ponto e Caio dois. J\u00e1 na terceira rodada, Carla e Pocah marcam um ponto e Viih Tube marca tr\u00eas. J\u00e1 na quarta etapa, Camilla de Lucas marca um ponto, Carla e Pocah fazem dois e Viih Tuber marca quatro. Na quinta rodada, Camilla e Caio marcam um ponto.<\/p>\n<p>PARED\u00c3O O oitavo Pared\u00e3o ser\u00e1 formado neste domingo (21). Ser\u00e3o quatro indica\u00e7\u00f5es: indica\u00e7\u00e3o do l\u00edder, participante mais votado da casa e a primeira dupla a sair da Prova do L\u00edder.<\/p>\n<p>Por serem os primeiros a desistir da Prova do L\u00edder, Fiuk e Carla Diaz est\u00e3o na berlinda. Ap\u00f3s quase nove horas de prova, o cantor disse precisar ir ao banheiro e perguntou para Carla Diaz se poderiam desistir. A atriz concordou e soltou a alavanca. Os dois ainda podem escapar caso ven\u00e7am a Prova Bate e Volta.<\/p>\n<p>L\u00edder, Gilberto J\u00fanior ainda estuda quem deve ser seu indicado ao Pared\u00e3o, que n\u00e3o tem direito de fazer a Prova Bate e Volta. Na madrugada deste s\u00e1bado (20), Arthur Picoli e Gilberto conversaram e o instrutor de crossfit afirmou que ele deve ser um dos indicados ao Pared\u00e3o.<\/p>\n<p>&#8220;Sobrou tudo para mim&#8221;, disse Arthur, que se afastou de Carla Diaz nos \u00faltimos dias e mant\u00e9m desaven\u00e7as com Fiuk desde o in\u00edcio do programa.<\/p>\n<p>Gilberto perguntou para Arthur se ele avalia que pode ir pela casa com v\u00e1rios votos. &#8220;N\u00e3o sei. Estou pensando em uma jogada a\u00ed que \u00e9 meio suicida. De voc\u00ea me botar&#8221;, responde o crossfiteiro. &#8220;Eu estava pensando nisso por alguns motivos&#8221;, revela Gilberto.<br \/>Arthur, ent\u00e3o, disse ter receio de que se for indica\u00e7\u00e3o ao Pared\u00e3o pelo l\u00edder, Rodolffo se torne alvo da casa: &#8220;Porque a\u00ed o problema vai sobrar tudo no Rodolffo ou no Caio.&#8221; &#8220;Mais, a\u00ed, n\u00e3o \u00e9 contigo&#8221;, retruca o doutorando em economia. &#8220;N\u00e3o quero que os caras se ferrem, mas confesso que estou pensando muito na possibilidade&#8221;, continua Arthur.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/1787968\/3-viih-tube-vence-anjo-no-bbb-21-e-indica-rodolffo-e-arthur-para-o-monstro?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viih Tube \u00e9 o Anjo da semana ap\u00f3s marcar mais pontos no jogo da mem\u00f3ria<\/p>\n","protected":false},"author":0,"featured_media":585,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=584"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/585"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}