{"id":487,"date":"2021-03-21T08:22:28","date_gmt":"2021-03-21T11:22:28","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/trilha-no-morro-de-santo-antonio-deve-ser-comunicada-com-antecedencia-a-sema\/"},"modified":"2021-03-21T08:22:28","modified_gmt":"2021-03-21T11:22:28","slug":"trilha-no-morro-de-santo-antonio-deve-ser-comunicada-com-antecedencia-a-sema","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/trilha-no-morro-de-santo-antonio-deve-ser-comunicada-com-antecedencia-a-sema\/","title":{"rendered":"Trilha no Morro de Santo Ant\u00f4nio deve ser comunicada com anteced\u00eancia \u00e0 Sema"},"content":{"rendered":"<br \/>\n<article>\n<header>Trilha no Morro de Santo Ant\u00f4nio deve ser comunicada com anteced\u00eancia \u00e0 Sema<\/header>\n<h2>Grupos com mais de 10 pessoas precisam ser acompanhados pelo Corpo de Bombeiros<\/h2>\n<p><span><br \/>\n    Sabrina Ventresqui<br \/>\n<\/span><br \/>\n    | <span>Sema<\/span><\/p>\n<div>\n<div>\n             &#8211; Foto por: Sema\/MT\n        <\/div>\n<p>        <img decoding=\"async\" alt=\"\" src=\"http:\/\/www.mt.gov.br\/documents\/21013\/11604101\/Morro+de+Santo+Ant%C3%B4nio\/246d62c4-9ec3-4bef-4558-98dd1cbdc35d?t=1565991732980+&amp;imageThumbnail=3\" title=\" - Foto por: Sema\/MT\"><\/div>\n<div class=\"full-content\">\n<p>O Monumento Natural\u00a0Morro de Santo Ant\u00f4nio, localizado no Munic\u00edpio de Santo Ant\u00f4nio do Leverger (27 km de Cuiab\u00e1), \u00e9 um dos pontos tur\u00edsticos mais conhecidos de Mato Grosso, especialmente para quem \u00e9 adepto de trilhas ou outras atividades ao ar livre.<\/p>\n<p>Para a visita\u00e7\u00e3o do local, a Secretaria de Estado de Meio Ambiente (Sema-MT) solicita que os interessados em realizar a subida fa\u00e7am o aviso pr\u00e9vio com pelo menos 48 horas de anteced\u00eancia para que o acesso seja controlado, e que possa ter apoio em caso de acidentes.\u00a0<\/p>\n<p>Segundo o gerente do Morro de Santo Ant\u00f4nio, Lucas Nascimento Padilha Silva, o visitante deve avisar a data de subida por e-mail ou por telefone.<\/p>\n<p>\u201cO visitante precisa preencher dois termos, um de autoriza\u00e7\u00e3o e outro de responsabilidade. Grupos com mais de 10 pessoas precisam ser acompanhados pelo Corpo de Bombeiros. Caso o visitante se recuse a assinar os termos, ser\u00e1 impedido de realizar a trilha&#8221;, explica o gerente.\u00a0<\/p>\n<p>O local est\u00e1 aberto a visita\u00e7\u00e3o durante o per\u00edodo de pandemia. O ponto tur\u00edstico est\u00e1 funcionando seguindo todas as regras de preven\u00e7\u00e3o contra o coronav\u00edrus. \u00c1lcool em gel, uso de m\u00e1scaras e o distanciamento social s\u00e3o imprescind\u00edveis para a visita\u00e7\u00e3o do Morro de Santo Ant\u00f4nio.\u00a0<\/p>\n<p>Para entrar em contato com a ger\u00eancia do Morro de Santo Ant\u00f4nio ligue: (65) 99245-5783 ou se preferir mande um e-mail para mnmorrostoantonio@sema.mt.gov.br. O hor\u00e1rio de funcionamento da gerencia \u00e9 das 07h30min \u00e0s 17h30min.\u00a0<\/p>\n<p><strong>Servi\u00e7o:<\/strong><br \/>\nSubida do Morro de Santo Ant\u00f4nio<br \/>\nAgendamento: (65) 99245-5783 ou mnmorrostoantonio@sema.mt.gov.br<\/p>\n<p>(Supervis\u00e3o\u00a0de\u00a0texto\u00a0de Lorena Bruschi)<\/p>\n<\/div>\n<p><\/p>\n<footer>C<\/footer>\n<\/article>\n<p><a href=\"http:\/\/www.mt.gov.br\/-\/16724037-trilha-no-morro-de-santo-antonio-deve-ser-comunicada-com-antecedencia-a-sema\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nGoverno do Estado de Mato Grosso<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trilha no Morro de Santo Ant\u00f4nio deve ser comunicada com anteced\u00eancia \u00e0 Sema Grupos com<\/p>\n","protected":false},"author":0,"featured_media":488,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=487"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/487\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/488"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}