{"id":483,"date":"2021-03-21T08:22:17","date_gmt":"2021-03-21T11:22:17","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/video-que-circula-nas-redes-sociais-e-do-inicio-do-mes-confira-as-medidas-atuais\/"},"modified":"2021-03-21T08:22:17","modified_gmt":"2021-03-21T11:22:17","slug":"video-que-circula-nas-redes-sociais-e-do-inicio-do-mes-confira-as-medidas-atuais","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/video-que-circula-nas-redes-sociais-e-do-inicio-do-mes-confira-as-medidas-atuais\/","title":{"rendered":"V\u00eddeo que circula nas redes sociais \u00e9 do in\u00edcio do m\u00eas; confira as medidas atuais"},"content":{"rendered":"<br \/>\n<article>\n<header>V\u00eddeo que circula nas redes sociais \u00e9 do in\u00edcio do m\u00eas; confira as medidas atuais<\/header>\n<h2>Pronunciamento era referente ao primeiro decreto restritivo; medidas foram atualizadas<\/h2>\n<p><span><br \/>\n    Lucas Rodrigues<br \/>\n<\/span><br \/>\n    | <span>Secom-MT<\/span><\/p>\n<div>\n<div>\n            V\u00eddeo que circula nas redes sociais \u00e9 antigo &#8211; Foto por: Reprodu\u00e7\u00e3o\n        <\/div>\n<p>        <img decoding=\"async\" alt=\"V\u00eddeo que circula nas redes sociais \u00e9 antigo\" src=\"http:\/\/www.mt.gov.br\/documents\/21013\/16717720\/Video+antigo+Mauro+Mendes\/afb6b4f6-0ac8-305d-3066-8d2e73bb120e?t=1616265046613+&amp;imageThumbnail=3\" title=\"V\u00eddeo que circula nas redes sociais \u00e9 antigo - Foto por: Reprodu\u00e7\u00e3o\"><\/div>\n<div class=\"full-content\">\n<p>O Governo de Mato Grosso esclarece que o v\u00eddeo que tem circulado nos \u00faltimos dias nas redes sociais &#8211; no qual o governador Mauro Mendes fala sobre medidas restritivas &#8211; \u00e9 datado do dia 1\u00ba de mar\u00e7o e j\u00e1 n\u00e3o representa as atuais regras, que foram atualizadas.<\/p>\n<p>Neste momento, est\u00e1 em vigor o decreto publicado no Di\u00e1rio Oficial do dia 16 de mar\u00e7o.<\/p>\n<p>Entre as atualiza\u00e7\u00f5es est\u00e1 a permiss\u00e3o para supermercados abrirem aos s\u00e1bados at\u00e9 \u00e0s 19h e aos domingos at\u00e9 o meio-dia; restaurantes at\u00e9 \u00e0s 14h nos s\u00e1bados e domingos; e delivery at\u00e9 \u00e0s 23h. Tamb\u00e9m est\u00e1 permitido at\u00e9 \u00e0s 2045m o funcionamento de restaurantes e cong\u00eaneres nas modalidades take-away (pegue e leve) e drive-thru.<\/p>\n<p><strong>Confira as regras atuais, v\u00e1lidas para os 141 munic\u00edpios de Mato Grosso:<\/strong><\/p>\n<p>&#8211; De segunda \u00e0 sexta, proibi\u00e7\u00e3o de todas as atividades econ\u00f4micas das 19h \u00e0s 5h. Aos s\u00e1bados e domingos, a proibi\u00e7\u00e3o ser\u00e1 ap\u00f3s o meio-dia. A exce\u00e7\u00e3o fica por conta das farm\u00e1cias, imprensa, hospedagem, servi\u00e7os de guincho, seguran\u00e7a e vigil\u00e2ncia privada, servi\u00e7os de sa\u00fade, funer\u00e1rias, postos de gasolina (exceto conveni\u00eancias), ind\u00fastrias, transporte de alimentos e gr\u00e3os, e servi\u00e7os de manuten\u00e7\u00e3o de atividades essenciais, como \u00e1gua, energia, telefone e coleta de lixo.<\/p>\n<p>&#8211; Supermercados poder\u00e3o funcionar nos s\u00e1bados das 5h \u00e0s 19h. Aos domingos at\u00e9 o meio-dia.<\/p>\n<p>&#8211; Restaurantes, inclusive os localizados em shoppings, poder\u00e3o atender nos s\u00e1bados e domingos at\u00e9 \u00e0s 14h.<\/p>\n<p>&#8211; Fica autorizado o funcionamento de restaurantes e cong\u00eaneres nas modalidades take-away e drive-thru somente at\u00e9 \u00e0s 20h45m.<\/p>\n<p>&#8211; Nos hor\u00e1rios permitidos, as atividades econ\u00f4micas dever\u00e3o respeitar as medidas de seguran\u00e7a, como o uso de m\u00e1scara, distanciamento e limita\u00e7\u00e3o de 50% da capacidade m\u00e1xima do local.<\/p>\n<p>&#8211; Eventos podem ocorrer dentro do hor\u00e1rio permitido, respeitado o limite 30% da capacidade do local, e n\u00famero m\u00e1ximo de 50 pessoas.<\/p>\n<p>&#8211; Os servi\u00e7os de entrega por delivery seguem autorizados at\u00e9 \u00e0s 23h.<\/p>\n<p>&#8211; O transporte coletivo e cong\u00eaneres (Uber, 99, etc) podem funcionar normalmente.<\/p>\n<p>&#8211; Toque de recolher a partir das 21h at\u00e9 \u00e0s 5h, com proibi\u00e7\u00e3o de circula\u00e7\u00e3o.<\/p>\n<p>&#8211; Nos \u00f3rg\u00e3os p\u00fablicos estaduais, fica suspenso o atendimento presencial em todas as secretarias e \u00f3rg\u00e3os do governo, com exce\u00e7\u00e3o das unidades final\u00edsticas. Quanto a jornada de trabalho, cada secretaria\/autarquia vai disciplinar medidas para redu\u00e7\u00e3o do fluxo de pessoas.<\/p>\n<\/div>\n<p><\/p>\n<footer>C<\/footer>\n<\/article>\n<p><a href=\"http:\/\/www.mt.gov.br\/-\/16727962-video-que-circula-nas-redes-sociais-e-do-inicio-do-mes-confira-as-medidas-atuais\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nGoverno do Estado de Mato Grosso<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00eddeo que circula nas redes sociais \u00e9 do in\u00edcio do m\u00eas; confira as medidas atuais<\/p>\n","protected":false},"author":0,"featured_media":484,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=483"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/483\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/484"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}