{"id":2562,"date":"2021-03-29T18:11:12","date_gmt":"2021-03-29T21:11:12","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/29\/segunda-feira-29-mato-grosso-registra-304-416-casos-e-7-485-obitos-por-covid-19\/"},"modified":"2021-03-29T18:11:12","modified_gmt":"2021-03-29T21:11:12","slug":"segunda-feira-29-mato-grosso-registra-304-416-casos-e-7-485-obitos-por-covid-19","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/29\/segunda-feira-29-mato-grosso-registra-304-416-casos-e-7-485-obitos-por-covid-19\/","title":{"rendered":"Segunda-feira (29): Mato Grosso registra 304.416 casos e 7.485 \u00f3bitos por Covid-19"},"content":{"rendered":"<br \/>\n<article>\n<header>Segunda-feira (29): Mato Grosso registra 304.416 casos e 7.485 \u00f3bitos por Covid-19<\/header>\n<h2>H\u00e1 491 interna\u00e7\u00f5es em UTIs p\u00fablicas e 512 em enfermarias p\u00fablicas; taxa de ocupa\u00e7\u00e3o est\u00e1 em 96% para UTIs adulto e em 61% para enfermarias.<\/h2>\n<p><span><br \/>\n    Rose Velasco<br \/>\n<\/span><br \/>\n    | <span>SES-MT<\/span><\/p>\n<div>\n<div>\n            Um total de 270.223 amostras j\u00e1 foram avaliadas pelo Laborat\u00f3rio Central do Estado (Lacen-MT) &#8211; Foto por: Tch\u00e9lo Figueiredo\n        <\/div>\n<p>        <img decoding=\"async\" alt=\"Um total de 270.223 amostras j\u00e1 foram avaliadas pelo Laborat\u00f3rio Central do Estado (Lacen-MT)\" src=\"http:\/\/www.mt.gov.br\/documents\/21013\/11469654\/_TCH5376.jpg\/6de9de1b-993e-07bb-9089-a480e06b2462?t=1557930779523+&amp;imageThumbnail=3\" title=\"Um total de 270.223 amostras j\u00e1 foram avaliadas pelo Laborat\u00f3rio Central do Estado (Lacen-MT) - Foto por: Tch\u00e9lo Figueiredo\"><\/div>\n<div class=\"full-content\">\n<p>A Secretaria de Estado de Sa\u00fade (SES-MT) notificou, at\u00e9 a tarde desta segunda-feira (29.03), 304.416 casos confirmados da Covid-19 em Mato Grosso, sendo registrados 7.485 \u00f3bitos em decorr\u00eancia do coronav\u00edrus no Estado.<\/p>\n<p>Foram notificadas 2.205 novas confirma\u00e7\u00f5es de casos de coronav\u00edrus no Estado. Dos 304.416 casos confirmados da Covid-19 em Mato Grosso, 15.002 est\u00e3o em isolamento domiciliar e 279.760 est\u00e3o recuperados.<\/p>\n<p>Entre casos confirmados, suspeitos e descartados para a Covid-19, h\u00e1 491 interna\u00e7\u00f5es em UTIs p\u00fablicas e 512 enfermarias p\u00fablicas. Isto \u00e9, a taxa de ocupa\u00e7\u00e3o est\u00e1 em 96,65% para UTIs adulto e em 61% para enfermarias adulto.<\/p>\n<p>Dentre os dez munic\u00edpios com maior n\u00famero de casos de Covid-19 est\u00e3o: Cuiab\u00e1 (65.583), Rondon\u00f3polis (23.227), V\u00e1rzea Grande (19.535), Sinop (15.253), Sorriso (11.498), Tangar\u00e1 da Serra (10.811), Lucas do Rio Verde (10.235), Primavera do Leste (8.951), C\u00e1ceres (6.614) e Alta Floresta (5.870).\u00a0<\/p>\n<p>A lista detalhada com todas as cidades que j\u00e1 registraram casos da Covid-19 em Mato Grosso pode ser acessada por meio do Painel Interativo da Covid-19, dispon\u00edvel\u00a0<a href=\"http:\/\/www.saude.mt.gov.br\/painelcovidmt2\/\">neste link<\/a>.<\/p>\n<p>O documento ainda aponta que um total de 270.223 amostras j\u00e1 foram avaliadas pelo Laborat\u00f3rio Central do Estado (Lacen-MT) e que, atualmente, restam 483 amostras em an\u00e1lise laboratorial.<\/p>\n<p><strong>Cen\u00e1rio nacional<\/strong><\/p>\n<p>No \u00faltimo domingo (28), o Governo Federal confirmou o total de 12.534.688 casos da Covid-19 no Brasil e 312.206 \u00f3bitos oriundos da doen\u00e7a. No levantamento do dia anterior, o pa\u00eds contabilizava 12.490.362 casos da Covid-19 no Brasil e 310.550 \u00f3bitos confirmados de pessoas infectadas pelo coronav\u00edrus.\u00a0<\/p>\n<p>At\u00e9 o fechamento deste material, o Minist\u00e9rio da Sa\u00fade n\u00e3o divulgou os dados atualizados desta segunda-feira (29).<\/p>\n<p><strong>Recomenda\u00e7\u00f5es<\/strong><\/p>\n<p>J\u00e1 h\u00e1 uma vacina para prevenir a infec\u00e7\u00e3o pelo novo coronav\u00edrus, mas ainda \u00e9 importante adotar algumas medidas de distanciamento e biosseguran\u00e7a.<\/p>\n<p>Os sites da SES e do Minist\u00e9rio da Sa\u00fade disp\u00f5em de informa\u00e7\u00f5es oficiais acerca da Covid-19. A orienta\u00e7\u00e3o \u00e9 de que n\u00e3o sejam divulgadas informa\u00e7\u00f5es inver\u00eddicas, pois as not\u00edcias falsas causam p\u00e2nico e atrapalham a condu\u00e7\u00e3o dos trabalhos pelos servi\u00e7os de sa\u00fade.<\/p>\n<p>O Minist\u00e9rio da Sa\u00fade orienta os cuidados b\u00e1sicos para reduzir o risco geral de contrair ou transmitir infec\u00e7\u00f5es respirat\u00f3rias agudas, incluindo o novo v\u00edrus. Entre as medidas est\u00e3o:<\/p>\n<p>&#8211; Lavar as m\u00e3os frequentemente com \u00e1gua e sab\u00e3o por pelo menos 20 segundos. Se n\u00e3o houver \u00e1gua e sab\u00e3o, usar um desinfetante para as m\u00e3os \u00e0 base de \u00e1lcool;<\/p>\n<p>&#8211; Evitar tocar nos olhos, nariz e boca com as m\u00e3os n\u00e3o lavadas;<\/p>\n<p>&#8211; Evitar contato pr\u00f3ximo com pessoas doentes;<\/p>\n<p>&#8211; Cobrir boca e nariz ao tossir ou espirrar com um len\u00e7o de papel e jogar no lixo;<\/p>\n<p>&#8211; Limpar e desinfetar objetos e superf\u00edcies tocados com frequ\u00eancia.<\/p>\n<\/div>\n<p><span class=\"attach-title\">Download <i class=\"icon-download-alt\"><\/i><\/span><\/p>\n<div class=\"attach-content\">\n<ol><a href=\"http:\/\/www.mt.gov.br\/documents\/21013\/0\/Painel+Epidemiol%C3%B3gico+386\/caeec6c8-0f48-292e-fac0-a71e85b3a2d8\" title=\"Baixar Painel Epidemiol\u00f3gico 386\"><\/p>\n<li>Painel Epidemiol\u00f3gico 386<\/li>\n<p>\t\t\t<\/a>\n\t\t\t\t<\/ol>\n<\/div>\n<footer>C<\/footer>\n<\/article>\n<p><a href=\"http:\/\/www.mt.gov.br\/-\/16774740-segunda-feira-29-mato-grosso-registra-304.416-casos-e-7.485-obitos-por-covid-19\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nGoverno do Estado de Mato Grosso<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segunda-feira (29): Mato Grosso registra 304.416 casos e 7.485 \u00f3bitos por Covid-19 H\u00e1 491 interna\u00e7\u00f5es<\/p>\n","protected":false},"author":0,"featured_media":2563,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-2562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2562"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/2563"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}