{"id":2531,"date":"2021-03-29T15:15:24","date_gmt":"2021-03-29T18:15:24","guid":{"rendered":"http:\/\/roteironoticias.com.br\/?p=2531"},"modified":"2021-03-29T15:15:25","modified_gmt":"2021-03-29T18:15:25","slug":"secretaria-de-saude-de-vera-convida-populacao-para-acompanhar-audiencia-publica-para-apresentacao-do-relatorio-anual-de-gestao","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/29\/secretaria-de-saude-de-vera-convida-populacao-para-acompanhar-audiencia-publica-para-apresentacao-do-relatorio-anual-de-gestao\/","title":{"rendered":"Secretaria de Sa\u00fade de Vera convida popula\u00e7\u00e3o para acompanhar audi\u00eancia p\u00fablica para apresenta\u00e7\u00e3o do Relat\u00f3rio Anual de Gest\u00e3o"},"content":{"rendered":"\n<p><em>A audi\u00eancia ser\u00e1 realizada nesta quarta-feira (31) \u00e0s 13h30 de forma remota devido \u00e0 pandemia do covid-19<\/em><\/p>\n\n\n\n<p>A Prefeitura Municipal de Vera atrav\u00e9s da Secretaria Municipal de Sa\u00fade convida toda a popula\u00e7\u00e3o verense, bem como as autoridades municipais para acompanhar a Audi\u00eancia P\u00fablica de apresenta\u00e7\u00e3o do Relat\u00f3rio Anual de Gest\u00e3o (RAG), do ano de 2020 e do Relat\u00f3rio Detalhado do 3\u00ba Quadrimestre do ano de 2020.<\/p>\n\n\n\n<p>Devido a estarmos passando pela pandemia do Coronav\u00edrus a Audi\u00eancia ser\u00e1 realizada na pr\u00f3xima quarta-feira (31) \u00e0s 13h30 de forma remota atrav\u00e9s da pela plataforma Google Meet, no seguinte endere\u00e7o eletr\u00f4nico: https:\/\/meet.google.com\/idd-hooz-wpe?authuser=0.<\/p>\n\n\n\n<p>Nutricionista do NASF Danieli Buzzacaro, falou sobre a realiza\u00e7\u00e3o da audi\u00eancia p\u00fablica. \u201cVamos fazer a nossa audi\u00eancia p\u00fablica da sa\u00fade de presta\u00e7\u00e3o de contas, de apresenta\u00e7\u00e3o 3\u00ba Relat\u00f3rio Quadrimestre detalhado do ano de 2020 e juntamente o Relat\u00f3rio Anual de Gest\u00e3o do ano de 2020 tamb\u00e9m. Por estarmos passando por este momento de pandemia n\u00e3o faremos como sempre \u00e9 feito, no plen\u00e1rio da C\u00e2mara de Vereadores, mas vamos fazer de forma remota pela plataforma Google Meet e estaremos disponibilizando o endere\u00e7o eletr\u00f4nico para todos\u201d, destacou.<\/p>\n\n\n\n<p>Danieli reformou o convite para que a popula\u00e7\u00e3o acompanhe a audi\u00eancia. \u201cGostaria de refor\u00e7ar o convite para toda a popula\u00e7\u00e3o, a audi\u00eancia p\u00fablica \u00e9 realizado com o intuito de todos participarem, e neste momento que temos um Decreto Estadual que nos diz para evitar reuni\u00f5es presenciais, para preferir usar da tecnologia como faremos neste momento, quem sabe a participa\u00e7\u00e3o da popula\u00e7\u00e3o seja at\u00e9 facilitada. Basta acessar o link atrav\u00e9s do computador ou do celular de onde estiver\u201d, conclui Buzzacaro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A audi\u00eancia ser\u00e1 realizada nesta quarta-feira (31) \u00e0s 13h30 de forma remota devido \u00e0 pandemia<\/p>\n","protected":false},"author":2,"featured_media":2536,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-2531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2531"}],"version-history":[{"count":1,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2531\/revisions"}],"predecessor-version":[{"id":2537,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2531\/revisions\/2537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/2536"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}