{"id":2270,"date":"2021-03-28T13:09:50","date_gmt":"2021-03-28T16:09:50","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/28\/tratores-caminhoes-e-helicoptero-em-um-ano-sema-remove-111-maquinas-utilizadas-em-crimes-ambientais-em-mt\/"},"modified":"2021-03-28T13:09:50","modified_gmt":"2021-03-28T16:09:50","slug":"tratores-caminhoes-e-helicoptero-em-um-ano-sema-remove-111-maquinas-utilizadas-em-crimes-ambientais-em-mt","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/28\/tratores-caminhoes-e-helicoptero-em-um-ano-sema-remove-111-maquinas-utilizadas-em-crimes-ambientais-em-mt\/","title":{"rendered":"Tratores, caminh\u00f5es e helic\u00f3ptero: Em um ano, Sema remove 111 m\u00e1quinas utilizadas em crimes ambientais em MT"},"content":{"rendered":"<br \/>\n<article>\n<header>Tratores, caminh\u00f5es e helic\u00f3ptero: Em um ano, Sema remove 111 m\u00e1quinas utilizadas em crimes ambientais em MT<\/header>\n<h2>Remo\u00e7\u00e3o dos equipamentos foi poss\u00edvel pela contrata\u00e7\u00e3o de empresa especializada com recursos do Programa REM<\/h2>\n<p><span><br \/>\n    Sabrina Ventresqui<br \/>\n<\/span><br \/>\n    | <span>Sema-MT<\/span><\/p>\n<div>\n<div>\n            Maquin\u00e1rio removido para o p\u00e1tio por ter sido utilizado em crimes ambientais &#8211; Foto por: Assessoria\n        <\/div>\n<p>        <img decoding=\"async\" alt=\"Maquin\u00e1rio removido para o p\u00e1tio por ter sido utilizado em crimes ambientais\" src=\"http:\/\/www.mt.gov.br\/documents\/21013\/16726262\/Maquin%C3%A1rio+apreendido+pela+fiscaliza%C3%A7%C3%A3o+de+crimes+ambientais\/378d65f5-53eb-8d7d-ba32-eab54abace1b?t=1616942895041+&amp;imageThumbnail=3\" title=\"Maquin\u00e1rio removido para o p\u00e1tio por ter sido utilizado em crimes ambientais - Foto por: Assessoria\"><\/div>\n<div class=\"full-content\">\n<p>Nos \u00faltimos doze meses, a Secretaria de Estado de Meio Ambiente (Sema-MT) removeu 111 m\u00e1quinas\u00a0(100 tratores, um helic\u00f3ptero, seis caminh\u00f5es e quatro ve\u00edculos) que estavam sendo utilizados em infra\u00e7\u00f5es ambientais em Mato Grosso.\u00a0 A opera\u00e7\u00f5es de combate ao desmatamento ilegal s\u00e3o realizadas em parceria com o Batalh\u00e3o de Pol\u00edcia Militar de Prote\u00e7\u00e3o Ambiental (BPMA) e o Corpo de Bombeiros Militar (CBM-MT).\u00a0<\/p>\n<p>O\u00a0superintendente de Fiscaliza\u00e7\u00e3o (SUF) da Sema, Bruno Nascimento, refor\u00e7a a import\u00e2ncia da apreens\u00e3o dos maquin\u00e1rios para impedir a continuidade do crime ambiental. <\/p>\n<p>\u201cA remo\u00e7\u00e3o promove a descapitaliza\u00e7\u00e3o imediata do respons\u00e1vel, e tem demonstrado \u00f3timos resultados com redu\u00e7\u00e3o dos \u00edndices de desmatamento no estado de Mato Grosso\u201d, afirma.<\/p>\n<p>Os maquin\u00e1rios pesados foram removidos das m\u00e3os de infratores ambientais com a contrata\u00e7\u00e3o de empresa especializada no transporte de m\u00e1quinas e equipamentos, que foi custeada com recursos do Programa REM, na ordem de R$500 mil.<\/p>\n<p>Com a contrata\u00e7\u00e3o, \u00e9 poss\u00edvel recolher o maquin\u00e1rio de forma imediata, e cumprir o que determina o decreto federal 6.514\/2008, que prev\u00ea que os bens apreendidos devem ficar sob a guarda do \u00f3rg\u00e3o ou entidade respons\u00e1vel pela fiscaliza\u00e7\u00e3o. Excepcionalmente o equipamento poderia ser deixado com o propriet\u00e1rio, como \u201cfiel deposit\u00e1rio\u201d at\u00e9 o final do julgamento administrativo.<\/p>\n<p>\u201cInfelizmente a experi\u00eancia de deixar o maquin\u00e1rio confiado ao propriet\u00e1rio como fiel deposit\u00e1rio mostra que, desta forma, n\u00e3o conseguimos impedir a continuidade da destrui\u00e7\u00e3o ambiental. In\u00fameras m\u00e1quinas foram apreendidas mais de uma vez cometendo o mesmo crime ou infra\u00e7\u00e3o\u201d, explica o superintendente.\u00a0<\/p>\n<p>Fellipe Santana, coordenador do Subprograma de Fortalecimento Institucional do REM-MT, destaca que o contrato ter\u00e1 um novo aditivo, desta vez de R$1,5 milh\u00e3o, para o pr\u00f3ximo semestre deste ano. O refor\u00e7o no contrato com a empresa Schumacher Transportes de M\u00e1quinas Equipamentos Pesados vem acompanhado de novos servi\u00e7os, pois al\u00e9m da apreens\u00e3o de maquin\u00e1rios, tamb\u00e9m ser\u00e1 poss\u00edvel retirar gr\u00e3os, madeira e carga viva dos infratores.<\/p>\n<p>O gestor avalia que investir nesse tipo de a\u00e7\u00e3o \u00e9 fundamental dentro da l\u00f3gica de combate ao desmatamento e preserva\u00e7\u00e3o da floresta. Destaca que, sem o maquin\u00e1rio, a probabilidade de o crime ambiental reincidir \u00e9 bem menor.\u00a0 \u201cAl\u00e9m disso, voc\u00ea consegue cessar o dano ambiental pela descapitaliza\u00e7\u00e3o e responsabiliza\u00e7\u00e3o imediata do infrator, com a retirada dos maquin\u00e1rios\u201d, enfatiza.<\/p>\n<p><strong>Como ocorre a apreens\u00e3o<\/strong><\/p>\n<p>Al\u00e9m de tratores, escavadeiras, ve\u00edculos pequenos, um helic\u00f3ptero adulterado foi apreendido em atividade il\u00edcita contra o meio ambiente. Esta foi a primeira vez que Mato Grosso apreende um helic\u00f3ptero adaptado ilegalmente para pulveriza\u00e7\u00e3o a\u00e9rea de subst\u00e2ncias qu\u00edmicas sobre a floresta. A equipe considerou o crime um atentado contra a sa\u00fade p\u00fablica e o meio ambiente.<\/p>\n<p><img decoding=\"async\" alt=\"\" src=\"http:\/\/www.mt.gov.br\/documents\/21013\/14657423\/WhatsApp+Image+2020-06-15+at+17.52.15.jpeg\/e2eb3ccd-1916-1948-d578-6bc68ffbdbe4?t=1592340951571+&amp;imageThumbnail=3\"><\/p>\n<p>As opera\u00e7\u00f5es s\u00e3o realizadas sempre em parceria com as for\u00e7as de seguran\u00e7a p\u00fablica de Mato Grosso, com o Batalh\u00e3o de Pol\u00edcia Militar de Prote\u00e7\u00e3o Ambiental (BPMA) e o Corpo de Bombeiros Militar (CBM-MT), o Instituto de Defesa Agropecu\u00e1ria do Estado de Mato Grosso (Indea-MT), e em alguns casos, prefeituras municipais.\u00a0 \u00a0<\/p>\n<p>As opera\u00e7\u00f5es levam em considera\u00e7\u00e3o alertas emitidos por sat\u00e9lite de alta precis\u00e3o. O monitoramento \u00e9 feito pela Plataforma Planet, tamb\u00e9m custeado pelo REM-MT, que acompanha diariamente altera\u00e7\u00f5es em vegeta\u00e7\u00f5es nativas no estado todo.<\/p>\n<p>Ao identificar alguma altera\u00e7\u00e3o, o Estado notifica automaticamente o propriet\u00e1rio, e tamb\u00e9m envia equipes para fiscaliza\u00e7\u00e3o em campo, para flagrar o crime ambiental, e aplicar medidas de responsabiliza\u00e7\u00e3o, dentre elas, a apreens\u00e3o e remo\u00e7\u00e3o dos maquin\u00e1rios.<\/p>\n<p><strong>Programa REM<\/strong><\/p>\n<p>O Programa remunera e premia o esfor\u00e7o de mitiga\u00e7\u00e3o das mudan\u00e7as clim\u00e1ticas de pioneiros do REDD + (Early Movers) e aplica recursos para o desenvolvimento sustent\u00e1vel. <\/p>\n<p>O contrato do REM Mato Grosso prev\u00ea recursos na ordem de 44 milh\u00f5es de euros do governo da Alemanha por meio do Banco Alem\u00e3o de Desenvolvimento (KfW), e o governo do Reino Unido, por meio do Departamento Brit\u00e2nico para Energia e Estrat\u00e9gia Industrial (BEIS). Entre as a\u00e7\u00f5es financiadas, est\u00e3o as de controle e fiscaliza\u00e7\u00e3o do desmatamento ilegal em MT.<\/p>\n<\/div>\n<p><\/p>\n<footer>C<\/footer>\n<\/article>\n<p><a href=\"http:\/\/www.mt.gov.br\/-\/16768176-tratores-caminhoes-e-helicoptero-em-um-ano-sema-remove-111-maquinas-utilizadas-em-crimes-ambientais-em-mt\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nGoverno do Estado de Mato Grosso<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tratores, caminh\u00f5es e helic\u00f3ptero: Em um ano, Sema remove 111 m\u00e1quinas utilizadas em crimes ambientais<\/p>\n","protected":false},"author":0,"featured_media":2271,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-2270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2270"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2270\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/2271"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}