{"id":226,"date":"2021-03-07T00:09:33","date_gmt":"2021-03-07T03:09:33","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/07\/prefeitura-do-rio-entra-com-recurso-contra-liminar-permitindo-bar-aberto-ate-20hnoticias-ao-minuto-brasil-brasil\/"},"modified":"2021-03-07T00:09:33","modified_gmt":"2021-03-07T03:09:33","slug":"prefeitura-do-rio-entra-com-recurso-contra-liminar-permitindo-bar-aberto-ate-20hnoticias-ao-minuto-brasil-brasil","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/07\/prefeitura-do-rio-entra-com-recurso-contra-liminar-permitindo-bar-aberto-ate-20hnoticias-ao-minuto-brasil-brasil\/","title":{"rendered":"Prefeitura do Rio entra com recurso contra liminar permitindo bar aberto at\u00e9 20hNot\u00edcias ao Minuto Brasil &#8211; Brasil"},"content":{"rendered":"<p>A Prefeitura do Rio entrou com recurso na manh\u00e3 deste s\u00e1bado, 6, para suspender a liminar que estende o hor\u00e1rio de funcionamento de bares e restaurantes das 17h para as 20h durante o per\u00edodo de restri\u00e7\u00e3o de circula\u00e7\u00e3o para conter a pandemia de covid-19. Segundo a Prefeitura, a decis\u00e3o de recorrer da liminar concedida na noite de sexta-feira (5) foi motivada pelo entendimento de que o fechamento \u00e0s 20h \u00e9 &#8220;insuficiente&#8221;.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>O decreto 48.573 que entrou em vigor ontem determina que os bares e restaurantes s\u00f3 poderiam funcionar at\u00e9 as 17h. A Associa\u00e7\u00e3o Brasileira de Bares e Restaurantes (Abrasel-RJ), no entanto, conseguiu na mesma noite uma liminar na Justi\u00e7a para que o fechamento fosse prorrogado para as 20h.<\/p>\n<p>De acordo com a Vigil\u00e2ncia em Sa\u00fade e a Secretaria de Ordem P\u00fablica, o hor\u00e1rio das 17h, que consta no decreto, foi estabelecido a partir de orienta\u00e7\u00e3o t\u00e9cnica para diminuir a circula\u00e7\u00e3o de pessoas, evitar aglomera\u00e7\u00f5es e garantir o distanciamento social. Somente este ano, das 284 infra\u00e7\u00f5es sanit\u00e1rias, mais de 87% foram realizadas no per\u00edodo noturno, evidenciando este ser o hor\u00e1rio com mais pontos de aglomera\u00e7\u00e3o e descumprimento das regras por parte da popula\u00e7\u00e3o.<\/p>\n<p>A interrup\u00e7\u00e3o das atividades no mesmo hor\u00e1rio acabou gerando uma aglomera\u00e7\u00e3o ainda maior do que vem sendo constatado nos meios de transporte.<\/p>\n<p>A Secretaria Municipal de Sa\u00fade constatou na quinta-feira um aumento de 16% dos casos de atendimento de s\u00edndrome gripal e s\u00edndrome respirat\u00f3ria aguda grave nas unidades de urg\u00eancia e emerg\u00eancia da cidade, o que refor\u00e7a a necessidade de maior rigor nas medidas de prote\u00e7\u00e3o \u00e0 vida.<\/p>\n<p>Neste s\u00e1bado, a Prefeitura autuou 230 estabelecimentos comerciais por descumprimento das determina\u00e7\u00f5es.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Brasil<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/ultima-hora\/1783577\/prefeitura-do-rio-entra-com-recurso-contra-liminar-permitindo-bar-aberto-ate-20h?utm_source=rss-brasil&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura do Rio entrou com recurso na manh\u00e3 deste s\u00e1bado, 6, para suspender a<\/p>\n","protected":false},"author":0,"featured_media":227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=226"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/226\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/227"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}