{"id":214,"date":"2021-03-07T00:09:30","date_gmt":"2021-03-07T03:09:30","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/07\/michel-platini-aponta-retorno-ao-futebol-e-defende-de-novo-a-copa-no-catar\/"},"modified":"2021-03-07T00:09:30","modified_gmt":"2021-03-07T03:09:30","slug":"michel-platini-aponta-retorno-ao-futebol-e-defende-de-novo-a-copa-no-catar","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/07\/michel-platini-aponta-retorno-ao-futebol-e-defende-de-novo-a-copa-no-catar\/","title":{"rendered":"Michel Platini aponta retorno ao futebol e defende de novo a Copa no Catar"},"content":{"rendered":"<p>Michel Platini, astro do futebol franc\u00eas e ex-presidente da UEFA, afirmou, nesta sexta-feira, em entrevista ao jornal alem\u00e3o Die Welt, que pretende retornar a trabalhar no futebol e defende a Copa do Mundo no Catar, no ano que vem.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Tr\u00eas vezes ganhador do pr\u00eamio Bola de Ouro (1983, 1984 e 1985), Platini, de 65 anos, est\u00e1 afastado desde 2015 por causa de um processo judicial no qual \u00e9 acusado de receber um pagamento suspeito de US$ 2,1 milh\u00f5es (cerca de R$ 12 milh\u00f5es) do ent\u00e3o presidente da Fifa, o su\u00ed\u00e7o Joseph Blatter.<\/p>\n<p>&#8220;Primeiro, deixe-me pensar com calma, n\u00e3o h\u00e1 pressa&#8221;, respondeu o franc\u00eas, sobre um poss\u00edvel retorno \u00e0s atividades como dirigente. &#8220;N\u00e3o me pro\u00edbo nada. Se acredito que isso \u00e9 bom para o futebol e que ainda posso ser \u00fatil, ent\u00e3o vou me comprometer totalmente&#8221;, acrescentou Platini, especificando que &#8220;ser\u00e1 a \u00faltima vez&#8221;. &#8220;Caso contr\u00e1rio, ficarei em casa e continuarei minha aposentadoria.&#8221;<\/p>\n<p>Platini aproveitou para defender a organiza\u00e7\u00e3o da pr\u00f3xima copa do mundo no Catar. &#8220;Os pa\u00edses \u00e1rabes j\u00e1 se candidataram dez vezes para ser sede de uma copa do mundo. \u00c9 importante para o desenvolvimento do futebol e \u00e9 exatamente por isso que votei neles, desde que seja em dezembro, como ser\u00e1. Espero uma Copa do Mundo muito boa, a 25 graus, n\u00e3o ser\u00e1 necess\u00e1rio ar condicionado.&#8221;<\/p>\n<p>Ao mesmo tempo, Platini disse ter se arrependido de ter revelado seu voto para o pa\u00eds \u00e1rabe. &#8220;S\u00f3 lamento ter sido muito educado, muito transparente, porque disse abertamente que tinha votado no Catar. Sou o \u00fanico dos quinze que admitiu e s\u00f3 tive problemas desde ent\u00e3o.&#8221;<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/1783271\/michel-platini-aponta-retorno-ao-futebol-e-defende-de-novo-a-copa-no-catar?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Michel Platini, astro do futebol franc\u00eas e ex-presidente da UEFA, afirmou, nesta sexta-feira, em entrevista<\/p>\n","protected":false},"author":0,"featured_media":215,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=214"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/214\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/215"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}