{"id":208940,"date":"2026-02-27T19:33:17","date_gmt":"2026-02-27T22:33:17","guid":{"rendered":"https:\/\/roteironoticias.com.br\/?p=208940"},"modified":"2026-02-27T19:34:15","modified_gmt":"2026-02-27T22:34:15","slug":"peixe-que-perde-os-olhos-ao-longo-da-evolucao-chega-ao-oceanic-aquarium","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2026\/02\/27\/peixe-que-perde-os-olhos-ao-longo-da-evolucao-chega-ao-oceanic-aquarium\/","title":{"rendered":"Peixe que perde os olhos ao longo da evolu\u00e7\u00e3o chega ao Oceanic Aquarium"},"content":{"rendered":"\n<p><em>Esp\u00e9cie adaptada \u00e0 vida em cavernas submersas ajuda a explicar sele\u00e7\u00e3o natural e gera curiosidade nos visitantes<\/em><\/p>\n\n\n\n<p>Um animal raro, que parece sa\u00eddo de um filme de fic\u00e7\u00e3o cient\u00edfica, rec\u00e9m chegou ao Oceanic Aquarium e j\u00e1 chama a aten\u00e7\u00e3o de quem passa pelo espa\u00e7o. Trata-se do Peixe-cego da caverna, conhecido como tetra-cego (Astyanax mexicanus), que vive naturalmente em rios subterr\u00e2neos e cavernas completamente escuras.<br>A principal curiosidade \u00e9 justamente a aus\u00eancia dos olhos. O peixe nasce com eles, mas perde a vis\u00e3o ainda no in\u00edcio da vida. Em ambientes sem luz, enxergar n\u00e3o faz diferen\u00e7a e, ao longo do tempo, a pr\u00f3pria natureza vai moldando o corpo do animal para esse tipo de habitat.<\/p>\n\n\n\n<p>Pequeno, com cerca de 8 a 12 cent\u00edmetros, o animal tem colora\u00e7\u00e3o clara, quase transl\u00facida. Para se locomover, usa sentidos como tato e percep\u00e7\u00e3o das vibra\u00e7\u00f5es da \u00e1gua, o que garante movimentos precisos, mesmo sem enxergar obst\u00e1culos. Origin\u00e1rio do M\u00e9xico, o peixe-cego vive em locais silenciosos e est\u00e1veis, longe da ilumina\u00e7\u00e3o solar. No Oceanic Aquarium, o espa\u00e7o foi adaptado para reproduzir essas condi\u00e7\u00f5es e permitir que o p\u00fablico observe de perto esses animais.<\/p>\n\n\n\n<p>Outra curiosidade \u00e9 que os Peixes-cegos de caverna, especificamente o Astyanax mexicanus (tetra-cego), possuem um aumento significativo de papilas gustativas que se espalham no corpo, principalmente pela cabe\u00e7a e queixo, \u00e0 medida que o peixe amadurece. Na natureza, se alimenta de pequenos invertebrados, larvas, crust\u00e1ceos e mat\u00e9ria org\u00e2nica dispon\u00edvel no ambiente subterr\u00e2neo. No aqu\u00e1rio a dieta \u00e9 balanceada e adaptada, com alimentos espec\u00edficos que garantem sa\u00fade, longevidade e est\u00edmulo ao comportamento natural de busca por alimento.<\/p>\n\n\n\n<p>Oceanic Aquarium<br>Do delicado cavalo-marinho aos imponentes tubar\u00f5es, o Oceanic Aquarium, em Balne\u00e1rio Cambori\u00fa (SC), convida o p\u00fablico a um mergulho inesquec\u00edvel no fascinante universo aqu\u00e1tico. S\u00e3o mais de 30 habitats e cerca de 170 esp\u00e9cies de \u00e1gua doce e salgada de diversas partes do mundo, em uma jornada repleta de descobertas.<\/p>\n\n\n\n<p>Entre os destaques est\u00e3o o casal de tubar\u00f5es-mangona, pinguins, axolotes, jacar\u00e9s, lontras, capivaras, polvos, \u00e1guas-vivas e os encantadores cavalos-marinhos. A experi\u00eancia se amplia na Imers\u00e3o Oceania, onde aves australianas surpreendem com cores vibrantes e cantos ex\u00f3ticos.<\/p>\n\n\n\n<p>Para quem busca emo\u00e7\u00e3o, a passarela de vidro suspensa de 30 metros permite caminhar sobre o habitat dos tubar\u00f5es e de outras 20 esp\u00e9cies, em um espa\u00e7o com mais de 300 mil litros de \u00e1gua. O passeio inclui ainda um ber\u00e7\u00e1rio marinho, onde \u00e9 poss\u00edvel ver filhotes de cavalos-marinhos, \u00e1guas-vivas e peixes-palha\u00e7o, al\u00e9m de um cinema 3D com realidade virtual que transporta os visitantes para dentro dos oceanos. Viva essa experi\u00eancia!<\/p>\n\n\n\n<p>Promo\u00e7\u00e3o \u2018Corre que ainda \u00e9 ver\u00e3o\u2019<br>At\u00e9 o dia 8 de mar\u00e7o, catarinense tem desconto para visitar o aqu\u00e1rio comprando exclusivamente pelo site com um dia de anteced\u00eancia. Garantindo o ingresso pelo site ou outro canal oficial, visitantes tamb\u00e9m ganham desconto, inclusive no Passaporte da Divers\u00e3o! Compre agora e use depois, a validade \u00e9 de um ano. Acesse www.passaportedadiversao.com.br para compras e demais informa\u00e7\u00f5es.<\/p>\n\n\n\n<p>Servi\u00e7o<br>Oceanic Aquarium<br>Aberto todos os dias das 9h \u00e0s 19h &#8211; entrada at\u00e9 18h<br>Rua 4000,133 &#8211; Barra Sul<br>Balne\u00e1rio Cambori\u00fa (SC)<br>www.oceanicaquarium.com.br<\/p>\n\n\n\n<p><em><strong>Por Ana Cirico\/Assessora de Imprensa<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2026\/02\/PEIXE-CEGO-4-1024x683.jpg\" alt=\"\" class=\"wp-image-208941\" srcset=\"https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2026\/02\/PEIXE-CEGO-4-1024x683.jpg 1024w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2026\/02\/PEIXE-CEGO-4-300x200.jpg 300w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2026\/02\/PEIXE-CEGO-4-768x512.jpg 768w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2026\/02\/PEIXE-CEGO-4-1536x1024.jpg 1536w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2026\/02\/PEIXE-CEGO-4-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"638\" height=\"1024\" src=\"https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2026\/02\/CEGO-VERTICAL-638x1024.png\" alt=\"\" class=\"wp-image-208942\" srcset=\"https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2026\/02\/CEGO-VERTICAL-638x1024.png 638w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2026\/02\/CEGO-VERTICAL-187x300.png 187w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2026\/02\/CEGO-VERTICAL-768x1232.png 768w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2026\/02\/CEGO-VERTICAL-958x1536.png 958w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2026\/02\/CEGO-VERTICAL-1277x2048.png 1277w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2026\/02\/CEGO-VERTICAL.png 1320w\" sizes=\"auto, (max-width: 638px) 100vw, 638px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Esp\u00e9cie adaptada \u00e0 vida em cavernas submersas ajuda a explicar sele\u00e7\u00e3o natural e gera curiosidade<\/p>\n","protected":false},"author":2,"featured_media":208944,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,2],"tags":[],"class_list":["post-208940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","category-agronoticias"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/208940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=208940"}],"version-history":[{"count":1,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/208940\/revisions"}],"predecessor-version":[{"id":208943,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/208940\/revisions\/208943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/208944"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=208940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=208940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=208940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}