{"id":195500,"date":"2024-10-17T08:31:58","date_gmt":"2024-10-17T11:31:58","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2024\/10\/17\/escolas-de-samba-do-rio-definem-calendario-de-ensaios-tecnicos\/"},"modified":"2024-10-17T08:31:58","modified_gmt":"2024-10-17T11:31:58","slug":"escolas-de-samba-do-rio-definem-calendario-de-ensaios-tecnicos","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/10\/17\/escolas-de-samba-do-rio-definem-calendario-de-ensaios-tecnicos\/","title":{"rendered":"Escolas de samba do Rio definem calend\u00e1rio de ensaios t\u00e9cnicos"},"content":{"rendered":"<p>O calend\u00e1rio dos ensaios t\u00e9cnicos das escolas de samba do Grupo Especial para o Rio Carnaval 2025 j\u00e1 est\u00e1 pronto. As apresenta\u00e7\u00f5es come\u00e7am em 25 de janeiro, com tr\u00eas agremia\u00e7\u00f5es por dia, e seguir\u00e3o at\u00e9 a semana que antecede os desfiles oficiais na Passarela da Marqu\u00eas de Sapuca\u00ed, o Samb\u00f3dromo, no centro da cidade.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>Para atender o pedido das agremia\u00e7\u00f5es, os ensaios t\u00e9cnicos ser\u00e3o aos s\u00e1bados. Nos \u00faltimos anos as escolas que se apresentavam aos domingos estavam reclamando porque terminavam tarde e havia dificuldades no transporte na volta para casa. Al\u00e9m disso, no dia seguinte os componentes precisavam come\u00e7ar a semana de trabalho.<\/p>\n<p>\u201cA ideia das escolas de mudar para s\u00e1bado j\u00e1 \u00e9 um pedido antigo de algumas escolas da Liesa, foi colocado em vota\u00e7\u00e3o, e n\u00e3o foi por unanimidade, mas venceu a ideia de ter ensaios t\u00e9cnicos aos s\u00e1bados\u201d, disse o presidente da Liga Independente das Escolas de Samba do Rio de Janeiro (Liesa), Gabriel David \u00e0 Ag\u00eancia Brasil.<\/p>\n<p>Outra novidade \u00e9 que todas as escolas v\u00e3o poder fazer teste de som e luz em um per\u00edodo de 4 dias. Nesse caso, o calend\u00e1rio marcou os ensaios entre quinta-feira (20) e domingo (23) de fevereiro. Com esses testes, tamb\u00e9m pela primeira vez, as agremia\u00e7\u00f5es v\u00e3o fazer 2 dias de ensaios t\u00e9cnicos.<\/p>\n<p>\u201c\u00c9 a primeira vez na hist\u00f3ria do carnaval que as 12 escolas de samba do Grupo Especial v\u00e3o poder testar som e luz oficiais da avenida do Rio Carnaval 2025. \u00c9 super fundamental isso. Tenho certeza que a gente vai ter um ganho art\u00edstico de preparo e tamb\u00e9m de entrega para a nossa cidade\u201d, disse.<\/p>\n<p>Com bastante anteced\u00eancia, a Liesa fez o an\u00fancio do calend\u00e1rio nesta segunda-feira (14). Para o presidente da liga, Gabriel David, os ensaios t\u00e9cnicos s\u00e3o fundamentais para a prepara\u00e7\u00e3o das agremia\u00e7\u00f5es. Ele destacou que a defini\u00e7\u00e3o da programa\u00e7\u00e3o foi coletiva, como tinha ocorrido quando houve a discuss\u00e3o de passar a ter 3 dias de desfiles. Em 2025, as apresenta\u00e7\u00f5es ser\u00e3o no domingo (2), na segunda-feira (3) e na ter\u00e7a-feira (4) de mar\u00e7o.<\/p>\n<p>\u201cA liga explicou a import\u00e2ncia e o que a gente poderia entregar mais para o p\u00fablico por conta disso. \u00c9 super importante para a gente j\u00e1 come\u00e7ar o pr\u00f3ximo ano de fato, e a virada do ano j\u00e1 ser com as escolas completamente programadas e organizadas para as suas grandes datas de in\u00edcio do ano, tanto para os ensaios nas quadras, como os das ruas e ensaios t\u00e9cnicos\u201d, disse Gabriel David.<\/p>\n<p>O presidente da Liesa avalia que os ensaios de luz e som v\u00e3o se transformar em um pr\u00e9 carnaval na cidade. \u201cQueria fortificar aqui a import\u00e2ncia desses dois ensaios t\u00e9cnicos por escola. Acho que \u00e9 um presente para a cidade do Rio de Janeiro, para o povo em geral, que pode assistir aos ensaios t\u00e9cnicos de forma gratuita, vai ter duas oportunidades por escola, sendo a segunda oportunidade uma semana antes do carnaval em um verdadeiro pr\u00e9-carnaval de 4 dias, quinta, sexta, s\u00e1bado e domingo com as escolas apresentando oficialmente um teste geral de som e luz para todas as escolas\u201d, completou.<\/p>\n<p>Calend\u00e1rio dos ensaios t\u00e9cnicos para o Rio Carnaval 2025:<\/p>\n<p><strong>25\/01<\/strong><\/p>\n<p>20h &#8211; Unidos de Padre Miguel<\/p>\n<p>21h30 &#8211; Unidos da Tijuca<\/p>\n<p>23h &#8211; Mocidade Independente<\/p>\n<p><strong>1\u00b0\/2<\/strong><\/p>\n<p>20h &#8211; Para\u00edso do Tuiuti<\/p>\n<p>21h30 &#8211; Beija-Flor<\/p>\n<p>23h &#8211; Mangueira<\/p>\n<p><strong>8\/2<\/strong><\/p>\n<p>20h &#8211; Vila Isabel<\/p>\n<p>21h30 &#8211; Portela<\/p>\n<p>23h &#8211; Grande Rio<\/p>\n<p><strong>15\/2<\/strong><\/p>\n<p>20h &#8211; Salgueiro<\/p>\n<p>21h30 &#8211; Imperatriz Leopoldinense<\/p>\n<p>23h &#8211; Viradouro<\/p>\n<p>Datas de teste de luz e som:<\/p>\n<p><strong>20\/2<\/strong><\/p>\n<p>20h &#8211; Unidos de Padre Miguel<\/p>\n<p>21h30 &#8211; Unidos da Tijuca<\/p>\n<p>23h &#8211; Mocidade Independente<\/p>\n<p><strong>21\/2<\/strong><\/p>\n<p>20h &#8211; Para\u00edso do Tuiuti<\/p>\n<p>21h30 &#8211; Beija-Flor<\/p>\n<p>23h &#8211; Mangueira<\/p>\n<p><strong>22\/2<\/strong><\/p>\n<p>18h &#8211; Lavagem<\/p>\n<p>20h &#8211; Vila Isabel<\/p>\n<p>21h30 &#8211; Portela<\/p>\n<p>23h &#8211; Salgueiro<\/p>\n<p><strong>23\/2<\/strong><\/p>\n<p>20h &#8211; Grande Rio<\/p>\n<p>21h30 &#8211; Imperatriz Leopoldinense<\/p>\n<p>23h &#8211; Viradouro<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Cultura<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/cultura\/2213669\/escolas-de-samba-do-rio-definem-calendario-de-ensaios-tecnicos?utm_source=rss-cultura&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O calend\u00e1rio dos ensaios t\u00e9cnicos das escolas de samba do Grupo Especial para o Rio<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-195500","post","type-post","status-publish","format-standard","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/195500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=195500"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/195500\/revisions"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=195500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=195500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=195500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}