{"id":195499,"date":"2024-10-17T08:31:56","date_gmt":"2024-10-17T11:31:56","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2024\/10\/17\/anitta-caetano-veloso-maria-bethania-e-ivete-sangalo-vao-cantar-no-reveillon-do-rio\/"},"modified":"2024-10-17T08:31:56","modified_gmt":"2024-10-17T11:31:56","slug":"anitta-caetano-veloso-maria-bethania-e-ivete-sangalo-vao-cantar-no-reveillon-do-rio","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/10\/17\/anitta-caetano-veloso-maria-bethania-e-ivete-sangalo-vao-cantar-no-reveillon-do-rio\/","title":{"rendered":"Anitta, Caetano Veloso, Maria Beth\u00e2nia e Ivete Sangalo v\u00e3o cantar no R\u00e9veillon do Rio"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Prefeito do Rio de Janeiro, Eduardo Paes (PSD) anunciou por meio das redes sociais algumas das atra\u00e7\u00f5es oficiais do R\u00e9veillon da cidade.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>&#8220;Pediram para eu n\u00e3o vazar, mas R\u00e9veillon do Rio vai ter Caetano e Beth\u00e2nia, Ivete Sangalo e Anitta. Turistas, podem reservar seus quartos de hotel. Cariocas, se preparem&#8221;, disse ele em seus perfis.<\/p>\n<p>Segundo comunicado da Prefeitura em julho, al\u00e9m da tradicional queima de fogos em Copacabana, que ter\u00e1 a dura\u00e7\u00e3o de 12 minutos, a cidade vai receber 12 palcos espalhados em diferentes pontos, montados nas zonas norte, oeste e centro.<\/p>\n<p>Ser\u00e3o dois palcos principais para shows. O Palco Rio, formado por pain\u00e9is de LED, e o Palco Samba, em formato de um pandeiro que vai reunir grandes estrelas da m\u00fasica brasileira. Ser\u00e3o 20 torres de som ser\u00e3o instaladas ao longo da orla. Paes ainda n\u00e3o informou aonde cada uma das atra\u00e7\u00f5es ir\u00e1 se apresentar.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Cultura<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2214178\/anitta-caetano-veloso-maria-bethania-e-ivete-sangalo-vao-cantar-no-reveillon-do-rio?utm_source=rss-cultura&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Prefeito do Rio de Janeiro, Eduardo Paes (PSD) anunciou por<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-195499","post","type-post","status-publish","format-standard","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/195499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=195499"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/195499\/revisions"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=195499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=195499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=195499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}