{"id":195496,"date":"2024-10-17T08:51:03","date_gmt":"2024-10-17T11:51:03","guid":{"rendered":"http:\/\/roteironoticias.com.br\/?p=195496"},"modified":"2024-10-17T08:51:04","modified_gmt":"2024-10-17T11:51:04","slug":"insumos-sem-componentes-carcinogenicos-protegem-o-futuro-da-agricultura","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/10\/17\/insumos-sem-componentes-carcinogenicos-protegem-o-futuro-da-agricultura\/","title":{"rendered":"Insumos sem componentes carcinog\u00eanicos protegem o futuro da agricultura"},"content":{"rendered":"\n<p><em>Subst\u00e2ncias como o nonilfenol etoxilado levantam s\u00e9rias preocupa\u00e7\u00f5es ambientais e de sa\u00fade, na contram\u00e3o disso, empresas como a Sell Agro investem em solu\u00e7\u00f5es sustent\u00e1veis para mitigar esses riscos e preservar a seguran\u00e7a dos ecossistemas<\/em><\/p>\n\n\n\n<p>Nos \u00faltimos anos, o debate sobre a seguran\u00e7a de insumos agr\u00edcolas como os adjuvantes, por exemplo, tem ganhado destaque nas discuss\u00f5es sobre sustentabilidade e sa\u00fade p\u00fablica. Um dos componentes que mais geram preocupa\u00e7\u00e3o \u00e9 o nonilfenol etoxilado, uma subst\u00e2ncia qu\u00edmica amplamente utilizada por sua capacidade de melhorar a efic\u00e1cia dos defensivos agr\u00edcolas. Embora tenha bom desempenho no campo, seus efeitos a longo prazo s\u00e3o alarmantes, tanto para os ecossistemas, quanto para os seres humanos.<\/p>\n\n\n\n<p>Diversos estudos indicam que o nonilfenol etoxilado tem potencial carcinog\u00eanico, podendo alterar o funcionamento das c\u00e9lulas e, com o tempo, aumentar o risco de desenvolvimento de c\u00e2ncer. Al\u00e9m disso, como disruptor end\u00f3crino, ele interfere nos sistemas hormonais, afetando a sa\u00fade reprodutiva e aumentando a vulnerabilidade a doen\u00e7as hormonais, como o c\u00e2ncer de mama e doen\u00e7as metab\u00f3licas. Essas preocupa\u00e7\u00f5es s\u00e3o particularmente graves em regi\u00f5es agr\u00edcolas, onde trabalhadores e comunidades locais ficam expostos a altos n\u00edveis dessas subst\u00e2ncias.<\/p>\n\n\n\n<p>No entanto, conforme explica o qu\u00edmico respons\u00e1vel na Sell Agro, Marcelo Hil\u00e1rio, os problemas v\u00e3o al\u00e9m da sa\u00fade humana. Pois, o nonilfenol etoxilado tem uma alta persist\u00eancia no meio ambiente, o que significa que ele n\u00e3o se degrada facilmente, acumulando-se nos solos e corpos d\u2019\u00e1gua. \u201cIsso gera um risco elevado para a biodiversidade, afetando de forma negativa ecossistemas aqu\u00e1ticos e a microbiota do solo\u201d, alerta.<\/p>\n\n\n\n<p>Em um estudo conduzido pela Ag\u00eancia Europeia de Subst\u00e2ncias Qu\u00edmicas (ECHA), foi constatado que o nonilfenol etoxilado \u00e9 altamente t\u00f3xico para organismos aqu\u00e1ticos. Ele interfere no sistema hormonal de peixes e anf\u00edbios, causando deformidades, comprometendo a reprodu\u00e7\u00e3o e afetando a capacidade de crescimento desses animais. \u201cEsse impacto em ecossistemas aqu\u00e1ticos pode levar a desequil\u00edbrios graves nas cadeias alimentares, resultando na redu\u00e7\u00e3o da biodiversidade e no colapso de habitats essenciais\u201d, refor\u00e7a o especialista.<\/p>\n\n\n\n<p>No solo, essa subst\u00e2ncia altera a microbiota, a comunidade de microrganismos essenciais para a ciclagem de nutrientes. \u201cA degrada\u00e7\u00e3o da diversidade microbiana afeta processos vitais como a fixa\u00e7\u00e3o de nitrog\u00eanio e a decomposi\u00e7\u00e3o de mat\u00e9ria org\u00e2nica, reduzindo a fertilidade dos solos agr\u00edcolas e, consequentemente, a produtividade das colheitas. Isso gera um efeito cascata na cadeia produtiva, que pode impactar diretamente os agricultores\u201d, explica o qu\u00edmico.<\/p>\n\n\n\n<p>No entanto, a crescente conscientiza\u00e7\u00e3o sobre esses problemas tem levado a ind\u00fastria agr\u00edcola a buscar alternativas mais seguras e sustent\u00e1veis para a formula\u00e7\u00e3o de seus produtos. Um exemplo dessa mudan\u00e7a \u00e9 a pr\u00f3pria Sell Agro, que se destaca ao desenvolver solu\u00e7\u00f5es livres de componentes nocivos, como o nonilfenol etoxilado.<\/p>\n\n\n\n<p>\u201cA sustentabilidade \u00e9 um dos pilares centrais da nossa empresa. Temos como compromisso o desenvolvimento de produtos que n\u00e3o ofere\u00e7am riscos ao meio ambiente ou \u00e0 sa\u00fade humana. Os adjuvantes s\u00e3o formulados com mat\u00e9rias-primas biodegrad\u00e1veis, assegurando que n\u00e3o contribuam para a bioacumula\u00e7\u00e3o ou a contamina\u00e7\u00e3o de ecossistemas\u201d, explica Hil\u00e1rio.<\/p>\n\n\n\n<p>Al\u00e9m disso, a companhia \u00e9 pioneira no uso de tecnologias que mant\u00eam a efici\u00eancia dos defensivos agr\u00edcolas sem recorrer a subst\u00e2ncias que comprometem a sa\u00fade p\u00fablica e o meio ambiente. Nenhum produto do portf\u00f3lio cont\u00e9m nonilfenol etoxilado. \u201cO que endossa o compromisso com a seguran\u00e7a e com a sustentabilidade, em um mercado que ainda enfrenta desafios para a substitui\u00e7\u00e3o completa desse tipo de subst\u00e2ncia\u201d, diz o profissional.<\/p>\n\n\n\n<p>Esse movimento tamb\u00e9m tem reflexos econ\u00f4micos positivos. O uso de produtos sustent\u00e1veis reduz os custos de remedia\u00e7\u00e3o ambiental e diminui a necessidade de medidas de mitiga\u00e7\u00e3o de impactos negativos. Al\u00e9m disso, o consumidor final, cada vez mais consciente das quest\u00f5es ambientais, tende a valorizar produtos que estejam alinhados com boas pr\u00e1ticas de sustentabilidade.<\/p>\n\n\n\n<p><strong>O futuro da formula\u00e7\u00e3o de adjuvantes<\/strong><\/p>\n\n\n\n<p>Com o avan\u00e7o da ci\u00eancia e a press\u00e3o crescente por pr\u00e1ticas mais sustent\u00e1veis, espera-se que a substitui\u00e7\u00e3o de produtos como o nonilfenol etoxilado se torne uma norma no setor agr\u00edcola. Regulamenta\u00e7\u00f5es mais rigorosas em v\u00e1rias partes do mundo, como as diretrizes da Uni\u00e3o Europeia, j\u00e1 est\u00e3o restringindo o uso de subst\u00e2ncias perigosas, e o mercado est\u00e1 respondendo com inova\u00e7\u00e3o e desenvolvimento de novas tecnologias.<\/p>\n\n\n\n<p>\u201cAcreditamos que o futuro da agricultura depende de solu\u00e7\u00f5es inovadoras que protejam o solo, a \u00e1gua e as pessoas. Estamos comprometidos em continuar desenvolvendo produtos que reflitam essa vis\u00e3o de longo prazo\u201d, conclui Marcelo.&nbsp;O caminho para uma agricultura mais segura e sustent\u00e1vel pode ser desafiador, mas os avan\u00e7os no setor mostram que \u00e9 poss\u00edvel preservar o futuro sem comprometer a produtividade.<\/p>\n\n\n\n<p><strong>Sell Agro<\/strong>\u00a0\u2013 Fundada em 2007, a Sell Agro atua na produ\u00e7\u00e3o de adjuvantes agr\u00edcolas, com sede em Rondon\u00f3polis-MT, e estrutura moderna com amplo laborat\u00f3rio de pesquisa e equipe altamente qualificada, composta por engenheiros qu\u00edmicos e agr\u00f4nomos. As solu\u00e7\u00f5es da empresa t\u00eam foco na gera\u00e7\u00e3o de economia e, ainda, em potencializar os resultados das lavouras. Mais informa\u00e7\u00f5es acesse: https:\/\/sellagro.com.br.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2024\/10\/nonilfenol-04-1024x1024.jpg\" alt=\"\" class=\"wp-image-195504\" srcset=\"https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2024\/10\/nonilfenol-04-1024x1024.jpg 1024w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2024\/10\/nonilfenol-04-300x300.jpg 300w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2024\/10\/nonilfenol-04-150x150.jpg 150w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2024\/10\/nonilfenol-04-768x768.jpg 768w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2024\/10\/nonilfenol-04-1536x1536.jpg 1536w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2024\/10\/nonilfenol-04.jpg 2025w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/files.pressmanager.net\/clientes\/d520c92a8cefa6c531073c08f38bc3a5\/imagens\/2019\/08\/01\/4aac47d9f778f6b4409defdaacd891af.png\" alt=\"Ruralpress\"\/><\/figure>\n\n\n\n<p><strong>Kassiana Bonisson<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Subst\u00e2ncias como o nonilfenol etoxilado levantam s\u00e9rias preocupa\u00e7\u00f5es ambientais e de sa\u00fade, na contram\u00e3o disso,<\/p>\n","protected":false},"author":2,"featured_media":195506,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-195496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agronoticias"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/195496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=195496"}],"version-history":[{"count":1,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/195496\/revisions"}],"predecessor-version":[{"id":195507,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/195496\/revisions\/195507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/195506"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=195496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=195496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=195496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}