{"id":1938,"date":"2021-03-26T13:09:39","date_gmt":"2021-03-26T16:09:39","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/26\/decreto-do-governo-sugere-acoes-porem-medidas-devem-ser-tomadas-pelo-prefeito\/"},"modified":"2021-03-26T13:09:39","modified_gmt":"2021-03-26T16:09:39","slug":"decreto-do-governo-sugere-acoes-porem-medidas-devem-ser-tomadas-pelo-prefeito","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/26\/decreto-do-governo-sugere-acoes-porem-medidas-devem-ser-tomadas-pelo-prefeito\/","title":{"rendered":"Decreto do Governo sugere a\u00e7\u00f5es, por\u00e9m medidas devem ser tomadas pelo prefeito"},"content":{"rendered":"<br \/>\n<article>\n<header>Decreto do Governo sugere a\u00e7\u00f5es, por\u00e9m medidas devem ser tomadas pelo prefeito<\/header>\n<h2>O munic\u00edpio que est\u00e1 classificado com o risco muito alto deve determinar, por meio de decreto municipal, quarentena coletiva obrigat\u00f3ria de 10 dias<\/h2>\n<p><span><br \/>\n    Secom-MT<br \/>\n<\/span><\/p>\n<div>\n<div>\n            pal\u00e1cio paiagu\u00e1s &#8211; Foto por: Christiano Antonucci\n        <\/div>\n<p>        <img decoding=\"async\" alt=\"pal\u00e1cio paiagu\u00e1s\" src=\"http:\/\/www.mt.gov.br\/documents\/21013\/13785755\/IMG_1194.jpg\/48bf2ec2-5fe2-21d3-cba5-5dc9e623dff9?t=1585174995920+&amp;imageThumbnail=3\" title=\"pal\u00e1cio paiagu\u00e1s - Foto por: Christiano Antonucci\"><\/div>\n<div class=\"full-content\">\n<p>O Decreto n\u00ba 874\u00a0publicado nesta quinta-feira (25.03), pelo Governo de Mato Grosso, trouxe as diretrizes que os prefeitos do Estado dever\u00e3o adotar no combate \u00e0\u00a0dissemina\u00e7\u00e3o do coronav\u00edrus.<\/p>\n<p>Conforme o decreto, foi atualizada a classifica\u00e7\u00e3o de risco epidemiol\u00f3gico e fixadas\u00a0as regras e diretrizes para a ado\u00e7\u00e3o, pelos munic\u00edpios, de medidas restritivas para prevenir a dissemina\u00e7\u00e3o da Covid-19.<\/p>\n<p>O munic\u00edpio que est\u00e1 classificado com o risco muito alto deve determinar, por meio de decreto municipal, quarentena coletiva obrigat\u00f3ria de 10 dias. Nesse per\u00edodo, o prefeito poder\u00e1 antecipar feriados para auxiliar as atividades econ\u00f4micas.<\/p>\n<p>Al\u00e9m das medidas contidas no decreto estadual, os prefeitos poder\u00e3o adotar a\u00e7\u00f5es mais restritivas para diminuir o n\u00famero de casos e a circula\u00e7\u00e3o do v\u00edrus.<\/p>\n<p><em><strong>Confira as medidas que devem ser adotadas pelos munic\u00edpios em N\u00edvel de Risco MUITO ALTO<\/strong><\/em><\/p>\n<p>a) implementa\u00e7\u00e3o e\/ou manuten\u00e7\u00e3o de todas as medidas previstas para os N\u00edveis de Risco BAIXO, MODERADO e ALTO;<br \/>\nb) quarentena coletiva obrigat\u00f3ria no territ\u00f3rio do Munic\u00edpio, por per\u00edodos de 10 (dez) dias, prorrog\u00e1veis, mediante reavalia\u00e7\u00e3o da autoridade competente, podendo, inclusive, haver antecipa\u00e7\u00e3o de feriados para referido per\u00edodo;<br \/>\nc) suspens\u00e3o de aulas presenciais em creches, escolas e universidades.<br \/>\nd) controle do per\u00edmetro da \u00e1rea de conten\u00e7\u00e3o, por barreiras sanit\u00e1rias, para triagem da entrada e sa\u00edda de pessoas, ficando autorizada apenas a circula\u00e7\u00e3o de pessoas com o objetivo de acessar e exercer atividades essenciais;<br \/>\ne) manuten\u00e7\u00e3o do funcionamento apenas dos servi\u00e7os p\u00fablicos e atividades essenciais;<br \/>\n\u00a71\u00ba Atingida determinada classifica\u00e7\u00e3o de risco, as medidas de restri\u00e7\u00e3o correspondentes devem ser aplicadas por, no m\u00ednimo, 10 (dez) dias, ainda que, neste per\u00edodo, ocorra o rebaixamento da classifica\u00e7\u00e3o do Munic\u00edpio.<br \/>\n\u00a72\u00ba Os munic\u00edpios cont\u00edguos devem adotar as medidas restritivas id\u00eanticas, correspondentes \u00e0s aplic\u00e1veis aquele que tiver classifica\u00e7\u00e3o de risco mais grave.<br \/>\n\u00a73\u00ba Os Munic\u00edpios poder\u00e3o adotar medidas mais restritivas do que as contidas neste Decreto, desde que justificadas em dados concretos locais que demonstrem a necessidade de maior rigor para o controle da dissemina\u00e7\u00e3o do novo coronav\u00edrus.<br \/>\nArt. 6\u00ba O funcionamento de parques p\u00fablicos estaduais seguir\u00e1 as restri\u00e7\u00f5es estabelecidas pelos Munic\u00edpios em que se encontrem e, na aus\u00eancia de normas a este respeito, poder\u00e3o ser utilizados, desde que observado o distanciamento m\u00ednimo de 1,5m entre as pessoas, ficando vedado o acesso sem o uso de m\u00e1scara de prote\u00e7\u00e3o facial.<\/p>\n<p><em><strong>Confira quais s\u00e3o os munic\u00edpios que est\u00e3o classificados como de risco muito alto<\/strong><\/em><\/p>\n<p>Araguainha, Bar\u00e3o de Melga\u00e7o, Canabrava do Norte, Itanhang\u00e1, Jangada, Juscimeira, Nova Santa Helena, Planalto da Serra, Ribeir\u00e3ozinho, Santa Cruz do Xingu, Santa Rita do Trivelato, Santa Terezinha, Santo Ant\u00f4nio do Leste, S\u00e3o Jos\u00e9 do Povo, S\u00e3o Jos\u00e9 do Xingu, S\u00e3o Pedro da Cipa, Torixor\u00e9u, Uni\u00e3o do Sul, Alta Floresta, Apiac\u00e1s, Aripuan\u00e3, Brasnorte, C\u00e1ceres, Campo Novo do Parecis, Campo Verde, Carlinda, Cl\u00e1udia, Cuiab\u00e1, Diamantino, Guarant\u00e3 do Norte, Juara, Juruena, Lucas do Rio Verde, Marcel\u00e2ndia, Matup\u00e1, Mirassol D\u2019Oeste, Nova Mutum, Nova Xavantina, Paranatinga, Peixoto de Azevedo, Pocon\u00e9, Pontes e Lacerda, Primavera do Leste, Rondon\u00f3polis, Sapezal, Sinop, Sorriso, Tapurah, V\u00e1rzea Grande, Vila Bela da Sant\u00edssima Trindade.<\/p>\n<\/div>\n<p><\/p>\n<footer>C<\/footer>\n<\/article>\n<p><a href=\"http:\/\/www.mt.gov.br\/-\/16761678-decreto-do-governo-sugere-acoes-porem-medidas-devem-ser-tomadas-pelo-prefeito\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nGoverno do Estado de Mato Grosso<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decreto do Governo sugere a\u00e7\u00f5es, por\u00e9m medidas devem ser tomadas pelo prefeito O munic\u00edpio que<\/p>\n","protected":false},"author":0,"featured_media":1939,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1938"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1938\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/1939"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}