{"id":188889,"date":"2024-08-21T06:08:20","date_gmt":"2024-08-21T09:08:20","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/21\/jovem-e-condenada-a-prisao-por-matar-estuprador-nos-eua\/"},"modified":"2024-08-21T06:08:20","modified_gmt":"2024-08-21T09:08:20","slug":"jovem-e-condenada-a-prisao-por-matar-estuprador-nos-eua","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/21\/jovem-e-condenada-a-prisao-por-matar-estuprador-nos-eua\/","title":{"rendered":"Jovem \u00e9 condenada a pris\u00e3o por matar estuprador nos EUA"},"content":{"rendered":"<p>Chrystul Kizer, atualmente com 24 anos, foi condenada a 11 anos de pris\u00e3o por ter matado o homem que a agrediu e traficou sexualmente quando era adolescente, em Milwaukee, nos estado norte-americano do Wisconsin.\u00a0<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>Segundo a BBC, Kizer foi acusada do crime de homic\u00eddio por alvejar Randall Volar, de 34 anos, em 2018, quando a jovem tinha apenas 17 anos. Seis anos depois, decidiu aceitar um acordo judicial para evitar ser condenada a pris\u00e3o perp\u00e9tua.<\/p>\n<p>A jovem contou que conheceu Volar quando tinha apenas 16 anos e que o homem a agrediu sexualmente, dando-lhe em troca dinheiro e presentes. Al\u00e9m do abuso, o agressor vendeu-a a outros homens para atos sexuais.\u00a0<\/p>\n<p>Na \u00e9poca da morte, uma investiga\u00e7\u00e3o do Washington Post revelou que as autoridades tinham provas, incluindo v\u00eddeos, de que Volar abusava de cerca de uma d\u00fazia de adolescentes, incluindo Kizer.<\/p>\n<p>O homem chegou a ser detido e acusado do crime de agress\u00e3o sexual, quatro meses antes da sua morte, mas foi libertado no mesmo dia.\u00a0<\/p>\n<p>No dia do crime, em junho de 2018, Kizer deslocou-se a casa de Volar com uma arma, alvejou-o na cabe\u00e7a com dois tiros, incendiou-lhe a casa e levou o carro. Foi acusada do crime de homic\u00eddio premeditado e a acusa\u00e7\u00e3o afirmou que o seu objetivo seria roubar o carro. No entanto, a defesa alegou leg\u00edtima defesa.\u00a0<\/p>\n<p>A jovem pediu ainda que o seu caso fosse inserido na lei de \u201cdefesa afirmativa\u201d, implementada em alguns Estados norte-americanos e que protege as v\u00edtimas de algumas acusa\u00e7\u00f5es, incluindo prostitui\u00e7\u00e3o ou roubo, se essas a\u00e7\u00f5es tiverem sido resultado do tr\u00e1fico. Em 2022, o Supremo Tribunal do Wisconsin permitiu o pedido.\u00a0<\/p>\n<p>No entanto, decidiu optar por um acordo judicial para n\u00e3o correr o risco de ser condenada a pris\u00e3o perp\u00e9tua no julgamento. \u201cPosso tentar seguir em frente\u201d, disse Kizer ao Washington Post.<\/p>\n<p>A jovem j\u00e1 cumpriu mais de um ano e meio da sua senten\u00e7a e ter\u00e1 de cumprir mais cinco anos antes de poder pedir liberdade condicional.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Mundo<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/mundo\/2190087\/jovem-e-condenada-a-prisao-por-matar-estuprador-nos-eua?utm_source=rss-mundo&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chrystul Kizer, atualmente com 24 anos, foi condenada a 11 anos de pris\u00e3o por ter<\/p>\n","protected":false},"author":0,"featured_media":188890,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-188889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188889"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188889\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188890"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}