{"id":188779,"date":"2024-08-20T08:08:35","date_gmt":"2024-08-20T11:08:35","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/20\/kamala-exalta-biden-durante-fala-surpresa-em-convencao-dos-democratas\/"},"modified":"2024-08-20T08:08:35","modified_gmt":"2024-08-20T11:08:35","slug":"kamala-exalta-biden-durante-fala-surpresa-em-convencao-dos-democratas","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/20\/kamala-exalta-biden-durante-fala-surpresa-em-convencao-dos-democratas\/","title":{"rendered":"Kamala exalta Biden durante &#8216;fala surpresa&#8217; em conven\u00e7\u00e3o dos democratas"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; Os democratas realizaram o primeiro dia da conven\u00e7\u00e3o do partido, em Chicago (EUA), nesta segunda-feira (19). O evento que ter\u00e1 cinco dias de dura\u00e7\u00e3o vai oficializar a indica\u00e7\u00e3o presidencial de Kamala Harris e seu companheiro de chapa, o governador de Minnesota, Tim Walz.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>Kamala Harris surpreendeu ao aparecer em palco da conven\u00e7\u00e3o e discursar por volta das 22h (hor\u00e1rio de Bras\u00edlia) -a sua fala estava prevista apenas para a pr\u00f3xima quinta-feira. &#8220;Quero come\u00e7ar celebrando nosso incr\u00edvel presidente Joe Biden. Obrigado por sua lideran\u00e7a hist\u00f3rica, por sua vida de servi\u00e7o \u00e0 nossa na\u00e7\u00e3o e por tudo o que voc\u00ea continuar\u00e1 a fazer. Seremos sempre gratos a voc\u00ea&#8221;, disse ela.<\/p>\n<p>O discurso durou apenas dois minutos. A vice-presidente foi aplaudida de p\u00e9 por uma plateia lotada.<\/p>\n<p>Os principais medalh\u00f5es da sigla estavam presentes. Al\u00e9m de Kamala, Tim Walz, Joe Biden, Nancy Pelosi e Hillary Clinton, entre outros, participaram do evento.<\/p>\n<p>Mais de 200 influenciadores foram credenciados para a conven\u00e7\u00e3o. O objetivo \u00e9 fazer o evento democrata viralizar nas redes sociais e demais plataformas online.<\/p>\n<p>Entre os nomes de peso presente, estavam: Carlos Eduardo Espina, ativista dos direitos dos imigrantes com 10,2 milh\u00f5es de seguidores, e Nabela Noor Martin, uma designer, com 7,6 milh\u00f5es, ambos no TikTok.<\/p>\n<p><span class=\"news_bold\">GRUPOS PR\u00d3-PALESTINA E PR\u00d3-ISRAEL PROTESTAM<\/span><\/p>\n<p>Pol\u00edcia precisou fazer barreira para separ\u00e1-los. Os dois grupos marcharam na Union Park, pr\u00f3ximo do local do evento democrata, e chegaram a ser afastados por seguran\u00e7as para evitar confronto.<\/p>\n<p>Os manifestantes que defendem a Palestina criticam a posi\u00e7\u00e3o do governo do presidente Joe Biden em rela\u00e7\u00e3o a Israel, que trava uma guerra contra o Hamas em Gaza. Manifestantes pr\u00f3-Israel em menor n\u00famero seguravam a bandeira israelense e americana e defendiam a ajuda militar contra extremistas.<\/p>\n<p>Estima-se que mais de 40 mil palestinos morreram em Gaza, de acordo com autoridades locais.<\/p>\n<p>Quatro pessoas foram presas. A pol\u00edcia de Chicago informou que elas foram presas ap\u00f3s violarem uma cerca de seguran\u00e7a perto do United Center, onde \u00e9 realizada a conven\u00e7\u00e3o democrata.<\/p>\n<p><span class=\"news_bold\">CONVEN\u00c7\u00c3O OFICIALIZA KAMALA<\/span><\/p>\n<p>O evento democrata deve durar pelo menos cinco dias. A conven\u00e7\u00e3o ir\u00e1 oficializar o lan\u00e7amento da chapa presidencial de Kamala Harris e Tim Walz. Eles enfrentar\u00e3o os republicanos Donald Trump e J.D. Vance nas elei\u00e7\u00f5es de novembro.<\/p>\n<p>A vice-presidente contou com o apoio de mais da metade dos delegados necess\u00e1rios para indica\u00e7\u00e3o de candidatura \u00e0 Presid\u00eancia dos Estados Unidos, em um processo interno realizado em julho.<\/p>\n<p>Kamala assumiu a fun\u00e7\u00e3o ap\u00f3s desist\u00eancia de Joe Biden. O presidente de 81 anos anunciou que n\u00e3o iria concorrer \u00e0 reelei\u00e7\u00e3o depois de enfrentar press\u00e3o interna e externa. O pedido foi feito em carta publicada nas redes sociais. Minutos depois, Biden publicou uma foto sinalizando apoio a sua vice para combater Trump.<\/p>\n<p>O desempenho de Biden em debate da CNN acendeu um alerta no Partido Democrata. Com a voz rouca, uma gagueira persistente e frases confusas, o presidente deixou uma imagem oposta \u00e0 mostrada pelo rival, que adotou um tom claro e en\u00e9rgico no evento realizado em junho. Desde ent\u00e3o, v\u00e1rios democratas demonstraram preocupa\u00e7\u00e3o e sugeriram que Biden abandonasse a disputa.<\/p>\n<p>As gafes cometidas por Biden tamb\u00e9m aumentaram a press\u00e3o. O chefe da Casa Branca chegou a confundir o nome da vice-presidente democrata Kamala Harris com o rival Donald Trump e chamou o presidente ucraniano Volodymyr Zelensky de Vladimir Putin.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Mundo<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/mundo\/2189544\/kamala-exalta-biden-durante-fala-surpresa-em-convencao-dos-democratas?utm_source=rss-mundo&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; Os democratas realizaram o primeiro dia da conven\u00e7\u00e3o do partido,<\/p>\n","protected":false},"author":0,"featured_media":188780,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-188779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188779"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188779\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188780"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}