{"id":188769,"date":"2024-08-20T07:08:52","date_gmt":"2024-08-20T10:08:52","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/20\/filho-de-jassa-detalha-a-ultima-ida-de-silvio-santos-ao-salao-do-pai\/"},"modified":"2024-08-20T07:08:52","modified_gmt":"2024-08-20T10:08:52","slug":"filho-de-jassa-detalha-a-ultima-ida-de-silvio-santos-ao-salao-do-pai","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/20\/filho-de-jassa-detalha-a-ultima-ida-de-silvio-santos-ao-salao-do-pai\/","title":{"rendered":"Filho de Jassa detalha a \u00faltima ida de Silvio Santos ao sal\u00e3o do pai"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Robson Jassa, filho de Jassa, cabeleireiro oficial de Silvio Santos durante quatro d\u00e9cadas, participou do programa Encontro com Patr\u00edcia Poeta na manh\u00e3 dessa segunda-feira (19). Ele falou da \u00faltima ida de Silvio Santos ao sal\u00e3o de seu pai, o Jassa Hair Studio, que aconteceu no dia 1\u00ba de fevereiro.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>&#8220;Ningu\u00e9m sabia que ele iria l\u00e1. Na \u00faltima vez que ele tinha feito o cabelo, meu pai tinha atendido na casa dele, a pedido da Iris Abravanel&#8221;, disse ele. Robson conta que Silvio se mostrava disposto e chegou a conversar com todos ali presentes. &#8220;Convivi com esse cara e fico com muita gratid\u00e3o ao ver o respeito que ele tem sido tratado pelas emissoras.&#8221;<\/p>\n<p>Robson tamb\u00e9m descreveu o desafio de dar a not\u00edcia ao pai, na manh\u00e3 de s\u00e1bado (17), quando Silvio Santos faleceu aos 93 anos. &#8220;O s\u00e1bado foi muito triste. Foi muito triste a hora que eu abri o celular e vi a not\u00edcia. Depois eu fui contar para o meu pai. E voc\u00ea est\u00e1 l\u00e1, tendo que atender as pessoas. N\u00e3o tivemos condi\u00e7\u00f5es. A gente fechou o sal\u00e3o&#8221;, compartilhou ele.<\/p>\n<p>O filho de Jassa foi criado como uma esp\u00e9cie de sobrinho simb\u00f3lico de Silvio Santos. De acordo com o site oficial do sal\u00e3o, Jassa conheceu o apresentador em 1976, quando Robson ainda era crian\u00e7a. Ele segue os passos do pai e hoje tamb\u00e9m \u00e9 cabeleireiro no Jassa Hair Studio.<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2189438\/silvia-abravanel-quase-foi-adotada-por-familia-de-um-amigo-de-silvio-santos\" target=\"_blank\" rel=\"noopener noreferrer\">Silvia Abravanel quase foi adotada por fam\u00edlia de um amigo de Silvio Santos<\/a><\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2189257\/3-silvio-santos-vai-ganhar-estatua-na-lapa-diz-eduardo-paes-prefeito-do-rio\" target=\"_blank\" rel=\"noopener noreferrer\">Silvio Santos vai ganhar est\u00e1tua na Lapa, diz Eduardo Paes, prefeito do Rio<\/a><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2189504\/5-filho-de-jassa-detalha-a-ultima-ida-de-silvio-santos-ao-salao-do-pai?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Robson Jassa, filho de Jassa, cabeleireiro oficial de Silvio Santos<\/p>\n","protected":false},"author":0,"featured_media":188770,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-188769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188769"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188770"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}