{"id":188721,"date":"2024-08-19T18:08:26","date_gmt":"2024-08-19T21:08:26","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/19\/veja-as-vagas-mais-disputadas-do-enem-dos-concursos\/"},"modified":"2024-08-19T18:08:26","modified_gmt":"2024-08-19T21:08:26","slug":"veja-as-vagas-mais-disputadas-do-enem-dos-concursos","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/19\/veja-as-vagas-mais-disputadas-do-enem-dos-concursos\/","title":{"rendered":"Veja as vagas mais disputadas do Enem dos Concursos"},"content":{"rendered":"<p>BRAS\u00cdLIA, DF (FOLHAPRESS) &#8211; O MGI (Minist\u00e9rio da Gest\u00e3o e Inova\u00e7\u00e3o) divulgou nesta segunda-feira (19) o n\u00famero de candidatos por vaga aberta pelo CNU (Concurso Nacional Unificado), realizado no domingo (18).<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>A mais concorrida entre todas as \u00e1reas foi a de Analista de Planejamento, Gest\u00e3o e Infraestrutura em Informa\u00e7\u00f5es Geogr\u00e1ficas e Estat\u00edsticas, vinculada ao IBGE (Instituto Brasileiro de Geografia e Estat\u00edstica), com somente uma vaga ofertada para um total de 28.534 inscritos.<\/p>\n<p>Em sequ\u00eancia, est\u00e3o os cargos de Analista Administrativo da Previc (Superintend\u00eancia Nacional de Previd\u00eancia Complementar), que aceitava profissionais de qualquer \u00e1rea do conhecimento, com 226.481 inscritos para 9 vagas (pouco mais 25 mil por vaga), e de T\u00e9cnico em Assuntos Educacionais do MGI, com 44.262 inscritos para duas vagas (pouco mais 22 mil por vaga).<\/p>\n<p><span class=\"news_bold\">Veja as vagas mais concorridas de cada bloco:<\/span><\/p>\n<p>Analista de Planejamento, Gest\u00e3o e Infra. em Info. Geogr\u00e1ficas e Estat\u00edsticas do IBGE: 28.534 inscritos para uma vaga (Bloco 1 &#8211; Infraestrutura, Exatas e Engenharias)<\/p>\n<p>Analista Administrativo (qualquer \u00e1rea do conhecimento) da Previc: 25.164,6 candidatos por vaga. Foram 226.481 inscritos para 9 vagas (Bloco 7 &#8211; Gest\u00e3o Governamental e Administra\u00e7\u00e3o P\u00fablica)<\/p>\n<p>T\u00e9cnico em Assuntos Educacionais, MGI: 22.131 candidatos por vaga. Foram 44.262 inscritos para duas vagas (Bloco 5 &#8211; Educa\u00e7\u00e3o, Sa\u00fade, Desenvolvimento Social e Direitos Humanos)<\/p>\n<p>Especialista em Pol\u00edticas P\u00fablicas e Gest\u00e3o Governamental 18.216,8 por vaga. Foram 182.168 inscritos para 10 vagas (Bloco 4 &#8211; Trabalho e Sa\u00fade do Servidor)<br \/>Especialista em Pol\u00edticas P\u00fablicas e Gest\u00e3o Governamental do MGI: 9.923,8 candidatos por vaga. Foram 49.619 inscritos para um total de 5 vagas (Bloco 3 &#8211; Ambiental, Agr\u00e1rio e Biol\u00f3gicas)<\/p>\n<p>Tecnologista em Info. Geogr\u00e1ficas e Estat\u00edsticas do IBGE: 8.208,3 inscritos por vaga. Foram 24.625 candidatos para apenas 3 vagas. (Bloco 2 &#8211; Tecnologia, Dados e Informa\u00e7\u00e3o)<\/p>\n<p>T\u00e9cnico em Informa\u00e7\u00f5es Geogr\u00e1ficas e Estat\u00edsticas, IBGE: 5.018,0 candidatos por vaga. Foram 200.721 inscritos para 40 vagas (Bloco 8 &#8211; N\u00edvel M\u00e9dio)<\/p>\n<p>A primeira edi\u00e7\u00e3o do concurso foi marcada por um \u00edndice de absten\u00e7\u00e3o de 52,5%, mas sem relatos de atrasos na aplica\u00e7\u00e3o, vazamentos e outros problemas na organiza\u00e7\u00e3o.<\/p>\n<p>Em declara\u00e7\u00e3o na noite deste domingo, a ministra Esther Dweck (Gest\u00e3o e da Inova\u00e7\u00e3o em Servi\u00e7os P\u00fablicos) afirmou que quase 1 milh\u00e3o de pessoas participaram do CNU. Isso representa menos da metade de pessoas fazendo a prova, tendo em vista que foram 2,1 milh\u00f5es de inscritos.<\/p>\n<p>O concurso, dividido em duas provas, uma na parte da manh\u00e3 e outra da tarde, foi conclu\u00eddo \u00e0s 18h do domingo.<\/p>\n<p>Entre 9h e 11h30, os concurseiros enfrentaram uma bateria de quest\u00f5es discursivas, espec\u00edficas para cada um dos oito blocos, e uma prova objetiva de conhecimentos gerais, comum a todos. Na parte da tarde, entre 14h30 e 18h, os candidatos responderam a perguntas espec\u00edficas de cada bloco.<\/p>\n<p>O gabarito das provas est\u00e1 previsto para ser divulgado na ter\u00e7a-feira (20), e os cadernos de resposta j\u00e1 foram liberados \u00e0s 20h do mesmo dia da prova.<\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/2189342\/veja-as-vagas-mais-disputadas-do-enem-dos-concursos?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BRAS\u00cdLIA, DF (FOLHAPRESS) &#8211; O MGI (Minist\u00e9rio da Gest\u00e3o e Inova\u00e7\u00e3o) divulgou nesta segunda-feira (19)<\/p>\n","protected":false},"author":0,"featured_media":188722,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-188721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188721"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188721\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188722"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}