{"id":188622,"date":"2024-08-18T14:08:15","date_gmt":"2024-08-18T17:08:15","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/18\/famosos-que-morreram-em-acidentes-de-aviao-3\/"},"modified":"2024-08-18T14:08:15","modified_gmt":"2024-08-18T17:08:15","slug":"famosos-que-morreram-em-acidentes-de-aviao-3","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/18\/famosos-que-morreram-em-acidentes-de-aviao-3\/","title":{"rendered":"Famosos que morreram em acidentes de avi\u00e3o"},"content":{"rendered":"<p>V\u00e1rias celebridades brasileiras e internacionais tiveram suas carreiras de sucesso abreviadas por conta de desastres a\u00e9reos. De acidentes de avi\u00e3o a helic\u00f3ptero, clique na galeria para relembrar uma s\u00e9rie de voos fatais que tiraram as vidas de algumas das figuras p\u00fablicas mais famosas do mundo.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/2188981\/familia-de-silvio-santos-deixa-carta-aberta-aos-fas-em-despedida\" target=\"_blank\" rel=\"noopener noreferrer\">Fam\u00edlia de Silvio Santos deixa carta aberta aos f\u00e3s em despedida<\/a><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/2188964\/famosos-que-morreram-em-acidentes-de-aviao?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00e1rias celebridades brasileiras e internacionais tiveram suas carreiras de sucesso abreviadas por conta de desastres<\/p>\n","protected":false},"author":0,"featured_media":188623,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-188622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188622"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188623"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}