{"id":188620,"date":"2024-08-18T14:08:12","date_gmt":"2024-08-18T17:08:12","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/18\/canais-de-tv-evitaram-helicopteros-no-sepultamento-de-silvio-santos\/"},"modified":"2024-08-18T14:08:12","modified_gmt":"2024-08-18T17:08:12","slug":"canais-de-tv-evitaram-helicopteros-no-sepultamento-de-silvio-santos","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/18\/canais-de-tv-evitaram-helicopteros-no-sepultamento-de-silvio-santos\/","title":{"rendered":"Canais de TV evitaram helic\u00f3pteros no sepultamento de Silvio Santos"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; Em respeito \u00e0 fam\u00edlia, canais de TV evitaram helic\u00f3pteros no sepultamento de Silvio Santos, na manh\u00e3 deste domingo (18).<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>O corpo do dono do SBT foi sepultado no Cemit\u00e9rio Israelita do Butant\u00e3, em S\u00e3o Paulo, por volta das 9h20.<\/p>\n<p>Desde o in\u00edcio do planejamento para registrar a ocasi\u00e3o, o SBT descartou o uso de helic\u00f3pteros. Mas, conforme apurou a reportagem, havia uma inseguran\u00e7a sobre o que fariam se outros canais de TV sobrevoassem o cemit\u00e9rio para captar imagens da cerim\u00f4nia -o que n\u00e3o aconteceu, em respeito \u00e0 fam\u00edlia.<\/p>\n<p>A cerim\u00f4nia fechada para o p\u00fablico foi breve, mantendo a discri\u00e7\u00e3o pedida por Silvio. O sepultamento come\u00e7ou pouco antes das 9h e contou com a presen\u00e7a de Iris Abravanel, das filhas do apresentador e alguns famosos, como Celso Portiolli, Carlos Alberto de N\u00f3brega e C\u00e9sar Filho.<\/p>\n<p>Alguns f\u00e3s foram \u00e0 porta do local, levando cartazes e homenagens com a foto do apresentador. Apesar disso, o ambiente estava silencioso, em clima de respeito.<\/p>\n<p>Na sa\u00edda do cemit\u00e9rio, Daniela e Rebeca falaram rapidamente com a imprensa. Ambas agradeceram a presen\u00e7a e apoio dos que l\u00e1 que estavam.<br \/>Silvio Santos n\u00e3o queria vel\u00f3rio. O corpo do apresentador foi sepultado seguindo o rito judaico e sem vel\u00f3rio, como pedido por ele. Silvio morreu neste s\u00e1bado, \u00e0s 4h50, de broncopneumonia decorrente de influenza (H1N1).<\/p>\n<p>Silvio foi enterrado ao lado do irm\u00e3o, Leonel Abravanel, que morreu de c\u00e2ncer, em 1982, segundo O Globo.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2189003\/2-canais-de-tv-evitaram-helicopteros-no-sepultamento-de-silvio-santos?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; Em respeito \u00e0 fam\u00edlia, canais de TV evitaram helic\u00f3pteros no<\/p>\n","protected":false},"author":0,"featured_media":188621,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-188620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188620"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188620\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188621"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}