{"id":188578,"date":"2024-08-18T09:08:29","date_gmt":"2024-08-18T12:08:29","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/18\/amazon-recebe-permissao-para-testes-com-drones-no-reino-unido\/"},"modified":"2024-08-18T09:08:29","modified_gmt":"2024-08-18T12:08:29","slug":"amazon-recebe-permissao-para-testes-com-drones-no-reino-unido","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/18\/amazon-recebe-permissao-para-testes-com-drones-no-reino-unido\/","title":{"rendered":"Amazon recebe permiss\u00e3o para testes com drones no Reino Unido"},"content":{"rendered":"<p>A Amazon recebeu permiss\u00e3o para testar drones al\u00e9m da linha de vis\u00e3o de um controlador humano no Reino Unido, o que poderia abrir caminho para o uso dessas m\u00e1quinas para entregar pacotes em resid\u00eancias. A varejista on-line \u00e9 uma das seis organiza\u00e7\u00f5es que participam de um teste liderado pela Autoridade de Avia\u00e7\u00e3o Civil (CAA, na sigla em ingl\u00eas). O teste engloba outros projetos como a inspe\u00e7\u00e3o de parques e\u00f3licos offshore, controle de tr\u00e1fego a\u00e9reo, policiamento e entrega de suprimentos m\u00e9dicos de emerg\u00eancia. As informa\u00e7\u00f5es s\u00e3o do <i>The Guardian<\/i>.<\/p>\n<p>De acordo com a reportagem, o aeroporto de Kirkwall, nas ilhas Orkney, na Esc\u00f3cia, participar\u00e1 de um dos projetos que testar\u00e1 como drones e outras aeronaves podem operar com seguran\u00e7a lado a lado. O \u00f3rg\u00e3o regulador, que busca finalizar regulamenta\u00e7\u00f5es para uso mais amplo de drones, disse que todos os esquemas usar\u00e3o &#8220;tecnologias avan\u00e7adas&#8221; para tarefas como navega\u00e7\u00e3o e detec\u00e7\u00e3o de outras aeronaves em um ambiente controlado. Os testes coletar\u00e3o dados importantes de seguran\u00e7a, como a forma como os drones detectam e evitam outras aeronaves, al\u00e9m dos sinais eletr\u00f4nicos que eles podem enviar para ficarem vis\u00edveis para outros usu\u00e1rios do espa\u00e7o a\u00e9reo e se comunicarem com o controle de tr\u00e1fego.<\/p>\n<\/p>\n<p>&#8220;Esses testes inovadores marcam um passo significativo na integra\u00e7\u00e3o segura de drones ao espa\u00e7o a\u00e9reo do Reino Unido&#8221;, disse Sophie O\u0092Sullivan, diretora do futuro de voo na CAA. &#8220;Ao apoiar projetos que v\u00e3o desde entregas ao consumidor at\u00e9 inspe\u00e7\u00f5es de infraestrutura cr\u00edtica, estamos reunindo dados essenciais para moldar pol\u00edticas e regulamenta\u00e7\u00f5es futuras. Nosso objetivo \u00e9 tornar as opera\u00e7\u00f5es de drones al\u00e9m da linha de vis\u00e3o uma realidade segura e cotidiana, contribuindo para a moderniza\u00e7\u00e3o do espa\u00e7o a\u00e9reo do Reino Unido e a incorpora\u00e7\u00e3o de novas tecnologias em nossos c\u00e9us&#8221;, complementou.<\/p>\n<\/p>\n<p>No ano passado, a Amazon disse que queria lan\u00e7ar entregas domiciliares via drones no Reino Unido e na It\u00e1lia antes do final de 2024. Atualmente, ela j\u00e1 oferece entregas por drones nos EUA, na regi\u00e3o de Lockeford, na Calif\u00f3rnia, e na cidade de College Station, no Texas, aponta o The Guardian. No entanto, j\u00e1 faz quase oito anos desde que a empresa de tecnologia anunciou a conclus\u00e3o de sua primeira entrega comercial de drones na cidade inglesa de Cambridge. A empresa reduziu o bra\u00e7o do Reino Unido de sua divis\u00e3o de drones, a Prime Air, em 2021.<\/p>\n<\/p>\n<p>&#8220;\u00c9 crucial para operadores como n\u00f3s termos requisitos regulat\u00f3rios claros para trazer e escalar novas tecnologias, como a entrega por drones para clientes no Reino Unido&#8221;, disse David Carbon, vice-presidente e gerente geral da Prime Air. &#8220;Agradecemos o esfor\u00e7o da CAA em fazer parceria conosco para ajudar a trazer clareza aos regulamentos que d\u00e3o suporte \u00e0 entrega comercial por drones&#8221;.<\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/2188823\/amazon-recebe-permissao-para-testes-com-drones-no-reino-unido?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Amazon recebeu permiss\u00e3o para testar drones al\u00e9m da linha de vis\u00e3o de um controlador<\/p>\n","protected":false},"author":0,"featured_media":188579,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-188578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188578"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188578\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188579"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}