{"id":188563,"date":"2024-08-18T07:08:38","date_gmt":"2024-08-18T10:08:38","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/18\/escandalo-na-argentina-goleiro-e-detido-por-denuncia-da-ex-mulher\/"},"modified":"2024-08-18T07:08:38","modified_gmt":"2024-08-18T10:08:38","slug":"escandalo-na-argentina-goleiro-e-detido-por-denuncia-da-ex-mulher","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/18\/escandalo-na-argentina-goleiro-e-detido-por-denuncia-da-ex-mulher\/","title":{"rendered":"Esc\u00e2ndalo na Argentina: goleiro \u00e9 detido por den\u00fancia da ex-mulher"},"content":{"rendered":"<p>Lucas Acosta, goleiro do Sarmiento de Jun\u00edn, foi detido, este s\u00e1bado (17), por suspeitas de ter cometido um delito de &#8220;viol\u00eancia de g\u00eanero&#8221;, de acordo com informa\u00e7\u00f5es do jornal argentino <span class=\"news_bold\"><a href=\"https:\/\/www.diariodemocracia.com\/mas-deportivo\/futbol\/306894-trasladan-buenos-aires-arquero-lucas-acosta-causa-\/\">Democracia<\/a><\/span>.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>A publica\u00e7\u00e3o revelou uma den\u00fancia apresentada h\u00e1 meses pela ex-mulher do jogador de 29 anos de idade, que o levou a ser transportado, pelas autoridades do pa\u00eds, para a capital, Buenos Aires, onde se espera que venha a depor perante um tribunal.<\/p>\n<p>Um epis\u00f3dio inesperado, que surgiu na v\u00e9spera da 11.\u00aa rodada, perante o Tigre, que pode ser fundamental para as duas equipes, visto que ambas est\u00e3o lutando contra o rebaixamento.<\/p>\n<p>No entanto, face ao sucedido, o treinador do Sarmiento de Jun\u00edn, Israel Damonte, j\u00e1 sabe que n\u00e3o ir\u00e1 poder contar com seu goleiro titular.<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2025405\/3-abel-e-eleito-pela-2-vez-melhor-tecnico-portugues-fora-de-portugal\" target=\"_blank\" rel=\"noopener noreferrer\">Abel \u00e9 eleito pela 2\u00aa vez melhor t\u00e9cnico portugu\u00eas fora de Portugal<\/a><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2188948\/escandalo-na-argentina-goleiro-e-detido-por-denuncia-da-ex-mulher?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lucas Acosta, goleiro do Sarmiento de Jun\u00edn, foi detido, este s\u00e1bado (17), por suspeitas de<\/p>\n","protected":false},"author":0,"featured_media":188564,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-188563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188563"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188563\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188564"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}