{"id":188545,"date":"2024-08-17T14:08:18","date_gmt":"2024-08-17T17:08:18","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/17\/governo-lula-ve-impasse-na-venezuela-resistencia-a-planos-e-recalibra-discurso\/"},"modified":"2024-08-17T14:08:18","modified_gmt":"2024-08-17T17:08:18","slug":"governo-lula-ve-impasse-na-venezuela-resistencia-a-planos-e-recalibra-discurso","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/17\/governo-lula-ve-impasse-na-venezuela-resistencia-a-planos-e-recalibra-discurso\/","title":{"rendered":"Governo Lula v\u00ea impasse na Venezuela, resist\u00eancia a planos e recalibra discurso"},"content":{"rendered":"<p>MARIANNA HOLANDA E RENATO MACHADO<br \/>BRAS\u00cdLIA, DF (FOLHAPRESS) &#8211; O governo do presidente Lula (PT) v\u00ea a crise na Venezuela ainda sem prazo para acabar e insiste numa alternativa de di\u00e1logo pela pol\u00edtica, mas o petista viveu uma semana de decep\u00e7\u00f5es: a desist\u00eancia do M\u00e9xico de participar das articula\u00e7\u00f5es ao lado do Brasil e da Col\u00f4mbia, a diminui\u00e7\u00e3o da expectativa de divulga\u00e7\u00e3o das atas eleitorais e o recha\u00e7o a propostas aventadas.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>A situa\u00e7\u00e3o levou a uma recalibragem do discurso do lado brasileiro, com frases cr\u00edticas ao regime chavista, com express\u00f5es at\u00e9 ent\u00e3o in\u00e9ditas. O pr\u00f3prio Lula chegou a afirmar que se trata de um &#8220;regime muito desagrad\u00e1vel&#8221; e com &#8220;vi\u00e9s autorit\u00e1rio&#8221;.<\/p>\n<p>A avalia\u00e7\u00e3o interna no governo \u00e9 que os \u00e2nimos ainda est\u00e3o exaltados e nenhum dos lados -oposi\u00e7\u00e3o ou regime- est\u00e1 disposto a aceitar uma solu\u00e7\u00e3o que n\u00e3o seja o reconhecimento de sua vit\u00f3ria.<\/p>\n<p>Nesta semana, Lula lan\u00e7ou publicamente duas sugest\u00f5es, ainda embrion\u00e1rias, para o regime do ditador Nicol\u00e1s Maduro e para a oposi\u00e7\u00e3o: novas elei\u00e7\u00f5es ou um governo de coaliz\u00e3o. As duas foram recha\u00e7adas por atores internacionais, pela l\u00edder da oposi\u00e7\u00e3o Mar\u00eda Corina Machado e pelo pr\u00f3prio Maduro -que sinalizou em suas falas n\u00e3o estar aberto a interfer\u00eancias externas, mesmo de aliados como o brasileiro.<\/p>\n<p>Auxiliares de Lula minimizam os reveses e dizem que as ideias surgem como bal\u00f5es de ensaio at\u00e9 que algo se sustente nos dois lados da mesa de negocia\u00e7\u00e3o. O importante \u00e9 manter a discuss\u00e3o no trilho da pol\u00edtica, disse um aliado.<\/p>\n<p>Para isso, integrantes do governo que participam das conversas dizem que h\u00e1 uma lista de itens indispens\u00e1veis com o intuito de construir um di\u00e1logo entre Maduro e a oposi\u00e7\u00e3o. Os principais s\u00e3o anistia numa eventual transi\u00e7\u00e3o de poder e a suspens\u00e3o de san\u00e7\u00f5es internacionais.<br \/>Apesar disso, nenhum desenho de solu\u00e7\u00e3o parece certo no momento, segundo auxiliares.<\/p>\n<p>O M\u00e9xico chegou a integrar com Brasil e Col\u00f4mbia a frente pela sa\u00edda diplom\u00e1tica na regi\u00e3o, mas deixou o grupo nos \u00faltimos dias. Segundo um interlocutor de Lula, a baixa prejudica a iniciativa, mas n\u00e3o a impede.<br \/>Outro baque veio dos Estados Unidos. Depois de ser noticiado de que o presidente Joe Biden apoiaria novas elei\u00e7\u00f5es na Venezuela, a Casa Branca em seguida distanciou o l\u00edder americano da proposta.<\/p>\n<p>A Venezuela vive uma grave crise institucional, que se agravou com a realiza\u00e7\u00e3o das elei\u00e7\u00f5es presidenciais no fim de julho. Maduro foi proclamado reeleito pouco depois do pleito, mas o resultado \u00e9 amplamente questionado.<br \/>O principal impasse no momento \u00e9 a divulga\u00e7\u00e3o das atas eleitorais. Apesar da press\u00e3o internacional, inclusive do Brasil, o CNE (Conselho Nacional Eleitoral) segue sem divulgar os documentos.<\/p>\n<p>A falta de transpar\u00eancia e as recusas p\u00fablicas \u00e0s propostas aventadas, tanto por Lula como pelo colombiano Gustavo Petro, foram seguidas por uma mudan\u00e7a de postura do lado brasileiro. Na quinta-feira (15), pela primeira vez Lula disse n\u00e3o reconhecer Maduro como vitorioso na elei\u00e7\u00e3o.<\/p>\n<p>&#8220;Ainda n\u00e3o [reconhece Maduro como vitorioso], ele sabe que est\u00e1 devendo explica\u00e7\u00e3o para a sociedade brasileira e para o mundo, ele sabe disso&#8221;, disse.<br \/>&#8220;Se ele [Maduro] tiver bom senso, podia tentar fazer conclama\u00e7\u00e3o ao povo da Venezuela, quem sabe at\u00e9 convocar novas elei\u00e7\u00f5es&#8221;, acrescentou.<\/p>\n<p>Avan\u00e7ando nesta linha, o assessor especial da Presid\u00eancia da Rep\u00fablica para assuntos internacionais, Celso Amorim, declarou em audi\u00eancia no Senado que n\u00e3o haveria reconhecimento sem as atas.<\/p>\n<p>Existe uma avalia\u00e7\u00e3o crescente de que Maduro permanecer\u00e1 no poder, pelo menos no curto prazo. Por isso, os atores envolvidos na negocia\u00e7\u00e3o aumentaram a press\u00e3o pela transpar\u00eancia das atas, mas t\u00eam consci\u00eancia que esticar a corda demasiadamente pode levar a uma radicaliza\u00e7\u00e3o do regime.<br \/>Os esfor\u00e7os de negocia\u00e7\u00e3o passaram a incluir no c\u00e1lculo a decis\u00e3o pr\u00f3xima do Tribunal Supremo de Justi\u00e7a (TSJ) da Venezuela sobre a validade das elei\u00e7\u00f5es. A presidente da corte, Carylsia Rodr\u00edguez, disse no \u00faltimo dia 10 que sua decis\u00e3o acerca do pleito seria inapel\u00e1vel.<\/p>\n<p>O lado brasileiro e colombiano exigem a divulga\u00e7\u00e3o das atas pelo CNE, independentemente do posicionamento da corte, que \u00e9 bastante influenciada pelo regime Maduro. No entanto, agora h\u00e1 a avalia\u00e7\u00e3o de que a decis\u00e3o, seja ela qual for, vai causar um impacto pol\u00edtico que precisar\u00e1 ser considerado nas negocia\u00e7\u00f5es.<\/p>\n<p>O pr\u00f3prio Lula passou a defender espera da manifesta\u00e7\u00e3o judicial. &#8220;Vamos esperar, porque agora tem uma Suprema Corte que est\u00e1 com os pap\u00e9is para decidir. Vamos esperar qual ser\u00e1 a decis\u00e3o&#8221;, disse.<\/p>\n<p>O pior cen\u00e1rio, segundo um interlocutor, \u00e9 a valida\u00e7\u00e3o do pleito sem a apresenta\u00e7\u00e3o das provas. Isso levaria a um acirramento das tens\u00f5es internas e haveria pouca margem de manobra para Brasil e outros atores.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Mundo<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/mundo\/2188796\/governo-lula-ve-impasse-na-venezuela-resistencia-a-planos-e-recalibra-discurso?utm_source=rss-mundo&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MARIANNA HOLANDA E RENATO MACHADOBRAS\u00cdLIA, DF (FOLHAPRESS) &#8211; O governo do presidente Lula (PT) v\u00ea<\/p>\n","protected":false},"author":0,"featured_media":188546,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-188545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188545"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188545\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188546"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}