{"id":188541,"date":"2024-08-17T13:08:41","date_gmt":"2024-08-17T16:08:41","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/17\/homem-tenta-roubar-relogio-de-cornor-mcgregor-leva-encarada-e-ganha-autografo-no-fim\/"},"modified":"2024-08-17T13:08:41","modified_gmt":"2024-08-17T16:08:41","slug":"homem-tenta-roubar-relogio-de-cornor-mcgregor-leva-encarada-e-ganha-autografo-no-fim","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/17\/homem-tenta-roubar-relogio-de-cornor-mcgregor-leva-encarada-e-ganha-autografo-no-fim\/","title":{"rendered":"Homem tenta roubar rel\u00f3gio de Cornor McGregor, leva encarada e ganha aut\u00f3grafo no fim"},"content":{"rendered":"<p>Uma situa\u00e7\u00e3o bastante inusitada aconteceu durante um encontro do lutador do UFC Conor McGregor e um grupo de f\u00e3s. N\u00e3o se sabe a exata localidade, mas o irland\u00eas estava com seu filho Rian no colo quando parou para cumprimentar e dar aut\u00f3grafos no que parece ser um p\u00eder com barcos.<\/p>\n<p>Neste momento, um rapaz tentou roubar seu rel\u00f3gio enquanto McGregor assinava a camisa de outra pessoa. O mais curioso \u00e9 que o pr\u00f3prio &#8216;f\u00e3&#8217; estava filmando toda a situa\u00e7\u00e3o. Sorrindo, esticou a m\u00e3o at\u00e9 o rel\u00f3gio do lutador, que rapidamente retirou o bra\u00e7o e deu uma encarada no jovem, que pareceu n\u00e3o ligar e continuou filmando. No fim, deu o pr\u00f3prio bra\u00e7o para que Conor McGregor desse um aut\u00f3grafo em sua pele.<\/p>\n<\/p>\n<p>O ato destemido divertiu e chamou a aten\u00e7\u00e3o dos internautas. &#8220;Louco!&#8221;, publicou um no X, antigo Twitter. &#8220;Por que tentar um neg\u00f3cio desse?&#8221;, questionou outra pessoa.<\/p>\n<\/p>\n<p>N\u00e3o se sabe ao certo o valor do rel\u00f3gio usado pelo lutador irland\u00eas naquele momento, mas recentemente viralizou uma foto de uma pe\u00e7a de alto valor usada por McGregor.<\/p>\n<\/p>\n<p>Fabricado pela Jacob &amp; Co, pe\u00e7a se chama Astronomia Tourbillon Baguette e vale cerca de R$ 5,5 milh\u00f5es. O rel\u00f3gio \u00e9 extremamente complexo e cheio de detalhes, com direito a um globo de magn\u00e9sio e uma base diamantes por dentro.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2188735\/homem-tenta-roubar-relogio-de-cornor-mcgregor-leva-encarada-e-ganha-autografo-no-fim?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma situa\u00e7\u00e3o bastante inusitada aconteceu durante um encontro do lutador do UFC Conor McGregor e<\/p>\n","protected":false},"author":0,"featured_media":188542,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-188541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188541"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188542"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}