{"id":188499,"date":"2024-08-17T09:08:27","date_gmt":"2024-08-17T12:08:27","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/17\/vou-ter-de-parar-meteorologista-sofre-ataque-de-panico-ao-vivo\/"},"modified":"2024-08-17T09:08:27","modified_gmt":"2024-08-17T12:08:27","slug":"vou-ter-de-parar-meteorologista-sofre-ataque-de-panico-ao-vivo","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/17\/vou-ter-de-parar-meteorologista-sofre-ataque-de-panico-ao-vivo\/","title":{"rendered":"&quot;Vou ter de parar&quot;: Meteorologista sofre ataque de p\u00e2nico ao vivo"},"content":{"rendered":"<p>O meteorologista australiano Nate Byrne sofreu um ataque de p\u00e2nico, ao vivo, enquanto apresentava a previs\u00e3o do tempo, na segunda-feira, no programa &#8216;News Breakfast&#8217; da Australian Broadcasting Corporation (ABC).<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>Durante a transmiss\u00e3o, Byrne, que anteriormente j\u00e1 havia se pronunciado sobre a sua luta contra os ataques de p\u00e2nico, acabou por pedir para passar a emiss\u00e3o \u00e0 jornalista Lisa Miller, quando apresentava a previs\u00e3o do tempo para as regi\u00f5es de Queensland e Nova Gales do Sul.<\/p>\n<p>&#8220;Vou ter de pedir para parar por um segundo. Alguns de voc\u00eas devem saber que ocasionalmente sou afetado por alguns ataques de p\u00e2nico, e na verdade, isso est\u00e1 acontecendo neste momento. Lisa, talvez te possa continuar a transmiss\u00e3o&#8221;, disse.\u00a0<\/p>\n<p>A jornalista acatou o pedido e aproveitou ainda o momento para lembrar um artigo que o colega j\u00e1 havia escrito sobre este problema, em 2022.\u00a0<\/p>\n<p>Alguns minutos depois, Nate regressou, mais calmo, ao programa, e pediu desculpa aos telespectadores pelo susto.<\/p>\n<p>&#8220;Pe\u00e7o desculpa se assustei algu\u00e9m&#8221;, disse.\u00a0<\/p>\n<p>Mais tarde, o australiano viria mesmo a destacar que, ap\u00f3s ver o v\u00eddeo do sucedido, percebeu que os sinais de um ataque de p\u00e2nico podem n\u00e3o ser \u00f3bvios para quem v\u00ea.\u00a0<\/p>\n<p>O momento rapidamente se tornou viral na Internet, com muitos utilizadores a expressarem o seu apoio a Nate e a elogiarem a postura dos seus colegas de equipe.<\/p>\n<blockquote class=\"twitter-tweet\" data-media-max-width=\"560\">\n<p dir=\"ltr\" lang=\"en\">Australian Weatherman Has Panic Attack Live On Air<\/p>\n<p>Nate Byrne from ABC was in the middle of presenting the forecast when he had to stop. <a href=\"https:\/\/t.co\/Fys1eDq9me\">pic.twitter.com\/Fys1eDq9me<\/a><\/p>\n<p>\u2014 RT_India (@RT_India_news) <a href=\"https:\/\/twitter.com\/RT_India_news\/status\/1824311393786396799?ref_src=twsrc%5Etfw\">August 16, 2024<\/a><\/p><\/blockquote>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/mundo\/2188428\/os-maiores-escandalos-da-carreira-politica-de-donald-trump\" target=\"_blank\" rel=\"noopener noreferrer\">Os maiores esc\u00e2ndalos da carreira pol\u00edtica de Donald Trump<\/a><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Mundo<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/mundo\/2188678\/vou-ter-de-parar-meteorologista-sofre-ataque-de-panico-ao-vivo?utm_source=rss-mundo&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O meteorologista australiano Nate Byrne sofreu um ataque de p\u00e2nico, ao vivo, enquanto apresentava a<\/p>\n","protected":false},"author":0,"featured_media":188500,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-188499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188499"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188500"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}