{"id":188487,"date":"2024-08-17T08:08:10","date_gmt":"2024-08-17T11:08:10","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/17\/problema-do-pais-nao-e-o-pobre-trabalhador-sao-os-ricos-diz-lula\/"},"modified":"2024-08-17T08:08:10","modified_gmt":"2024-08-17T11:08:10","slug":"problema-do-pais-nao-e-o-pobre-trabalhador-sao-os-ricos-diz-lula","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/17\/problema-do-pais-nao-e-o-pobre-trabalhador-sao-os-ricos-diz-lula\/","title":{"rendered":"Problema do pa\u00eds n\u00e3o \u00e9 o pobre trabalhador, s\u00e3o os ricos, diz Lula"},"content":{"rendered":"<p>CARLOS VILLELA E ARTUR B\u00daRIGO<br \/>PORTO ALEGRE, RS E BELO HORIZONTE, MG (FOLHAPRESS) &#8211; O presidente Luiz In\u00e1cio Lula da Silva (PT) afirmou nesta sexta-feira (16) que o papel do governo \u00e9 distribuir recursos \u00e0 popula\u00e7\u00e3o via bancos p\u00fablicos para fazer a economia girar.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>&#8220;A hora que todo mundo tiver um pouco, a gente vai perceber que a economia vai melhorar, o desemprego vai cair. Estamos com o melhor \u00edndice desde 2014&#8221;, disse o presidente, referindo-se \u00e0 taxa de desemprego.<\/p>\n<p>&#8220;Dinheiro parado s\u00f3 interessa a banqueiro e especulador, quero dinheiro circulando na m\u00e3o do povo. O problema do Brasil n\u00e3o \u00e9 o povo pobre trabalhador, o problema s\u00e3o os ricos, porque o pobre, se estiver consumindo, a economia vai para frente e todo mundo vai viver bem neste pa\u00eds&#8221;, completou o mandat\u00e1rio, em agenda em S\u00e3o Leopoldo (RS).<\/p>\n<p>Em viagem ao estado para inaugurar obras e entregar moradias do programa Minha Casa, Minha Vida, o presidente tamb\u00e9m voltou a criticar a insatisfa\u00e7\u00e3o de parte do setor agropecu\u00e1rio junto ao seu governo.<\/p>\n<p>&#8220;O agroneg\u00f3cio est\u00e1 reclamando do qu\u00ea? Nunca teve um Plano Safra [do tamanho] como teve no nosso governo. Duvido que em algum momento algu\u00e9m tratou eles com a dec\u00eancia e o respeito como fizemos eu e a Dilma [Rousseff]&#8221;, afirmou Lula.<\/p>\n<p>&#8220;Eu n\u00e3o pedi favor nem vou pedir. Eles que falem e fa\u00e7am o que quiser, porque a agricultura \u00e9 muito importante para o pa\u00eds e para o mundo&#8221;, completou o presidente.<\/p>\n<p>Em julho, o governo anunciou um Plano Safra para 2024 e 2025 com a cifra recorde de R$ 400,5 bilh\u00f5es. Na \u00e9poca, ele afirmou que os respons\u00e1veis por tomar terra de fazendeiros no pa\u00eds s\u00e3o os banqueiros, n\u00e3o o MST (Movimento dos Trabalhadores Rurais sem Terra).<\/p>\n<p>Na cidade ga\u00facha, o ministro da Secretaria Extraordin\u00e1ria para Apoio \u00e0 Reconstru\u00e7\u00e3o do estado, Paulo Pimenta, tamb\u00e9m destacou os recursos injetados pelo governo para o estado se recuperar da enchente. Ele citou a suspens\u00e3o da d\u00edvida do estado junto \u00e0 Uni\u00e3o por 36 meses, os empr\u00e9stimos subsidiados e a libera\u00e7\u00e3o do FGTS (Fundo de Garantia do Tempo de Servi\u00e7o).<\/p>\n<p>Segundo o ministro, essas pol\u00edticas fizeram a economia do estado girar, reverteram a queda de arrecada\u00e7\u00e3o e impulsionaram o resultado da ind\u00fastria no m\u00eas de julho. Em evento mais cedo nesta sexta, o governador Eduardo Leite (PSDB) afirmou que h\u00e1 uma demora no repasse de verbas por parte do governo federal.<\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/2188599\/problema-do-pais-nao-e-o-pobre-trabalhador-sao-os-ricos-diz-lula?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CARLOS VILLELA E ARTUR B\u00daRIGOPORTO ALEGRE, RS E BELO HORIZONTE, MG (FOLHAPRESS) &#8211; O presidente<\/p>\n","protected":false},"author":0,"featured_media":188488,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-188487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188487"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188487\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188488"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}