{"id":188224,"date":"2024-08-15T06:08:29","date_gmt":"2024-08-15T09:08:29","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/15\/bia-haddad-cai-na-primeira-rodada-em-cincinnati-e-marcelo-melo-vence-nas-duplas\/"},"modified":"2024-08-15T06:08:29","modified_gmt":"2024-08-15T09:08:29","slug":"bia-haddad-cai-na-primeira-rodada-em-cincinnati-e-marcelo-melo-vence-nas-duplas","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/15\/bia-haddad-cai-na-primeira-rodada-em-cincinnati-e-marcelo-melo-vence-nas-duplas\/","title":{"rendered":"Bia Haddad cai na primeira rodada em Cincinnati e Marcelo Melo vence nas duplas"},"content":{"rendered":"<p>A brasileira Beatriz Haddad Maia, 22\u00aa do ranking mundial, perdeu em sua estreia no WTA 1000 de Cincinnati nesta quarta-feira. Ap\u00f3s vencer a primeira parcial, a tenista n\u00e3o suportou o bom ritmo de jogo da russa Anastasia Pavlyuchenkova (28\u00aa) e levou a virada de 2 sets a 1, 4\/6, 7\/6 (7\/4) e 6\/3 em 2h56. O resultado apresenta um aproveitamento de 100% da russa no retrospecto particular com a rival brasileira. S\u00e3o quatro vit\u00f3rias em quatro disputas.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>No primeiro set, Bia abriu vantagem de 2 a 0, mas teve uma quebra de servi\u00e7o e sofreu o empate. A rea\u00e7\u00e3o, por\u00e9m, n\u00e3o demorou, e ela voltou a abrir uma diferen\u00e7a de dois games (4 a 2). A partir da\u00ed, foi administrar a gordura para fazer 1 a 0 em sets.<\/p>\n<p>De volta \u00e0 quadra, Pavlyuchenka e Bia realizaram uma segunda parcial bem disputada, que s\u00f3 foi definida no tiebreak em favor da tenista russa (7\/4). No terceiro set, Bia oscilou e acabou comprometendo sua atua\u00e7\u00e3o. A advers\u00e1ria ganhou tr\u00eas games seguidos (3 a 1) e manteve um jogo consistente para definir o triunfo em 6\/3.<\/p>\n<p>MARCELO MELO VENCE NAS DUPLAS<\/p>\n<p>O tenista Marcelo Melo estreou com vit\u00f3ria nas duplas, ao lado de Alexander Zverev, nesta quarta-feira ao superar os anfitri\u00f5es americanos Nathaniel Lammons e Jackson Withrow por 2 sets a 1, parciais de 6\/4, 6\/7 (5\/7) e 10\/2 em 1h27 de um confronto bastante disputado.<\/p>\n<p>Feliz pelo resultado, o brasileiro agora aposta em uma evolu\u00e7\u00e3o da dupla para conseguir manter o n\u00edvel de atua\u00e7\u00f5es no torneio que serve de prepara\u00e7\u00e3o para o US Open, \u00faltimo Grand Slam da temporada.<\/p>\n<p>&#8220;Acho que jogamos muito bem. Aproveitamos as chances que a gente teve e fomos superiores durante toda a partida. Foi um belo resultado diante de uma dupla que vem atuando muito bem. Agora \u00e9 usar toda a energia para o pr\u00f3ximo compromisso&#8221;, afirmou Marcelo Melo.<\/p>\n<p>Os dois tenistas voltam \u00e0 quadra nesta quinta e encaram Marcelo Arevalo, de El Salvador, e o croata Mate Pavic, cabe\u00e7as de chave n\u00famero 4, pelas oitavas de final. Este \u00e9 o quarto torneio que Melo e Zverev atuam em parceria nesta temporada. O melhor resultado foi o vice-campeonato no ATP de Monte Carlo, em abril. Juntos, eles tamb\u00e9m disputaram o Masters 1000 de Indian Wells e o torneio de Roma.<\/p>\n<p>Na chave de simples, o italiano Jannik Sinner, n\u00famero 1 do mundo, confirmou o seu favoritismo e superou o americano Alex Michelsen em dois sets com parciais de 6\/4 e 7\/5. J\u00e1 Stefanos Tsitsipas levou um susto. Ap\u00f3s sair perdendo, ele precisou de uma virada para bater Jan-Lennard Struff por 2 sets a 1, parciais de 4\/6, 6\/4 e 6\/3.<\/p>\n<p>J\u00e1 o canadense Felix Auger-Aliassime (19\u00ba) n\u00e3o tomou conhecimento de Aleksandar Kovacevic (79\u00ba) venceu o americano com facilidade ao aplicar um 6\/3 e 6\/1 para definir o triunfo e confirmar sua perman\u00eancia no torneio. Por fim o dinamarqu\u00eas Holger Hune (16\u00ba) tamb\u00e9m passou de fase ao derrotar o italiano Matteo Berrettini (42\u00ba) por 2 sets a 1 de virada (2\/6, 6\/1 e 6\/4).<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2187633\/bia-haddad-cai-na-primeira-rodada-em-cincinnati-e-marcelo-melo-vence-nas-duplas?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A brasileira Beatriz Haddad Maia, 22\u00aa do ranking mundial, perdeu em sua estreia no WTA<\/p>\n","protected":false},"author":0,"featured_media":188225,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-188224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188224"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188225"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}