{"id":188204,"date":"2024-08-14T23:08:16","date_gmt":"2024-08-15T02:08:16","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/14\/divorcio-testamento-e-ate-declaracao-de-doador-de-orgaos-ja-podem-ser-feitos-pela-internet\/"},"modified":"2024-08-14T23:08:16","modified_gmt":"2024-08-15T02:08:16","slug":"divorcio-testamento-e-ate-declaracao-de-doador-de-orgaos-ja-podem-ser-feitos-pela-internet","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/14\/divorcio-testamento-e-ate-declaracao-de-doador-de-orgaos-ja-podem-ser-feitos-pela-internet\/","title":{"rendered":"Div\u00f3rcio, testamento e at\u00e9 declara\u00e7\u00e3o de doador de \u00f3rg\u00e3os j\u00e1 podem ser feitos pela internet"},"content":{"rendered":"<p>RIO DE JANEIRO, RJ (FOLHAPRESS) &#8211; A plataforma online dos cart\u00f3rios brasileiros, que re\u00fane atualmente 8.500 representa\u00e7\u00f5es, j\u00e1 \u00e9 respons\u00e1vel por at\u00e9 35% dos atos notariais. O cart\u00f3rio digital permite que o cidad\u00e3o solicite servi\u00e7os desde div\u00f3rcios at\u00e9 autoriza\u00e7\u00f5es de viagem para menores de 18 anos pela internet.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>Os dados s\u00e3o do Col\u00e9gio Notarial do Brasil (CNB), respons\u00e1vel pelo site. Ao todo, 4,3 milh\u00f5es de atos foram feitos na plataforma desde 2020, quando o CNJ (Conselho Nacional de Justi\u00e7a) publicou resolu\u00e7\u00e3o regulamentando o e-notariado.<\/p>\n<p>Segundo Giselle Oliveira de Barros, presidente do Conselho Federal do CNB, o portal reduz o tempo gasto para cidad\u00e3os solicitarem atos que antes eram feitos exclusivamente em cart\u00f3rios f\u00edsicos.<\/p>\n<p>&#8220;Tamb\u00e9m facilitou para n\u00f3s, que, \u00e0s vezes, precisamos ir a algum local pegar assinaturas. Usar a plataforma economiza tempo de locomo\u00e7\u00e3o, ainda mais em centros urbanos.&#8221;<\/p>\n<p>Os servi\u00e7os notariais s\u00e3o exercidos por entes privados, delegados pelo poder p\u00fablico, e fiscalizados pelo Judici\u00e1rio. Mesmo no e-notariado, os registros permitem que cidad\u00e3o exer\u00e7a direitos.<\/p>\n<p>Entre os atos realizados nos \u00faltimos tr\u00eas anos est\u00e3o 1,2 milh\u00e3o de escrituras, que incluem testamentos e div\u00f3rcios, e 336 mil procura\u00e7\u00f5es. Tamb\u00e9m foram feitas 684 mil reconhecimentos de assinaturas eletr\u00f4nicas, 23 mil autoriza\u00e7\u00f5es de viagem e 8.500 autoriza\u00e7\u00f5es de doa\u00e7\u00e3o de \u00f3rg\u00e3os.<\/p>\n<p>Esse \u00faltimo ato foi institu\u00eddo em mar\u00e7o deste ano pelo CNJ. Com ele, cidad\u00e3os podem solicitar, pelo e-notariado, uma declara\u00e7\u00e3o gratuita e eletr\u00f4nica de que \u00e9 doador de \u00f3rg\u00e3os.<\/p>\n<p>Para ter acesso a esse e a outros atos notariais pela internet, o cidad\u00e3o deve emitir um certificado digital pelo e-notariado, que ser\u00e1 vinculado ao cart\u00f3rio que escolher.<\/p>\n<p>A emiss\u00e3o \u00e9 gratuita. Na plataforma, ele registra os dados cadastrais do cidad\u00e3o e um documento, que pode ser a carteira de identifica\u00e7\u00e3o, a Carteira Nacional de Habilita\u00e7\u00e3o ou o passaporte. Depois, o cart\u00f3rio agenda uma videochamada com o interessado para validar sua identidade.<\/p>\n<p>Quando o certificado digital estiver pronto, ficar\u00e1 registrado no celular do solicitante e ter\u00e1 validade de at\u00e9 tr\u00eas anos. A reemiss\u00e3o tamb\u00e9m \u00e9 sem custos, caso o prazo ven\u00e7a.<\/p>\n<p>De acordo com Giselle de Barros, a validade existe porque h\u00e1 cidad\u00e3os que podem, em pouco tempo, ter dificuldade de responder por si mesmos.<\/p>\n<p>O prazo tamb\u00e9m segue a m\u00e9trica do ICP-Brasil (Infraestrutura de Chaves P\u00fablicas Brasileira), voltada \u00e0 emiss\u00e3o de certificados digitais.<\/p>\n<p>Quando tiver o certificado digital, o cidad\u00e3o deve entrar em contato com um cart\u00f3rio para pedir escrituras e procura\u00e7\u00f5es pelo e-notariado. O cart\u00f3rio vai registrar o ato na plataforma e o pagamento do servi\u00e7o tamb\u00e9m \u00e9 feito pelo site.<\/p>\n<p>O usu\u00e1rio assina o documento pela internet e cadastra quem mais far\u00e1 a assinatura. Quando todos tiverem preenchido, o cart\u00f3rio vai reconhecer as firmas eletr\u00f4nicas para validar o documento.<\/p>\n<p>Se o cidad\u00e3o estiver se divorciando, por exemplo, ele e o c\u00f4njuge devem solicitar o processo ao mesmo cart\u00f3rio, que pedir\u00e1 documentos adicionais para dar in\u00edcio ao processo -como certid\u00e3o de casamento, partilha de bens, entre outros.<\/p>\n<p>O casal participar\u00e1 de uma confer\u00eancia de v\u00eddeo, juntos ou separados, para declarar a separa\u00e7\u00e3o. Depois, eles recebem um link por e-mail para assinar o documento. O procedimento vale apenas para div\u00f3rcios extrajudiciais de casais sem filhos menores de 18 anos.<\/p>\n<p>O e-notariado permite ainda que pessoas de fora do Brasil solicitem servi\u00e7os sem emitir uma procura\u00e7\u00e3o, documento que d\u00e1 plenos poderes para algu\u00e9m que permanece no pa\u00eds para agir em seu nome. Mas, se o cidad\u00e3o preferir, a procura\u00e7\u00e3o tamb\u00e9m pode ser feita pela plataforma.<\/p>\n<p>Dos 8.500 cart\u00f3rios registrados na plataforma, 5.500 s\u00e3o ativos, de acordo com o Col\u00e9gio Notarial. A presidente do CNB Giselle de Barros diz que, entre os inativos, a justificativa para n\u00e3o usar \u00e9 a falta de demanda, sobretudo em cidades menores.<\/p>\n<p>&#8220;Para cart\u00f3rios, \u00e9 o mesmo custo&#8221;, diz. &#8220;\u00c9 preciso de um movimento do tabeli\u00e3o para aderir. \u00c9 um trabalho que temos feito, de formiguinha, para que todos estejam integrados.&#8221;<\/p>\n<p>Os cart\u00f3rios devem ter um computador com acesso \u00e0 internet para aderir e usar o e-notariado.<\/p>\n<p>S\u00e3o Paulo \u00e9 o estado com maior n\u00famero de atos feitos pelo portal, com 1,2 milh\u00e3o. Em seguida, vem o Rio de Janeiro, com 554 mil. Entre os \u00faltimos, Alagoas tem o menor n\u00famero de atos, com apenas 3.700. Antes, vem o Amap\u00e1, com 4.400.<\/p>\n<p><span class=\"news_bold\">VALORES PARA EMITIR ATOS NO E-NOTARIADO EM SP<\/span><\/p>\n<p>Escritura com valor declarado: a partir de R$ 328<br \/>Testamento: a partir de R$ 124 (p\u00fablico sem conte\u00fado patrimonial)<br \/>Procura\u00e7\u00e3o: a partir de R$ 113<br \/>Reconhecimento de firma: a partir de R$ 8<\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/2187326\/divorcio-testamento-e-ate-declaracao-de-doador-de-orgaos-ja-podem-ser-feitos-pela-internet?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RIO DE JANEIRO, RJ (FOLHAPRESS) &#8211; A plataforma online dos cart\u00f3rios brasileiros, que re\u00fane atualmente<\/p>\n","protected":false},"author":0,"featured_media":188205,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-188204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188204"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188204\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188205"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}