{"id":188067,"date":"2024-08-13T22:08:24","date_gmt":"2024-08-14T01:08:24","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/13\/nunca-bati-em-uma-mulher-diz-fernandez-apos-ser-acusado-de-agressao-por-ex-companheira\/"},"modified":"2024-08-13T22:08:24","modified_gmt":"2024-08-14T01:08:24","slug":"nunca-bati-em-uma-mulher-diz-fernandez-apos-ser-acusado-de-agressao-por-ex-companheira","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/13\/nunca-bati-em-uma-mulher-diz-fernandez-apos-ser-acusado-de-agressao-por-ex-companheira\/","title":{"rendered":"&#8216;Nunca bati em uma mulher&#8217;, diz Fern\u00e1ndez ap\u00f3s ser acusado de agress\u00e3o por ex-companheira"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; O ex-presidente da Argentina Alberto Fern\u00e1ndez negou, em entrevista ao jornal El Pa\u00eds publicada nesta ter\u00e7a-feira (13), ter agredido sua ex-companheira, Fabiola Y\u00e1\u00f1ez, cuja acusa\u00e7\u00e3o de viol\u00eancia de g\u00eanero contra o peronista respingou na pol\u00edtica do pa\u00eds.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>&#8220;Estou sendo acusado de algo que n\u00e3o fiz. N\u00e3o bati em Fabiola. Nunca bati em uma mulher&#8221;, afirmou Fern\u00e1ndez durante a conversa em Buenos Aires. Trata-se da primeira entrevista do ex-presidente desde que Ya\u00f1ez formalizou as den\u00fancias por agress\u00e3o contra o ex-marido. Nela, ele rejeita as acusa\u00e7\u00f5es, como j\u00e1 havia feito por meio de uma nota.<\/p>\n<p>&#8220;N\u00e3o estou aqui para alimentar toda a sujeira midi\u00e1tica que est\u00e1 sendo gerada. Recebi voc\u00ea para lhe dizer sob seus olhos que n\u00e3o fui o autor de nenhum desses fatos&#8221;, insistiu o pol\u00edtico, que governou a Argentina entre 2019 e 2023. &#8220;O que vou fazer \u00e9 esperar, ir \u00e0 Justi\u00e7a e deixar a Justi\u00e7a resolver&#8221;, acrescentou o pol\u00edtico de 65 anos na entrevista.<\/p>\n<p>O caso teve in\u00edcio em abril, a Justi\u00e7a argentina bloqueou os os bens de Fern\u00e1ndez e determinou a quebra do sigilo banc\u00e1rio de suas contas em meio a uma acusa\u00e7\u00e3o de desvio de verba p\u00fablica. No meio desse processo, os respons\u00e1veis pelo caso acessaram mensagens em que Ya\u00f1ez relatava as agress\u00f5es e a chamaram a testemunhar. Pouco depois, ela formalizou as den\u00fancias por agress\u00e3o contra o ex-marido.<\/p>\n<p>O caso escalou ap\u00f3s o portal Infobae publicar fotos de Ya\u00f1ez machucada, nos olhos e nos bra\u00e7os, na semana passada. A pr\u00f3pria ex-primeira-dama teria enviado as imagens a Fern\u00e1ndez pelo aplicativo WhatsApp.<\/p>\n<p>Em capturas de tela das mensagens reveladas pelo mesmo site, h\u00e1 textos como: &#8220;Isso j\u00e1 n\u00e3o funciona se a todo momento voc\u00ea me bate. N\u00e3o posso deixar que voc\u00ea me fa\u00e7a isso quando n\u00e3o te fiz nada. Tudo que tento fazer \u00e9 defender-me, e voc\u00ea me agride fisicamente.&#8221; Em outra, a ex-primeira-dama relata que havia tr\u00eas dias que Fern\u00e1ndez a agredia.<\/p>\n<p>Y\u00e1\u00f1ez mora em Madri com o filho pequeno, fruto de seu relacionamento de mais de uma d\u00e9cada com o ex-presidente. Desde a den\u00fancia, um juiz argentino pediu um refor\u00e7o de sua prote\u00e7\u00e3o na Espanha e proibiu o ex-presidente de deixar a Argentina.<\/p>\n<p>O caso abalou a pol\u00edtica argentina. Tanto o atual presidente, Javier Milei, rival pol\u00edtico, quanto a peronista e ex-chefe de Estado Cristina Kirchner, que foi vice-presidente de Fern\u00e1ndez, criticaram o l\u00edder pelos supostos atos que lhe foram atribu\u00eddos.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Mundo<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/mundo\/2186775\/nunca-bati-em-uma-mulher-diz-fernandez-apos-ser-acusado-de-agressao-por-ex-companheira?utm_source=rss-mundo&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; O ex-presidente da Argentina Alberto<\/p>\n","protected":false},"author":0,"featured_media":188068,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-188067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188067"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188067\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188068"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}