{"id":188017,"date":"2024-08-13T14:08:21","date_gmt":"2024-08-13T17:08:21","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/13\/edmundo-gonzalez-assumira-como-novo-presidente-da-venezuela-diz-oposicao\/"},"modified":"2024-08-13T14:08:21","modified_gmt":"2024-08-13T17:08:21","slug":"edmundo-gonzalez-assumira-como-novo-presidente-da-venezuela-diz-oposicao","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/13\/edmundo-gonzalez-assumira-como-novo-presidente-da-venezuela-diz-oposicao\/","title":{"rendered":"Edmundo Gonz\u00e1lez assumir\u00e1 como novo presidente da Venezuela, diz oposi\u00e7\u00e3o"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; Mar\u00eda Corina Machado, l\u00edder da oposi\u00e7\u00e3o Venezuela, afirmou que Edmundo Gonz\u00e1lez ser\u00e1 empossado como novo presidente no dia 10 de janeiro de 2025.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>A fala foi feita em tom de press\u00e3o \u00e0 Nicolas Maduro, que foi anunciado como reeleito pelo \u00f3rg\u00e3o eleitoral. A declara\u00e7\u00e3o de Corina foi dada \u00e0 ag\u00eancia de not\u00edcias EFE nesta segunda-feira (12).<\/p>\n<p>&#8221;Sei que teremos um novo presidente&#8221;, disse. &#8221;Edmundo Gonz\u00e1lez ser\u00e1 o novo chefe de Estado e o novo comandante das For\u00e7as Armadas, e isso depende do que todos n\u00f3s fizermos, dentro e fora do pa\u00eds, confio no povo da Venezuela&#8221;, acrescentou.<\/p>\n<p>Corina chamou vit\u00f3ria de Maduro como a &#8221;maior fraude da hist\u00f3ria&#8221;. A ex-deputada tamb\u00e9m reiterou o apelo \u00e0 comunidade internacional e disse esperar que governos estrangeiros fa\u00e7am o ditador venezuelano &#8221;compreender que o est\u00e1 fazendo \u00e9 inaceit\u00e1vel&#8221;.<\/p>\n<p>A oposi\u00e7\u00e3o acredita em vit\u00f3ria de candidato com 67% dos votos. O partido opositor recolheu as atas de vota\u00e7\u00e3o manualmente e elaborou uma contagem paralela, que teria indicado que Gonz\u00e1lez ganhou de Maduro com uma vantagem de 4 milh\u00f5es de votos.<\/p>\n<p><span class=\"news_bold\">VENEZUELA EM CRISE<\/span><\/p>\n<p>A situa\u00e7\u00e3o pol\u00edtica da Venezuela ficou ainda mais complicada desde a elei\u00e7\u00e3o realizada em 28 de julho. A oposi\u00e7\u00e3o alega ter vencido a disputa, mas o Conselho Nacional Eleitoral declarou vit\u00f3ria de Maduro com 52% dos votos.<\/p>\n<p>As atas de vota\u00e7\u00e3o n\u00e3o foram apresentadas e a suspei\u00e7\u00e3o levou manifestantes \u00e0s ruas. Eles protestam porque o \u00f3rg\u00e3o eleitoral \u00e9 composto de aliados do ditador e existem a reclama\u00e7\u00e3o de resultado forjado.<\/p>\n<p>As for\u00e7as de seguran\u00e7a usaram a viol\u00eancia para responder \u00e0s manifesta\u00e7\u00f5es e dezenas de pessoas morreram. A informa\u00e7\u00e3o \u00e9 da ONG Provea. No s\u00e1bado (10), o Conselho Nacional Eleitoral informou que o resultado ser\u00e1 &#8220;inapel\u00e1vel&#8221;.<\/p>\n<p>O Brasil informou que n\u00e3o reconhecer\u00e1 a contagem de votos sem a apresenta\u00e7\u00e3o das atas. A divulga\u00e7\u00e3o do documento \u00e9 cobrada por diversos pa\u00edses que pressionam o pa\u00eds.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Mundo<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/mundo\/2186758\/edmundo-gonzalez-assumira-como-novo-presidente-da-venezuela-diz-oposicao?utm_source=rss-mundo&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; Mar\u00eda Corina Machado, l\u00edder da oposi\u00e7\u00e3o Venezuela, afirmou que Edmundo<\/p>\n","protected":false},"author":0,"featured_media":188018,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-188017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=188017"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/188017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/188018"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=188017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=188017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=188017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}