{"id":187989,"date":"2024-08-13T10:08:26","date_gmt":"2024-08-13T13:08:26","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/13\/duda-beat-diz-que-teve-mala-revirada-e-acusa-companhia-aerea-de-roubar-artigos-de-luxo\/"},"modified":"2024-08-13T10:08:26","modified_gmt":"2024-08-13T13:08:26","slug":"duda-beat-diz-que-teve-mala-revirada-e-acusa-companhia-aerea-de-roubar-artigos-de-luxo","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/13\/duda-beat-diz-que-teve-mala-revirada-e-acusa-companhia-aerea-de-roubar-artigos-de-luxo\/","title":{"rendered":"Duda Beat diz que teve mala revirada e acusa companhia a\u00e9rea de roubar artigos de luxo"},"content":{"rendered":"<p>RIO DE JANEIRO, RJ (FOLHAPRESS) &#8211; Duda Beat saiu de f\u00e9rias com as amigas Anitta, Bruna Griphao, Dani Calabresa, Maya Massafera e Vivi Wanderley para curtir uma viagem \u00e0 Gr\u00e9cia. S\u00f3 que o come\u00e7o da jornada n\u00e3o foi o que a cantora esperava. A int\u00e9rprete de &#8220;Sinto Muito&#8221; lamentou que teve a sua mala revirada durante o voo para a Europa e notou a aus\u00eancia de alguns itens de luxo. &#8220;Estou com sangue nos olhos&#8221;, come\u00e7ou.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>A cantora disse ainda estar perplexa com a situa\u00e7\u00e3o. &#8220;Abriram a minha mala e estava faltando uma bolsa da Chanel, outra da Balenciaga, minha caixinha de joias, uma saia e meu chap\u00e9u da Miu Miu. Algu\u00e9m roubou essas coisas!&#8217;, relatou afirmando a certeza de ter colocado os objetos na mala. &#8220;Coloquei tudo na bagagem e isso praticamente estragou a minha viagem. Estou superchateada. S\u00e3o itens valiosos para mim&#8221;, observou ela.<\/p>\n<p>A artista n\u00e3o quis expor o nome da companhia a\u00e9rea, mas afirmou que ir\u00e1 entrar na Justi\u00e7a para reaver seus danos materiais. &#8220;Em nenhum momento imaginei passar por isso. A gente confia a bagagem \u00e0s pressas para a companhia a\u00e9rea e acontece isso. J\u00e1 acionei meus advogados&#8221;, comentou.<\/p>\n<p>Por fim, ela concluiu: &#8220;Estou muito chateada. N\u00e3o tanto pelo valor das coisas, mas pelo fato de a not\u00edcia ter impactado umas f\u00e9rias que eu tinha tirado. A pessoa acaba perdendo todo o ch\u00e3o por saber que est\u00e1 vulner\u00e1vel dessa forma. Tem coisas que s\u00e3o inestim\u00e1veis. Estou muito triste.&#8221;<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2186327\/duda-beat-diz-que-teve-mala-revirada-e-acusa-companhia-aerea-de-roubar-artigos-de-luxo?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RIO DE JANEIRO, RJ (FOLHAPRESS) &#8211; Duda Beat saiu de f\u00e9rias com as amigas Anitta,<\/p>\n","protected":false},"author":0,"featured_media":187990,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-187989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187989"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/187990"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}