{"id":187987,"date":"2024-08-13T09:08:48","date_gmt":"2024-08-13T12:08:48","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/13\/romenia-propoe-dividir-bronze-de-final-vencida-por-rebeca\/"},"modified":"2024-08-13T09:08:48","modified_gmt":"2024-08-13T12:08:48","slug":"romenia-propoe-dividir-bronze-de-final-vencida-por-rebeca","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/13\/romenia-propoe-dividir-bronze-de-final-vencida-por-rebeca\/","title":{"rendered":"Rom\u00eania prop\u00f5e dividir bronze de final vencida por Rebeca"},"content":{"rendered":"<p>Os Jogos Ol\u00edmpicos de Paris-2024 podem j\u00e1 ter acabado, mas o drama que cerca a final do solo da gin\u00e1stica art\u00edstica parece longe de terminar. Nesta segunda-feira, a Federa\u00e7\u00e3o Romena de Gin\u00e1stica (FRG) divulgou um comunicado em seu site onde afirma n\u00e3o ter pedido pela retirada da medalha de bronze da americana Jordan Chiles.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>Ainda na nota, o \u00f3rg\u00e3o esportivo sugere uma poss\u00edvel solu\u00e7\u00e3o para o imbr\u00f3glio: a divis\u00e3o do terceiro lugar entre as tr\u00eas ginastas afetadas. &#8220;A iniciativa de premiar medalhas de bronze \u00e0s tr\u00eas atletas, Jordan Chiles, Ana Maria Barbosu e Sabrina Maneca-Voinea, foi proposta pelos advogados da FRG, com a aprova\u00e7\u00e3o pr\u00e9via da Federa\u00e7\u00e3o&#8221;, afirmou o \u00f3rg\u00e3o esportivo em nota \u00e0 imprensa.<\/p>\n<p>&#8220;A FRG, por meio de seus representantes, tomou todas as medidas necess\u00e1rias para alcan\u00e7ar esse consenso. Destacamos que certos pedidos foram feitos pelo lado americano para atingir esse objetivo, e nossa parte atendeu a todos os pedidos&#8221;, continuou a Federa\u00e7\u00e3o.<\/p>\n<p>No comunicado, o \u00f3rg\u00e3o esportivo tamb\u00e9m afirma que sempre procurou resolver a disputa de uma maneira que &#8220;demonstre respeito e apre\u00e7o pelos atletas envolvidos&#8221; e pediu para que a comunidade esportiva parasse de &#8220;atacar as atletas envolvidas&#8221;. &#8220;A FRG nunca concordou em retirar uma medalha&#8221;, finalizou a Federa\u00e7\u00e3o.<\/p>\n<p><span class=\"news_bold\">ENTENDA O CASO<\/span><\/p>\n<p>A final foi vencida pela brasileira Rebeca Andrade e o segundo lugar ficou com a americana Simone Biles. O terceiro lugar, no entanto, \u00e9 motivo de controv\u00e9rsias. Ao final da competi\u00e7\u00e3o, a ginasta romena Ana Maria Barbosu terminou com 13.700 pontos, o que a deixou em terceiro lugar. Em quarto, sua compatriota Sabrina Maneca-Voinea, tamb\u00e9m com os mesmos 13.700 pontos. Como ambas as ginastas terminaram com o mesmo valor, a nota de dificuldade das manobras se tornou o crit\u00e9rio de desempate. Por fim, em quinto lugar, a americana Jordan Chiles com 13.666 pontos.<\/p>\n<p>Ana Maria Barbosu chegou a comemorar a conquista, mas acabou vendo sua medalha ir para outro pesco\u00e7o. A Federa\u00e7\u00e3o de Gin\u00e1stica dos Estados Unidos entrou com um pedido de revis\u00e3o da nota do solo da americana Jordan Chiles e a Federa\u00e7\u00e3o Internacional de Gin\u00e1stica (FIG) acatou o pedido. Com isso, a nota de Chiles foi revista, teve seu valor aumentado para 13.766 e a americana passou para o terceiro lugar da final.<\/p>\n<p>A cerim\u00f4nia do p\u00f3dio ocorreu normalmente e Rebeca Andrade, Simone Biles e Jordan Chiles foram coroadas como medalhistas ol\u00edmpicas. Alguns dias depois, no entanto, uma bomba: a Federa\u00e7\u00e3o Romena de Gin\u00e1stica questionou o recurso da Federa\u00e7\u00e3o de Gin\u00e1stica dos Estados Unidos que mudou a nota de Chiles.<\/p>\n<p>A Corte Arbitral do Esporte (CAS) anulou a revis\u00e3o da nota de Chiles, argumentando que o recurso foi feito fora do prazo. Na gin\u00e1stica, um recurso s\u00f3 pode ser pedido dentro do prazo de 1 minuto ap\u00f3s a publica\u00e7\u00e3o da nota. Com isso, a medalha de bronze foi retirada da ginasta americana e premiada para a romena Ana Maria Barbosu.<\/p>\n<p>A Federa\u00e7\u00e3o de Gin\u00e1stica dos Estados Unidos, no entanto, afirma ter provas de que o pedido de revis\u00e3o da nota de Chiles foi feito dentro do prazo de 1 minuto. Em nota \u00e0 imprensa, o \u00f3rg\u00e3o esportivo afirma ter enviado as evid\u00eancias para a Corte Arbitral do Esporte e espera que a decis\u00e3o seja revista.<\/p>\n<p>Para deixar a situa\u00e7\u00e3o ainda mais confusa, a Federa\u00e7\u00e3o Romena de Gin\u00e1stica tamb\u00e9m pediu a revis\u00e3o de uma puni\u00e7\u00e3o dada a ginasta romena Sabrina Maneca-Voinea, que ficou em quinto lugar. Nas redes sociais, v\u00eddeos que questionavam se Sabrina havia de fato pisado fora da linha, motivo que acarretou puni\u00e7\u00e3o, viralizaram. Caso a puni\u00e7\u00e3o fosse retirada, a ginasta ultrapassaria Ana Maria e Chiles e herdaria a medalha de bronze. O CAS, no entanto, n\u00e3o aceitou a revis\u00e3o.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2186564\/romenia-propoe-dividir-bronze-de-final-vencida-por-rebeca-nao-concordamos-em-tirar-a-medalha?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os Jogos Ol\u00edmpicos de Paris-2024 podem j\u00e1 ter acabado, mas o drama que cerca a<\/p>\n","protected":false},"author":0,"featured_media":187988,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-187987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187987"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187987\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/187988"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}