{"id":187976,"date":"2024-08-13T08:08:42","date_gmt":"2024-08-13T11:08:42","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/13\/entrevista-de-trump-a-musk-atrasa-e-bilionario-culpa-ataque\/"},"modified":"2024-08-13T08:08:42","modified_gmt":"2024-08-13T11:08:42","slug":"entrevista-de-trump-a-musk-atrasa-e-bilionario-culpa-ataque","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/13\/entrevista-de-trump-a-musk-atrasa-e-bilionario-culpa-ataque\/","title":{"rendered":"Entrevista de Trump a Musk atrasa, e bilion\u00e1rio culpa ataque"},"content":{"rendered":"<p>WASHINGTON, EUA (FOLHAPRESS) &#8211; Mais uma tentativa de fazer um grande evento pol\u00edtico no X (ex-Twitter) falhou, ao menos por alguns minutos. Uma entrevista de Donald Trump a Elon Musk, marcada para as 21h (hor\u00e1rio de Bras\u00edlia) atrasou por aproximadamente 40 minutos. Diversos usu\u00e1rios relataram que n\u00e3o conseguiam acessar a live.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>A Folha tentou entrar na conversa tanto pelo celular quanto pelo desktop por aproximadamente 30 minutos. Conseguiu acessar apenas \u00e0s 21h32, pelo celular, mas a entrevista n\u00e3o havia come\u00e7ado.<\/p>\n<p>Dono do X, Musk culpou um ataque massivo pela falha e disse que estava trabalhando para resolv\u00ea-la. Nas redes sociais, por\u00e9m, o problema remeteu imediatamente ao fracasso do lan\u00e7amento da candidatura do republicano Ron DeSantis \u00e0 vaga do partido na disputa pela Casa Branca, em maio do ano passado.<\/p>\n<p>A transmiss\u00e3o foi marcada por diversas falhas t\u00e9cnicas, ganhando ares de pren\u00fancio ao derretimento do governador da Fl\u00f3rida que se viu a partir de ent\u00e3o.<\/p>\n<p>Golpistas aproveitaram o interesse na conversa entre Musk e Trump. No YouTube, um canal que simula pertencer \u00e0 Tesla transmite um v\u00eddeo que se anuncia como a entrevista, mas na verdade parece ser uma vers\u00e3o do bilion\u00e1rio criada por intelig\u00eancia artificial em que ele pede que o espectador deposite uma criptomoeda em troca de receber o dobro do valor depositado.<\/p>\n<p>Por volta das 21h40, quase 10 mil pessoas assistiam o v\u00eddeo. Apoiadores do empres\u00e1rio, por sua vez, afirmam que ele e Musk &#8220;quebraram a internet&#8221;.<\/p>\n<p>Trump havia sido banido pelo Twitter em 2021, ap\u00f3s o 6 de Janeiro e antes de a plataforma ter sido adquirida por Musk. O empres\u00e1rio lan\u00e7ou sua pr\u00f3pria vers\u00e3o da rede social, chamada Truth, e se manteve nela mesmo ap\u00f3s o X autorizar novamente sua conta. A exce\u00e7\u00e3o havia sido o dia em que foi fichado na Ge\u00f3rgia, quando postou sua foto retirada pelas autoridades naquele dia.<\/p>\n<p>Nesta segunda, Trump voltou com for\u00e7a total \u00e0 sua conta no X, e fez diversas postagens. Em resposta, a campanha de Kamala Harris usou uma conta na Truth para tirar sarro da falha da conversa com Musk, repostando um coment\u00e1rio feito pelo empres\u00e1rio ap\u00f3s o fracasso de DeSantis.<\/p>\n<p>&#8220;Wow! O lan\u00e7amento no Twitter de DeSanctus \u00e9 um desastre! A campanha inteira dele ser\u00e1 um desastre. Prestem aten\u00e7\u00e3o!&#8221;, disse Trump na \u00e9poca.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Mundo<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/mundo\/2186591\/entrevista-de-trump-a-musk-atrasa-e-bilionario-culpa-ataque?utm_source=rss-mundo&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>WASHINGTON, EUA (FOLHAPRESS) &#8211; Mais uma tentativa de fazer um grande evento pol\u00edtico no X<\/p>\n","protected":false},"author":0,"featured_media":187977,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-187976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187976"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187976\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/187977"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}