{"id":187924,"date":"2024-08-12T22:09:02","date_gmt":"2024-08-13T01:09:02","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/12\/emmanuel-macron-festeja-sucesso-da-olimpiada-de-paris-duas-semanas-com-o-ar-mais-leve\/"},"modified":"2024-08-12T22:09:02","modified_gmt":"2024-08-13T01:09:02","slug":"emmanuel-macron-festeja-sucesso-da-olimpiada-de-paris-duas-semanas-com-o-ar-mais-leve","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/12\/emmanuel-macron-festeja-sucesso-da-olimpiada-de-paris-duas-semanas-com-o-ar-mais-leve\/","title":{"rendered":"Emmanuel Macron festeja sucesso da Olimp\u00edada de Paris: &#8216;Duas semanas com o ar mais leve&#8217;"},"content":{"rendered":"<p>Os Jogos Ol\u00edmpicos de Paris mostraram &#8220;a verdadeira cara da Fran\u00e7a&#8221;, afirmou nesta segunda-feira o presidente Emmanuel Macron, acrescentando que o evento encerrado no domingo que foi &#8220;um sucesso de seguran\u00e7a, organiza\u00e7\u00e3o e tamb\u00e9m no esporte e no respeito ao p\u00fablico&#8221;.<\/p>\n<p>&#8220;Vivemos duas semanas em um pa\u00eds com o sentimento de que o ar era mais leve. N\u00e3o queremos que a vida volte \u00e0 normalidade&#8221;, afirmou o presidente, admitindo que  j\u00e1 sentia saudades durante uma recep\u00e7\u00e3o nos jardins do Pal\u00e1cio do Eliseu, onde ele se reuniu com volunt\u00e1rios dos Jogos, policiais e bombardeiros.<\/p>\n<\/p>\n<p>&#8220;J\u00e1 n\u00e3o h\u00e1 mais provas para acompanhar nem o entusiasmo de cada manh\u00e3&#8221;, lamentou Macron, que destacou o excelente papel dos desportistas franceses, que terminaram na quinta coloca\u00e7\u00e3o no quadro de medalhas.<\/p>\n<\/p>\n<p>Nos Jogos de T\u00f3quio, em 2021, a delega\u00e7\u00e3o da Fran\u00e7a terminou com 33 p\u00f3dios. Em casa, os franceses conseguiram quase dobrar esse n\u00famero e conquistaram 64 medalhas (16 ouros, 26 pratas e 22 bronzes) no melhor desempenho do pa\u00eds na hist\u00f3ria dos Jogos Ol\u00edmpicos. <\/p>\n<\/p>\n<p>&#8220;Este esp\u00edrito ol\u00edmpico demonstra uma coisa muito simples. Unidos, somos imbat\u00edveis&#8221;, completou o presidente, que enfrenta um embate pol\u00edtico depois de sua decis\u00e3o de dissolver a Assembleia Nacional antes da Olimp\u00edada.<\/p>\n<\/p>\n<p>Macron agradeceu o trabalho de todos que colaboraram para o sucesso dos Jogos e enfatizou a participa\u00e7\u00e3o dos agentes de seguran\u00e7a. &#8220;Gra\u00e7as ao Servi\u00e7o Nacional de Seguran\u00e7a conseguimos evitar situa\u00e7\u00f5es de risco e identificar 5.6000 pessoas potencialmente perigosas.&#8221;<\/p>\n<\/p>\n<p>&#8220;Fizemos uma edi\u00e7\u00e3o sustent\u00e1vel e parit\u00e1ria. N\u00e3o poderia ser de outra maneira&#8221;, afirmou Emmanuel M\u00e1cron. &#8220;Deixamos o Sena em condi\u00e7\u00f5es para nata\u00e7\u00e3o e isso continuar\u00e1&#8221;, completou ele, ressaltando que ambientes culturais criados para a Olimp\u00edada tamb\u00e9m ser\u00e3o preservados.<\/p>\n<\/p>\n<p>&#8220;Vamos ver quem consegue repetir Jogos como estes&#8221;, provocou Macron, que pediu aos envolvidos nos Jogos Paral\u00edmpicos n\u00e3o &#8220;baixem a guarda at\u00e9 o dia 8 de setembro&#8221;, data da cerim\u00f4nia de encerramento do evento que come\u00e7a no dia 28 de agosto.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2186343\/emmanuel-macron-festeja-sucesso-da-olimpiada-de-paris-duas-semanas-com-o-ar-mais-leve?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os Jogos Ol\u00edmpicos de Paris mostraram &#8220;a verdadeira cara da Fran\u00e7a&#8221;, afirmou nesta segunda-feira o<\/p>\n","protected":false},"author":0,"featured_media":187925,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-187924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187924"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/187925"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}