{"id":187910,"date":"2024-08-12T20:08:23","date_gmt":"2024-08-12T23:08:23","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/12\/cidh-pede-que-venezeula-proteja-integridade-de-opositora-que-filmou-a-propria-detencao\/"},"modified":"2024-08-12T20:08:23","modified_gmt":"2024-08-12T23:08:23","slug":"cidh-pede-que-venezeula-proteja-integridade-de-opositora-que-filmou-a-propria-detencao","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/12\/cidh-pede-que-venezeula-proteja-integridade-de-opositora-que-filmou-a-propria-detencao\/","title":{"rendered":"CIDH pede que Venezeula proteja integridade de opositora que filmou a pr\u00f3pria deten\u00e7\u00e3o"},"content":{"rendered":"<p>DANIELA ARCANJO<br \/>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; A CIDH (Comiss\u00e3o Interamericana de Direitos Humanos) pediu que a Venezuela informe se Mar\u00eda Oropeza, opositora do regime de Nicol\u00e1s Maduro que filmou a pr\u00f3pria pris\u00e3o na semana passada, est\u00e1 sob cust\u00f3dia do Estado e adote medidas para proteg\u00ea-la.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>A resolu\u00e7\u00e3o, divulgada no \u00faltimo s\u00e1bado (10), responde a uma solicita\u00e7\u00e3o feita dois dias antes pelo Lola (Ladies of Liberty Alliance), grupo de mulheres de direita ao qual Oropeza pertence.<\/p>\n<p>A alian\u00e7a pediu que o \u00f3rg\u00e3o da OEA (Organiza\u00e7\u00e3o dos Estados Americanos) solicitasse medidas cautelares \u00e0 advogada -o mecanismo \u00e9 usado em situa\u00e7\u00f5es graves e urgentes para prevenir danos irrepar\u00e1veis a pessoas.<\/p>\n<p>Ap\u00f3s analisar as alega\u00e7\u00f5es do grupo, a entidade concluiu que as condi\u00e7\u00f5es em que Oropeza se encontra permitem a solicita\u00e7\u00e3o, uma vez que seu paradeiro \u00e9 desconhecido desde a ter\u00e7a-feira passada (6), quando foi detida.<\/p>\n<p>&#8220;A comiss\u00e3o lembra que, de acordo com os padr\u00f5es interamericanos, o Estado tem a obriga\u00e7\u00e3o de manter um registro atualizado de deten\u00e7\u00f5es, fornecer rapidamente informa\u00e7\u00f5es sobre o paradeiro da pessoa e seu estado de sa\u00fade e, caso ela esteja sob cust\u00f3dia do Estado, apresent\u00e1-la \u00e0 autoridade judicial competente dentro dos termos legais e respeitando em todos os momentos as garantias judiciais&#8221;, afirma o \u00f3rg\u00e3o na resolu\u00e7\u00e3o.<\/p>\n<p>A CIDH, ent\u00e3o, solicita que o regime adote as medidas necess\u00e1rias para proteger os direitos \u00e0 vida da advogada, informe se ela est\u00e1 sob cust\u00f3dia do Estado e esclare\u00e7a em quais circunst\u00e2ncias se encontra. A ditadura tem 15 dias, a partir da notifica\u00e7\u00e3o, para adotar as a\u00e7\u00f5es -o pa\u00eds, no entanto, nem sequer respondeu aos pedidos de esclarecimento feitos pelo \u00f3rg\u00e3o ap\u00f3s as alega\u00e7\u00f5es do Lola.<\/p>\n<p>&#8220;A comiss\u00e3o lamenta a falta de resposta do Estado da Venezuela ao pedido feito, apesar da gravidade das alega\u00e7\u00f5es manifestadas. Embora isso por si s\u00f3 n\u00e3o seja suficiente para justificar a concess\u00e3o de uma medida cautelar, impede que a Comiss\u00e3o tenha observa\u00e7\u00f5es do Estado e, portanto, analise se as alega\u00e7\u00f5es dos solicitantes s\u00e3o desvirtuadas ou n\u00e3o&#8221;, afirmou a entidade na resolu\u00e7\u00e3o.<\/p>\n<p>Essa n\u00e3o \u00e9 a primeira vez que o regime ignora a entidade. A Venezuela tampouco se manifestou, por exemplo, quando a comiss\u00e3o pediu informa\u00e7\u00f5es antes de conceder medidas cautelares a Joel Antonio Garc\u00eda Hern\u00e1ndez em maio deste ano -o ativista de direitos humanos havia sofrido amea\u00e7as por suas den\u00fancias meses antes.<\/p>\n<p>Segundo o bra\u00e7o do Lola no Brasil, advogados e organiza\u00e7\u00f5es de direitos humanos venezuelanos teriam confirmado que Oropeza est\u00e1 no Helicoide, pris\u00e3o em Caracas para onde normalmente s\u00e3o levados presos pol\u00edticos do regime. A informa\u00e7\u00e3o, no entanto, n\u00e3o \u00e9 oficial.<\/p>\n<p>Chefe regional da campanha da oposi\u00e7\u00e3o, a advogada ganhou aten\u00e7\u00e3o internacional na noite da ter\u00e7a-feira passada, quando agentes da DGCIM (Dire\u00e7\u00e3o de Contraintelig\u00eancia Militar) entraram na casa em que ela estava e a levaram mesmo sem mandado de pris\u00e3o, de acordo com a oposi\u00e7\u00e3o.<\/p>\n<p>A a\u00e7\u00e3o foi registrada pela pr\u00f3pria Oropeza, que transmitiu o v\u00eddeo em seu perfil no Instagram. A grava\u00e7\u00e3o viralizou e fez sua pris\u00e3o se destacar entre as muitas que est\u00e3o ocorrendo no pa\u00eds desde que Maduro foi declarado reeleito h\u00e1 duas semanas, ap\u00f3s uma apura\u00e7\u00e3o contestada.<\/p>\n<p>De acordo com a ONG Foro Penal, 1.305 pessoas foram detidas desde o dia seguinte \u00e0 vota\u00e7\u00e3o at\u00e9 a manh\u00e3 deste domingo (11) -segundo Maduro, as pris\u00f5es passam de 2.200. Antes mesmo do pleito, a organiza\u00e7\u00e3o j\u00e1 havia verificado a captura de mais de 100 pessoas ligadas \u00e0 oposi\u00e7\u00e3o.<\/p>\n<p>De acordo com a CIDH, o Lola anexou no pedido um v\u00eddeo no qual a m\u00e3e de Oropeza diz ter buscado a filha em todos os centros de deten\u00e7\u00e3o em Guanare, onde a ativista foi detida, e Acarigua, outra cidade da regi\u00e3o, mas n\u00e3o conseguiu informa\u00e7\u00f5es.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Mundo<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/mundo\/2186340\/cidh-pede-que-venezeula-proteja-integridade-de-opositora-que-filmou-a-propria-detencao?utm_source=rss-mundo&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DANIELA ARCANJOS\u00c3O PAULO, SP (FOLHAPRESS) &#8211; A CIDH (Comiss\u00e3o Interamericana de Direitos Humanos) pediu que<\/p>\n","protected":false},"author":0,"featured_media":187911,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-187910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187910"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187910\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/187911"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}