{"id":187862,"date":"2024-08-12T15:08:45","date_gmt":"2024-08-12T18:08:45","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/12\/famosos-que-apoiam-kamala-harris-para-presidente-dos-estados-unidos\/"},"modified":"2024-08-12T15:08:45","modified_gmt":"2024-08-12T18:08:45","slug":"famosos-que-apoiam-kamala-harris-para-presidente-dos-estados-unidos","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/12\/famosos-que-apoiam-kamala-harris-para-presidente-dos-estados-unidos\/","title":{"rendered":"Famosos que apoiam Kamala Harris para presidente dos Estados Unidos"},"content":{"rendered":"<p>Em 21 de julho de 2024, o presidente Joe Biden anunciou que estava desistindo da corrida presidencial de 2024. A sa\u00edda de Biden tamb\u00e9m foi marcada pelo apoio \u00e0 atual vice-presidente, <a href=\"https:\/\/br.starsinsider.com\/celebridades\/452561\/a-surpreendente-conexao-entre-o-brasil-e-kamala-harris-candidata-a-presidente-dos-eua\" target=\"_blank\" rel=\"noopener\">Kamala Harris<\/a>, como a pessoa certa para o cargo m\u00e1ximo do pa\u00eds. Desde o an\u00fancio, muitos famosos se apresentaram em defesa de Kamala Harris (e at\u00e9 j\u00e1 fazem campanha) para a pr\u00f3xima presidente dos Estados Unidos.<\/p>\n<p>De m\u00fasicos a estrelas de Hollywood, voc\u00ea conhecer\u00e1 as celebridades que est\u00e3o apoiando Kamala Harris para presidente. Clique a seguir na galeria!<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/2186220\/famosos-que-apoiam-kamala-harris-para-presidente-dos-estados-unidos?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em 21 de julho de 2024, o presidente Joe Biden anunciou que estava desistindo da<\/p>\n","protected":false},"author":0,"featured_media":187863,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-187862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187862"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187862\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/187863"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}