{"id":187812,"date":"2024-08-12T10:08:26","date_gmt":"2024-08-12T13:08:26","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/12\/apresentador-se-envolve-em-acidente-com-caminhao-e-quebra-o-pescoco\/"},"modified":"2024-08-12T10:08:26","modified_gmt":"2024-08-12T13:08:26","slug":"apresentador-se-envolve-em-acidente-com-caminhao-e-quebra-o-pescoco","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/12\/apresentador-se-envolve-em-acidente-com-caminhao-e-quebra-o-pescoco\/","title":{"rendered":"Apresentador se envolve em acidente com caminh\u00e3o e quebra o pesco\u00e7o"},"content":{"rendered":"<p>O apresentador do reality show Catfish, Nev Schulman, passou por momentos de terror na \u00faltima [dia da semana]. Em um passeio de bicicleta pela cidade de Nova York, o apresentador se envolveu em um grave acidente ao colidir com um caminh\u00e3o. A for\u00e7a do impacto causou uma fratura no pesco\u00e7o de Schulman, deixando f\u00e3s e amigos preocupados com seu estado de sa\u00fade.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>Em um post emocionante nas redes sociais, Nev compartilhou a not\u00edcia com seus seguidores e agradeceu pelo apoio recebido. &#8220;Tenho sorte de estar aqui, vivo, de p\u00e9 e abra\u00e7ando minha fam\u00edlia&#8221;, escreveu o apresentador, que passou por uma cirurgia e est\u00e1 se recuperando no hospital. Apesar do susto, os m\u00e9dicos informaram que a fratura n\u00e3o afetou sua medula espinhal e que ele ter\u00e1 uma recupera\u00e7\u00e3o completa.<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/C-gJdX5PLCA\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div><a href=\"https:\/\/www.instagram.com\/p\/C-gJdX5PLCA\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\"><\/p>\n<div>\n<div>\u00a0<\/div>\n<div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<\/div>\n<\/div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>\n<div>Ver essa foto no Instagram<\/div>\n<\/div>\n<div>\u00a0<\/div>\n<div>\n<div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<\/div>\n<div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<\/div>\n<div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<\/div>\n<p><\/a><\/p>\n<p><a href=\"https:\/\/www.instagram.com\/p\/C-gJdX5PLCA\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Uma publica\u00e7\u00e3o compartilhada por N\u0113v Schulman (@nevschulman)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p>&#8220;Estou come\u00e7ando a entender o significado de gratid\u00e3o. Pelas coisas grandes e pequenas antes do acidente, e agora por tudo o que est\u00e1 acontecendo&#8221;, completou Nev, demonstrando positividade e determina\u00e7\u00e3o para superar esse desafio.<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/2186148\/biografa-da-familia-real-diz-que-kate-middleton-deve-deixar-a-inglaterra\" target=\"_blank\" rel=\"noopener noreferrer\">Bi\u00f3grafa da Fam\u00edlia Real diz que Kate Middleton deve deixar a Inglaterra<\/a><\/p>\n<p>\u00a0<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/2186239\/apresentador-se-envolve-em-acidente-com-caminhao-e-quebra-o-pescoco?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O apresentador do reality show Catfish, Nev Schulman, passou por momentos de terror na \u00faltima<\/p>\n","protected":false},"author":0,"featured_media":187813,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-187812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187812"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187812\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/187813"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}