{"id":187772,"date":"2024-08-12T06:08:30","date_gmt":"2024-08-12T09:08:30","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/12\/comissaria-manda-recado-ao-marido-instantes-antes-da-queda-do-aviao\/"},"modified":"2024-08-12T06:08:30","modified_gmt":"2024-08-12T09:08:30","slug":"comissaria-manda-recado-ao-marido-instantes-antes-da-queda-do-aviao","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/12\/comissaria-manda-recado-ao-marido-instantes-antes-da-queda-do-aviao\/","title":{"rendered":"Comiss\u00e1ria manda recado ao marido instantes antes da queda do avi\u00e3o"},"content":{"rendered":"<p>Familiares de D\u00e9bora Soper \u00c1vila, comiss\u00e1ria de bordo da Voepass, perceberam que a \u00faltima mensagem enviada por ela ao marido ocorreu no exato momento em que o avi\u00e3o ATR-72 come\u00e7ou a perder altitude e caiu em Vinhedo, S\u00e3o Paulo. D\u00e9bora, de 28 anos, estava a bordo do voo Voepass 2283, que partiu de Cascavel e tinha como destino final Guarulhos.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>O irm\u00e3o de D\u00e9bora, Luigi Soper, relatou emocionado que a mensagem foi recebida pelo marido dela \u00e0s 13h20, e que \u00e0s 13h22 o avi\u00e3o desapareceu do radar, segundo informa\u00e7\u00f5es da For\u00e7a A\u00e9rea Brasileira. \u201cMeu cunhado recebeu uma mensagem dela por volta das 13h20 e depois, vendo as reportagens, pelo hor\u00e1rio da queda do voo, ela s\u00f3 conseguiu mandar mensagem para ele dizendo \u2018n\u00e3o esquece que te amo\u2019.<\/p>\n<p>Em entrevista, Luigi, aos prantos, disse que se tivesse tempo, D\u00e9bora teria enviado mensagens de despedida tamb\u00e9m para ele e para seus pais. Ele destacou a paix\u00e3o da irm\u00e3 pela avia\u00e7\u00e3o, lembrando que trabalhar como comiss\u00e1ria de bordo era a realiza\u00e7\u00e3o de um sonho para ela.<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/ultima-hora\/2185723\/advogada-que-falava-de-acoes-contra-empresas-aereas-e-uma-das-vitimas-da-queda-do-aviao\" target=\"_blank\" rel=\"noopener noreferrer\">Advogada morta em queda de avi\u00e3o moveu mais de 90 a\u00e7\u00f5es contra a\u00e9reas<\/a><\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/brasil\/2185743\/fisiculturista-morta-em-queda-de-aviao-participou-de-primeiro-campeonato-internacional-em-abril\" target=\"_blank\" rel=\"noopener noreferrer\">Fisiculturista morta em queda de avi\u00e3o participou de primeiro campeonato internacional em abril<\/a><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Brasil<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/brasil\/2186142\/comissaria-manda-recado-ao-marido-instantes-antes-da-queda-do-aviao?utm_source=rss-brasil&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Familiares de D\u00e9bora Soper \u00c1vila, comiss\u00e1ria de bordo da Voepass, perceberam que a \u00faltima mensagem<\/p>\n","protected":false},"author":0,"featured_media":187773,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-187772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187772"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187772\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/187773"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}