{"id":187694,"date":"2024-08-11T07:08:19","date_gmt":"2024-08-11T10:08:19","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/11\/celine-dion-critica-uso-de-uma-das-suas-musicas-em-comicio-de-trump\/"},"modified":"2024-08-11T07:08:19","modified_gmt":"2024-08-11T10:08:19","slug":"celine-dion-critica-uso-de-uma-das-suas-musicas-em-comicio-de-trump","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/11\/celine-dion-critica-uso-de-uma-das-suas-musicas-em-comicio-de-trump\/","title":{"rendered":"C\u00e9line Dion critica uso de uma das suas m\u00fasicas em com\u00edcio de Trump"},"content":{"rendered":"<p>A m\u00fasica &#8216;My Heart Will Go On&#8217; (da trilha sonora de &#8216;Titanic&#8217;), de C\u00e9line Dion, foi ouvido num com\u00edcio da campanha Donald Trump e JD Vance (a escolha de Trump para vice-presidente) em Bozeman, Montana, no dia 9 de agosto, segundo a NBC News.\u00a0<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>Durante o com\u00edcio foi exibido um v\u00eddeo da artista cantando a famosa m\u00fasica, de 1997, e tudo sem o consentimento de C\u00e9line Dion.\u00a0<\/p>\n<p>Este s\u00e1bado, a equipe da cantora emitiu um comunicado no X (antigo Twitter) onde se manifesta contra o uso indevido da m\u00fasica.\u00a0<\/p>\n<p>&#8220;Hoje, a equipe e gest\u00e3o da C\u00e9line Dion e a sua gravadora, Sony Music Entertainment Canada Inc., tomaram conhecimento do uso n\u00e3o autorizado do v\u00eddeo, grava\u00e7\u00e3o, performance musical e imagem de C\u00e9line Dion cantando &#8216;My Heart Will Go On&#8217; num com\u00edcio da campanha de Donald Trump\/JD Vance em Montana. De forma alguma esse uso \u00e9 autorizado, e a C\u00e9line Dion n\u00e3o apoia esse ou qualquer uso semelhante. E, a s\u00e9rio, aquela m\u00fasica?&#8221;, pode se ler na nota.\u00a0<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Today, Celine Dion\u2019s management team and her record label, Sony Music Entertainment Canada Inc., became aware of the unauthorized usage of the video, recording, musical performance, and likeness of Celine Dion singing \u201cMy Heart Will Go On\u201d at a Donald Trump \/ JD Vance campaign\u2026 <a href=\"https:\/\/t.co\/28CYLFvgER\">pic.twitter.com\/28CYLFvgER<\/a><\/p>\n<p>\u2014 Celine Dion (@celinedion) <a href=\"https:\/\/twitter.com\/celinedion\/status\/1822347994223587506?ref_src=twsrc%5Etfw\">August 10, 2024<\/a><\/p><\/blockquote>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/2185785\/do-amor-a-furia-como-brad-pitt-e-angelina-jolie-foram-do-romance-perfeito-ao-divorcio\" target=\"_blank\" rel=\"noopener noreferrer\">Do amor \u00e0 f\u00faria: Como Brad Pitt e Angelina Jolie foram do romance perfeito ao div\u00f3rcio<\/a><\/p>\n<p>\u00a0<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/2185925\/celine-dion-critica-uso-de-uma-das-suas-musicas-em-comicio-de-trump?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A m\u00fasica &#8216;My Heart Will Go On&#8217; (da trilha sonora de &#8216;Titanic&#8217;), de C\u00e9line Dion,<\/p>\n","protected":false},"author":0,"featured_media":187695,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-187694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187694"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/187695"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}