{"id":187648,"date":"2024-08-10T13:08:26","date_gmt":"2024-08-10T16:08:26","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/10\/fiuk-beija-lumena-e-comenta-status-de-relacionamento\/"},"modified":"2024-08-10T13:08:26","modified_gmt":"2024-08-10T16:08:26","slug":"fiuk-beija-lumena-e-comenta-status-de-relacionamento","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/10\/fiuk-beija-lumena-e-comenta-status-de-relacionamento\/","title":{"rendered":"Fiuk beija Lumena e comenta status de relacionamento"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; Fiuk beijou Lumena durante uma festa no rancho de Carlinhos Maia na \u00faltima quinta-feira (8) e comentou se est\u00e1 apaixonado.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>O filho de F\u00e1bio Jr usou seus Stories na tarde desta sexta (9) e brincou sobre estar apaixonado. &#8220;Acabei de ler algu\u00e9m dizer &#8216;Fiuk, voc\u00ea est\u00e1 apaixonado? Apareceu cantando Djavan&#8217;&#8221;.<\/p>\n<p>O cantor declarou. &#8220;E pra ouvir Djavan tem que estar apaixonado? T\u00e1 bom, eu t\u00f4 apaixonado&#8221;.<\/p>\n<p>Fiuk completou. &#8220;T\u00f4 apaixonado pela vida, pela solitude. Olha que loucura!&#8221;.<\/p>\n<p>O beijo entre Fiuk e Lumena foi compartilhado nas redes sociais de Carlinhos Maia. A dupla conversa e \u00e9 incentivada pelos presentes. Ap\u00f3s os gritos dos amigos, a dupla se beija.<\/p>\n<p>Vale destacar que os dois se conheceram e se tornaram amigos ap\u00f3s a conviv\u00eancia no BBB 21. Ap\u00f3s o reality, eles mantiveram a amizade.<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2185574\/sikera-jr-ganha-primeira-batalha-contra-a-redetv-em-processo-na-justica\" target=\"_blank\" rel=\"noopener noreferrer\">Sik\u00eara Jr ganha primeira batalha contra a RedeTV! em processo na Justi\u00e7a<\/a><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2185602\/fiuk-beija-lumena-e-comenta-status-de-relacionamento?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; Fiuk beijou Lumena durante uma festa no rancho de Carlinhos<\/p>\n","protected":false},"author":0,"featured_media":187649,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-187648","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187648"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187648\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/187649"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}