{"id":187501,"date":"2024-08-09T13:08:28","date_gmt":"2024-08-09T16:08:28","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/09\/jennifer-garner-fica-presa-em-elevador-e-mostra-tudo-em-videos-veja\/"},"modified":"2024-08-09T13:08:28","modified_gmt":"2024-08-09T16:08:28","slug":"jennifer-garner-fica-presa-em-elevador-e-mostra-tudo-em-videos-veja","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/09\/jennifer-garner-fica-presa-em-elevador-e-mostra-tudo-em-videos-veja\/","title":{"rendered":"Jennifer Garner fica presa em elevador e mostra tudo em v\u00eddeos; veja"},"content":{"rendered":"<p>Jennifer Garner teve uma experi\u00eancia memor\u00e1vel durante sua estreia na Comic-Con, quando acabou ficando presa em um elevador por uma hora e 12 minutos.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>A atriz compartilhou detalhes dessa experi\u00eancia em sua p\u00e1gina no Instagram, onde publicou v\u00e1rios v\u00eddeos relatando o que ocorreu enquanto estava confinada no elevador.<\/p>\n<p>Confira todos os v\u00eddeos que Jennifer Garner postou em sua rede social na galeria abaixo.<br \/>\u00a0<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2185109\/aos-49-anos-buchecha-celebra-primeira-graduacao\" target=\"_blank\" rel=\"noopener noreferrer\">Aos 49 anos, Buchecha celebra primeira gradua\u00e7\u00e3o<\/a><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/2185240\/jennifer-garner-fica-presa-em-elevador-e-mostra-tudo-em-videos-veja?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jennifer Garner teve uma experi\u00eancia memor\u00e1vel durante sua estreia na Comic-Con, quando acabou ficando presa<\/p>\n","protected":false},"author":0,"featured_media":187502,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-187501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187501"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187501\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/187502"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}