{"id":187393,"date":"2024-08-08T17:08:24","date_gmt":"2024-08-08T20:08:24","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/08\/joao-siemsen-e-marina-arndt-terminam-em-9o-lugar-na-nacra-17-da-vela-na-olimpiada-de-paris\/"},"modified":"2024-08-08T17:08:24","modified_gmt":"2024-08-08T20:08:24","slug":"joao-siemsen-e-marina-arndt-terminam-em-9o-lugar-na-nacra-17-da-vela-na-olimpiada-de-paris","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/08\/joao-siemsen-e-marina-arndt-terminam-em-9o-lugar-na-nacra-17-da-vela-na-olimpiada-de-paris\/","title":{"rendered":"Jo\u00e3o Siemsen e Marina Arndt terminam em 9\u00ba lugar na Nacra 17 da vela na Olimp\u00edada de Paris"},"content":{"rendered":"<p>J\u00e1 sem chances de p\u00f3dio, os brasileiros Jo\u00e3o Siemsen e Marina Arndt terminaram na terceira coloca\u00e7\u00e3o a medal race da Nacra 17 (multicasco misto) da vela nesta quinta-feira na Marina de Marselha e terminaram os Jogos Ol\u00edmpicos de Paris-2024 na nona coloca\u00e7\u00e3o.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>A medal race, \u00faltima regata da disputa, reuniu os 10 mais bem classificados ap\u00f3s 12 etapas. Os brasileiros iniciaram a regata na 10\u00aa posi\u00e7\u00e3o na classifica\u00e7\u00e3o geral, mas com o resultado desta quinta conseguiram superar Emil Jarudd e Hanna Jonsson, da Su\u00e9cia. Jo\u00e3o Siemsen e Marina Arndt terminaram com 115 pontos perdidos contra 118 dos suecos. O ouro ficou com a It\u00e1lia (31), a prata com a Argentina (55) e o bronze com a Nova Zel\u00e2ndia (63).<\/p>\n<p>Outra classe com medal race na manh\u00e3 desta quinta foi a dinghy misto (bote). Henrique Haddad e Isabel Swan tamb\u00e9m j\u00e1 n\u00e3o tinham possibilidade de conquistar medalha e terminaram na d\u00e9cima e \u00faltima coloca\u00e7\u00e3o. Na classifica\u00e7\u00e3o final, eles tamb\u00e9m ficaram no d\u00e9cimo lugar.<\/p>\n<p>Aos 31 anos, Isabel Swan disputou sua terceira Olimp\u00edada. Ela conquistou a medalha de bronze no dinghy feminino, ao lado de Fernanda Oliveira. Nos Jogos do Rio-2016, Isabel Swan tamb\u00e9m terminou na 10\u00aa coloca\u00e7\u00e3o da Nacra 17 (multicasco misto), com Samuel Albrecht.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2184664\/joao-siemsen-e-marina-arndt-terminam-em-9-lugar-na-nacra-17-da-vela-na-olimpiada-de-paris?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 sem chances de p\u00f3dio, os brasileiros Jo\u00e3o Siemsen e Marina Arndt terminaram na terceira<\/p>\n","protected":false},"author":0,"featured_media":187394,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-187393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187393"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/187394"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}