{"id":187278,"date":"2024-08-07T19:08:19","date_gmt":"2024-08-07T22:08:19","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/07\/daisy-ridley-diz-ter-sido-diagnosticada-com-doenca-autoimune\/"},"modified":"2024-08-07T19:08:19","modified_gmt":"2024-08-07T22:08:19","slug":"daisy-ridley-diz-ter-sido-diagnosticada-com-doenca-autoimune","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/07\/daisy-ridley-diz-ter-sido-diagnosticada-com-doenca-autoimune\/","title":{"rendered":"Daisy Ridley diz ter sido diagnosticada com doen\u00e7a autoimune"},"content":{"rendered":"<p>(FOLHAPRESS) &#8211; Estrela da nova trilogia de &#8220;Star Wars&#8221;, Daisy Ridley, 32, descobriu ter uma doen\u00e7a autoimune em 2023. O diagn\u00f3stico veio ap\u00f3s consultar um endocrinologista: s\u00edndrome Graves ou Basedow-Graves, um tipo de hipertireoidismo que produz horm\u00f4nio em excesso. &#8220;Foi engra\u00e7ado, pensei que estava com raiva do mundo, mas acontece que tudo funciona t\u00e3o r\u00e1pido que n\u00e3o d\u00e1 para relaxar&#8221;, explicou atriz.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>Daisy soube do dist\u00farbio ap\u00f3s sentir ondas de calor, fadiga, batimentos card\u00edacos acelerados, perda de peso e tremores nas m\u00e3os. &#8220;Pensei: &#8216;Acabei de desempenhar um papel muito estressante, provavelmente \u00e9 por isso que me sinto mal'&#8221;, contou ela lembrando que tinha acabado de filmar o longa &#8220;Magpie&#8221;.<\/p>\n<p>Embora a doen\u00e7a de Graves n\u00e3o tenha cura, Daisy Ridley toma rem\u00e9dios diariamente, o que a faz se sentir melhor, e ela teve que se tornar mais rigorosa com sua dieta e exerc\u00edcios. &#8220;N\u00e3o sou muito r\u00edgida quanto a isso, mas no geral cortar o gl\u00faten me fez sentir melhor&#8221;, disse ela que \u00e9 vegana.<\/p>\n<p>Ridley tamb\u00e9m afirmou em uma entrevista para a &#8220;Women&#8217;s Health&#8221; ter inclu\u00eddo em sua rotina atividades como saunas infravermelhas, crioterapia, massagens e acupuntura. Ela tamb\u00e9m comentou sofrer de endometriose e s\u00edndrome dos ov\u00e1rios polic\u00edsticos. &#8220;Estamos todos lutando contra algo que os outros n\u00e3o conseguem ver, e conhecer as pessoas com gentileza, gra\u00e7a e carinho \u00e9 o m\u00e1ximo que podemos fazer&#8221;, disse atriz brit\u00e2nica sobre seus problemas de sa\u00fade.<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/ultima-hora\/2184045\/brasil-ultrapassa-marca-de-5-mil-mortes-por-dengue\" target=\"_blank\" rel=\"noopener noreferrer\">Brasil ultrapassa marca de 5 mil mortes por dengue<\/a><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2184221\/daisy-ridley-diz-ter-sido-diagnosticada-com-doenca-autoimune?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(FOLHAPRESS) &#8211; Estrela da nova trilogia de &#8220;Star Wars&#8221;, Daisy Ridley, 32, descobriu ter uma<\/p>\n","protected":false},"author":0,"featured_media":187279,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-187278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187278"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187278\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/187279"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}