{"id":187256,"date":"2024-08-07T17:08:16","date_gmt":"2024-08-07T20:08:16","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/07\/fluxo-cambial-total-em-2024-ate-2-de-agosto-e-positivo-em-us-13716-bi-mostra-bc\/"},"modified":"2024-08-07T17:08:16","modified_gmt":"2024-08-07T20:08:16","slug":"fluxo-cambial-total-em-2024-ate-2-de-agosto-e-positivo-em-us-13716-bi-mostra-bc","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/07\/fluxo-cambial-total-em-2024-ate-2-de-agosto-e-positivo-em-us-13716-bi-mostra-bc\/","title":{"rendered":"Fluxo cambial total em 2024, at\u00e9 2 de agosto, \u00e9 positivo em US$ 13,716 bi, mostra BC"},"content":{"rendered":"<p>O fluxo cambial do Brasil \u00e9 positivo em US$ 13,716 bilh\u00f5es este ano, at\u00e9 a \u00faltima sexta-feira, 2, de acordo com dados preliminares do Banco Central divulgados nesta quarta-feira, 7. Em 2023, houve entrada l\u00edquida de US$ 11,491 bilh\u00f5es.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>O canal financeiro acumula sa\u00edda l\u00edquida de US$ 43,672 bilh\u00f5es, com aportes de US$ 347,219 bilh\u00f5es e retiradas de US$ 390,891 bilh\u00f5es.<\/p>\n<p>O segmento re\u00fane os investimentos estrangeiros diretos e em carteira, remessas de lucro e pagamento de juros, entre outras opera\u00e7\u00f5es.<\/p>\n<p>O saldo do com\u00e9rcio exterior \u00e9 positivo em US$ 57,388 bilh\u00f5es em 2024, com importa\u00e7\u00f5es de US$ 128,476 bilh\u00f5es e exporta\u00e7\u00f5es de US$ 185,864 bilh\u00f5es.<\/p>\n<p>Nas exporta\u00e7\u00f5es, est\u00e3o inclu\u00eddos US$ 20,375 bilh\u00f5es em adiantamento de contrato de c\u00e2mbio (ACC), US$ 43,861 bilh\u00f5es em pagamento antecipado (PA) e US$ 121,628 bilh\u00f5es em outras entradas.<\/p>\n<p><strong>Mensal<\/strong><\/p>\n<p>Segundo dados preliminares do BC, o fluxo cambial do Brasil ficou positivo em US$ 1,743 bilh\u00e3o em julho. As estat\u00edsticas finais ser\u00e3o divulgadas at\u00e9 a terceira semana deste m\u00eas. Em junho, o fluxo foi positivo em US$ 5,603 bilh\u00f5es.<\/p>\n<p>O canal financeiro teve sa\u00edda l\u00edquida de US$ 3,302 bilh\u00f5es, resultado de US$ 49,380 bilh\u00f5es em compras e US$ 52,682 bilh\u00f5es em vendas.<\/p>\n<p>O saldo preliminar do com\u00e9rcio exterior foi positivo em US$ 5,046 bilh\u00f5es, com US$ 20,460 bilh\u00f5es em importa\u00e7\u00f5es e US$ 25,506 bilh\u00f5es em exporta\u00e7\u00f5es. Nas exporta\u00e7\u00f5es, est\u00e3o inclu\u00eddos US$ 2,669 bilh\u00f5es em ACC, US$ 5,803 bilh\u00f5es em pagamento antecipado e US$ 17,034 bilh\u00f5es em outras entradas.<\/p>\n<p>Nos dias 1\u00ba e 2 de agosto, o fluxo cambial total foi positivo em US$ 534 milh\u00f5es. O canal financeiro teve sa\u00edda l\u00edquida de US$ 790 milh\u00f5es, com US$ 3,608 bilh\u00f5es em compras e US$ 4,398 bilh\u00f5es em vendas.<\/p>\n<p>O saldo do com\u00e9rcio exterior foi positivo em US$ 1,324 bilh\u00e3o, com US$ 1,224 bilh\u00e3o em importa\u00e7\u00f5es e US$ 2,547 bilh\u00f5es em exporta\u00e7\u00f5es &#8211; incluindo US$ 254 milh\u00f5es em ACC, US$ 544 milh\u00f5es em PA e US$ 1,749 bilh\u00e3o em outras entradas.<\/p>\n<p><strong>Semanal<\/strong><\/p>\n<p>Conforme os dados preliminares do BC, o fluxo cambial do Brasil ficou positivo em US$ 1,341 bilh\u00e3o na semana passada.<\/p>\n<p>O canal financeiro teve sa\u00edda l\u00edquida de US$ 2,083 bilh\u00f5es entre os dias 29 de julho e 2 de agosto, com compras no valor de US$ 9,681 bilh\u00f5es e vendas de US$ 11,764 bilh\u00f5es.<\/p>\n<p>O saldo do com\u00e9rcio exterior foi positivo em US$ 3,424 bilh\u00f5es, com US$ 3,843 bilh\u00f5es em importa\u00e7\u00f5es e US$ 7,267 bilh\u00f5es em exporta\u00e7\u00f5es. Nas exporta\u00e7\u00f5es, est\u00e3o inclu\u00eddos US$ 580 milh\u00f5es em adiantamento de contrato de c\u00e2mbio, US$ 1,635 bilh\u00e3o em pagamento antecipado e US$ 5,052 bilh\u00f5es em outras entradas.<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/2184205\/confira-quanto-o-trabalhador-vai-receber-de-lucro-do-fgts-em-2024\" target=\"_blank\" rel=\"noopener noreferrer\">Confira quanto o trabalhador vai receber de lucro do FGTS em 2024<\/a><\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/2184241\/fluxo-cambial-total-em-2024-ate-2-de-agosto-e-positivo-em-us-13-716-bi-mostra-bc?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O fluxo cambial do Brasil \u00e9 positivo em US$ 13,716 bilh\u00f5es este ano, at\u00e9 a<\/p>\n","protected":false},"author":0,"featured_media":187257,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-187256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187256"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187256\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/187257"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}