{"id":187043,"date":"2024-08-06T09:08:23","date_gmt":"2024-08-06T12:08:23","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/06\/apos-polemica-dandara-mariana-homenageia-rebeca-pelo-ouro\/"},"modified":"2024-08-06T09:08:23","modified_gmt":"2024-08-06T12:08:23","slug":"apos-polemica-dandara-mariana-homenageia-rebeca-pelo-ouro","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/06\/apos-polemica-dandara-mariana-homenageia-rebeca-pelo-ouro\/","title":{"rendered":"Ap\u00f3s pol\u00eamica, Dandara Mariana homenageia Rebeca pelo ouro"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Dandara Mariana se redimiu com os brasileiros e decidiu parabenizar Rebeca Andrade pela medalha de ouro nesta segunda-feira (5). Em seu perfil no Instagram, a atriz tentou desfazer &#8220;ru\u00eddos de comunica\u00e7\u00e3o&#8221; e disse que admira a ginasta h\u00e1 muito tempo.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>Na \u00faltima sexta-feira (2), Dandara elogiou Simone Biles e deixou de lado a brasileira, medalha de prata na prova anterior. A atitude foi apontada como revanchismo por internautas, j\u00e1 que, em 2021, Rebeca deu uma nota baixa para Dandara na Dan\u00e7a dos Famosos.<\/p>\n<p>&#8220;Evitando ru\u00eddos de comunica\u00e7\u00e3o: Parab\u00e9ns, Rebeca Andrade, mais uma vez! Somos ouro. Voc\u00ea \u00e9 inspira\u00e7\u00e3o para muitos brasileiros! E minha admira\u00e7\u00e3o por voc\u00ea n\u00e3o \u00e9 de hoje&#8221;, escreveu a atriz.<\/p>\n<p>Na ocasi\u00e3o, a atleta comp\u00f4s o j\u00fari e, ao avaliar a apresenta\u00e7\u00e3o da atriz, deu nota 9,9, ao contr\u00e1rio do 10 dado pelos outros jurados.<\/p>\n<p>&#8220;Que mico a atriz Dandara Mariana comemorando a vit\u00f3ria da Biles e ignorando a conquista da Rebeca s\u00f3 porque ganhou um 9,9 da nossa diva em 2021&#8221;, opinou um internauta.<\/p>\n<p>&#8220;At\u00e9 a Viola Davis comentando e reconhecendo o gigantismo da Rebeca e advinha quem fica lambendo a estadunidense? Dandara Mariana por ter recebido 9.9 na Dan\u00e7a dos Famosos&#8221;, escreveu outra usu\u00e1ria.<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2183236\/anitta-vibra-com-musica-na-coreografia-campea-olimpica-de-rebeca-andrade\" target=\"_blank\" rel=\"noopener noreferrer\">Anitta vibra com m\u00fasica na coreografia campe\u00e3 ol\u00edmpica de Rebeca Andrade<\/a><\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/paris-2024\/2183181\/4-nao-e-so-sobre-vencer-a-simone-e-sobre-vencer-a-mim-mesma-diz-rebeca-sobre-forca-mental\" target=\"_blank\" rel=\"noopener noreferrer\">&#8216;N\u00e3o \u00e9 s\u00f3 sobre vencer a Simone, \u00e9 sobre vencer a mim mesma&#8217;, diz Rebeca sobre for\u00e7a mental<\/a><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2183383\/apos-polemica-dandara-mariana-homenageia-rebeca-pelo-ouro?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Dandara Mariana se redimiu com os brasileiros e decidiu parabenizar<\/p>\n","protected":false},"author":0,"featured_media":187044,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-187043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187043"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187043\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/187044"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}