{"id":186974,"date":"2024-08-05T21:08:28","date_gmt":"2024-08-06T00:08:28","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/05\/globo-promove-apresentadora-local-e-fecha-com-silvero-pereira-para-estrela-da-casa\/"},"modified":"2024-08-05T21:08:28","modified_gmt":"2024-08-06T00:08:28","slug":"globo-promove-apresentadora-local-e-fecha-com-silvero-pereira-para-estrela-da-casa","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/05\/globo-promove-apresentadora-local-e-fecha-com-silvero-pereira-para-estrela-da-casa\/","title":{"rendered":"Globo promove apresentadora local e fecha com Silvero Pereira para Estrela da Casa"},"content":{"rendered":"<p>ARACAJU, SE (FOLHAPRESS) &#8211; A Globo fechou nesta segunda-feira (5) o elenco que far\u00e1 reportagens e vai apresentar as atra\u00e7\u00f5es que envolvem o Estrela da Casa, seu novo reality show, que estreia na pr\u00f3xima ter\u00e7a-feira (13).<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>A grande novidade \u00e9 a promo\u00e7\u00e3o de Cec\u00edlia Ribeiro. Apresentadora da TV Integra\u00e7\u00e3o, afiliada da Globo no interior de Minas Gerais desde 2009, Ceci, como \u00e9 conhecida, ter\u00e1 sua primeira experi\u00eancia em um programa exibido para todo o Brasil.<\/p>\n<p>Junto com ela, estar\u00e1 o ator Silvero Pereira, conhecido por fazer diversas novelas na emissora, como &#8220;A For\u00e7a do Querer&#8221; (2017). Ser\u00e1 a primeira experi\u00eancia de Silvero como apresentador na Globo. Juntos, Ceci e Silvero v\u00e3o comandar o Bate-papo Estrela da Casa, toda ter\u00e7a-feira, logo ap\u00f3s o final do Festival, que define o eliminado da semana.<\/p>\n<p>O programa ser\u00e1 transmitido no Globoplay. J\u00e1 no dia seguinte, quarta-feira, cabe \u00e0 jornalista Kenya Sade apresentar o Estrela da Casa &#8211; Backstage, no Multishow, canal de variedades da Globo na TV por assinatura.<\/p>\n<p>\u00c0 Folha de S.Paulo, Cec\u00edlia comemora sua primeira oportunidade em rede nacional. &#8220;Eu ainda estou processando que vou trabalhar com a melhor equipe de reality show do mundo. S\u00f3 tem gente de quem sou f\u00e3. Admiro muito o Silvero. E estou igual a internet toda, que est\u00e1 h\u00e1 anos pedindo a Ana \u00e0 frente do pr\u00f3prio programa, vibrando que vou ver acontecer, e bem de perto&#8221;.<\/p>\n<p>J\u00e1 Silvero agradeceu ao convite da Globo e projeta a parceria com Cec\u00edlia: &#8220;Fiquei muito emocionado e empolgado com essa nova experi\u00eancia e tenho certeza de que vou me divertir muito. Sou um veterano de competi\u00e7\u00f5es&#8221;, brinca ele, que foi campe\u00e3o do The Masked Singer Brasil e vice-campe\u00e3o do Show dos Famosos.<\/p>\n<p>Por fim, Kenya Sade comemorou o fato de ser lembrada em um programa musical, que \u00e9 sua \u00e1rea de atua\u00e7\u00e3o faz muito tempo, baseando inclusive o seu nome.<\/p>\n<p>&#8220;A m\u00fasica \u00e9 meu territ\u00f3rio e faz parte da minha vida, a come\u00e7ar pelo meu nome. &#8216;Sade&#8217; \u00e9 em homenagem \u00e0 cantora Sade Adu. E eu sou uma grande apaixonada pelas din\u00e2micas, provas, os burburinhos dentro da casa e os debates que surgem fora dela comovendo o pa\u00eds nos realities de confinamento. A entrega dos jogadores \u00e9 sempre muito gostosa de acompanhar&#8221;, conta Kenya.<\/p>\n<p>O Estrela da Casa estreia na semana que vem, e fica no ar at\u00e9 1\u00ba de outubro. A atra\u00e7\u00e3o ser\u00e1 apresentada por Ana Clara Lima, e ter\u00e1 exibi\u00e7\u00e3o di\u00e1ria na Globo, al\u00e9m de um sinal 24 horas no Globoplay.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2183171\/globo-promove-apresentadora-local-e-fecha-com-silvero-pereira-para-estrela-da-casa?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ARACAJU, SE (FOLHAPRESS) &#8211; A Globo fechou nesta segunda-feira (5) o elenco que far\u00e1 reportagens<\/p>\n","protected":false},"author":0,"featured_media":186975,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-186974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/186974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=186974"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/186974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/186975"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=186974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=186974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=186974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}