{"id":186852,"date":"2024-08-05T07:08:32","date_gmt":"2024-08-05T10:08:32","guid":{"rendered":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/05\/leonardo-dicaprio-e-namorada-sao-flagrados-em-passeio-na-italia-veja\/"},"modified":"2024-08-05T07:08:32","modified_gmt":"2024-08-05T10:08:32","slug":"leonardo-dicaprio-e-namorada-sao-flagrados-em-passeio-na-italia-veja","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2024\/08\/05\/leonardo-dicaprio-e-namorada-sao-flagrados-em-passeio-na-italia-veja\/","title":{"rendered":"Leonardo DiCaprio e namorada s\u00e3o flagrados em passeio na it\u00e1lia; veja"},"content":{"rendered":"<p>Leonardo DiCaprio, de 49 anos, e sua namorada, Vittoria Ceretti, est\u00e3o aproveitando uma pausa na It\u00e1lia.<\/p>\n<div class=\"dummyPub\">\u00a0<\/div>\n<p>Na \u00faltima quinta-feira, 1\u00ba de agosto, o casal foi clicado enquanto passeava pela Sardenha, conforme relatado pela People.<\/p>\n<p>Vittoria Ceretti, de 26 anos, foi fotografada usando um biqu\u00edni, enquanto o ator tamb\u00e9m apareceu com cal\u00e7\u00f5es de banho.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"it\">Leonardo DiCaprio and bikini-clad Vittoria Ceretti soak up sun <a href=\"https:\/\/t.co\/6MiEqT9HJM\">https:\/\/t.co\/6MiEqT9HJM<\/a><\/p>\n<p>\u2014 Reki (@Rekizzz) <a href=\"https:\/\/twitter.com\/Rekizzz\/status\/1820025518596710470?ref_src=twsrc%5Etfw\">August 4, 2024<\/a><\/p><\/blockquote>\n<p>\u00a0<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/2182869\/leonardo-dicaprio-e-namorada-sao-flagrados-em-passeio-na-italia-veja?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leonardo DiCaprio, de 49 anos, e sua namorada, Vittoria Ceretti, est\u00e3o aproveitando uma pausa na<\/p>\n","protected":false},"author":0,"featured_media":186853,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-186852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/186852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=186852"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/186852\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/186853"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=186852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=186852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=186852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}